{"id":4124,"date":"2014-01-24T05:48:40","date_gmt":"2014-01-24T05:48:40","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2014\/01\/24\/expande-sus-beneficios-la-direccin-de-fomento-econmico-municipal-a-las-comunid\/"},"modified":"2014-01-24T05:48:40","modified_gmt":"2014-01-24T05:48:40","slug":"expande-sus-beneficios-la-direccin-de-fomento-econmico-municipal-a-las-comunid","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2014\/01\/24\/expande-sus-beneficios-la-direccin-de-fomento-econmico-municipal-a-las-comunid\/","title":{"rendered":"Expande sus beneficios la direcci&oacute;n de fomento econ&oacute;mico municipal a las comunid"},"content":{"rendered":"<p>Por redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><strong><span lang=\"ES-TRAD\">Hermosillo, Sonora, 24 de enero 2014.- <\/span><\/strong><span lang=\"ES-TRAD\">A trav&eacute;s de la Comisi&oacute;n de Fomento Econ&oacute;mico, el Ayuntamiento de Hermosillo inici&oacute; un programa de orientaci&oacute;n sobre la Reforma Hacendaria, dirigido a microempresarios del &aacute;rea rural del municipio.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">El programa de Repeco a Incorporaci&oacute;n se ofreci&oacute; a los microempresarios del poblado Miguel Alem&aacute;n, para orientarlos de una manera sencilla, clara y pertinente<span>&nbsp; <\/span>sobre las nuevas disposiciones fiscales, precis&oacute; la directora de Formaci&oacute;n Empresarial, Lizeth Duarte Salido, en representaci&oacute;n de la titular de la comisi&oacute;n, Lyzeth Salcedo Salinas. <\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">Dijo que se despleg&oacute; esta estrategia por instrucciones del alcalde Alejandro L&oacute;pez Caballero, a fin de apoyar a los microempresarios del municipio y poner &eacute;nfasis <span>&nbsp;<\/span>en la formaci&oacute;n de<span>&nbsp; <\/span>la cultura de la formalidad y la orientaci&oacute;n amigable en el &aacute;rea rural, para cumplir con las obligaciones tributarias. <\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">A la reuni&oacute;n asistieron m&aacute;s de 60 microempresarios de giros como ferreter&iacute;as, restaurantes, papeler&iacute;as, tortiller&iacute;as, panader&iacute;as, refaccionarias, talleres mec&aacute;nicos y electricistas, a quienes se les proporcionaron herramientas que <span>&nbsp;<\/span>facilitan y aclaran el cambio de r&eacute;gimen, as&iacute; como el aspecto social de la reforma.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">En cuanto a los contenidos del programa, expuso que se abordaron temas como la desaparici&oacute;n del R&eacute;gimen del Peque&ntilde;o Contribuyente (Repeco), lo mismo que la del R&eacute;gimen Intermedio, pensi&oacute;n m&iacute;nima garantizada y seguro para el desempleo, entre otros. <\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\"><br \/> Duarte Salido anunci&oacute; que esta orientaci&oacute;n se brindar&aacute; tambi&eacute;n el pr&oacute;ximo 29 de enero en el sal&oacute;n ejidal de San Pedro El Saucito, lo mismo que se har&aacute; m&aacute;s adelante en el Centro de Desarrollo de Negocios de la Comisi&oacute;n de Fomento Econ&oacute;mico, por lo cual invit&oacute; a los empresarios de la localidad para que aprovechen las sesiones de capacitaci&oacute;n que son gratuitas y de f&aacute;cil comprensi&oacute;n.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\"><span>&nbsp;<\/span><\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">Para acudir a estas sesiones, los interesados pueden obtener su registro al comunicarse al tel&eacute;fono 2-12-58-57, o bien, visitar para ese efecto la p&aacute;gina de la comisi&oacute;n en el sitio <\/span><span lang=\"ES-TRAD\"><a href=\"http:\/\/www.economiahermosillo.gob.mx\/\" target=\"_blank\" rel=\"noopener\"><span>www.economiahermosillo.gob.mx<\/span><\/a><\/span><span lang=\"ES-TRAD\">. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El programa de Repeco a Incorporaci&oacute;n se ofreci&oacute; a los microempresarios del poblado Miguel Alem&aacute;n, para orientarlos de una manera sencilla, clara y pertinente  sobre las nuevas disposiciones fiscales, precis&oacute; la directora de Formaci&oacute;n Empresarial, Li<\/p>\n","protected":false},"author":1,"featured_media":20158,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[643],"class_list":["post-4124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-fomento-economico"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2014\/01\/1390567720_capacita-microempresas-rurales-300x225.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/4124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=4124"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/4124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/20158"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=4124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=4124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=4124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}