{"id":39599,"date":"2015-10-26T08:10:49","date_gmt":"2015-10-26T08:10:49","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2015\/10\/26\/realiza-oomapas-muestreo-del-agua\/"},"modified":"2015-10-26T08:10:49","modified_gmt":"2015-10-26T08:10:49","slug":"realiza-oomapas-muestreo-del-agua","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2015\/10\/26\/realiza-oomapas-muestreo-del-agua\/","title":{"rendered":"Realiza Oomapas muestreo del agua"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\">Para confirmar la buena calidad del agua que se consume en Agua Prieta, a fin de que se cumpla con los rangos establecidos en la Norma Oficial Mexicana, y no ponga en riesgo la salud humana, el Oomapas realiz&oacute; un muestreo en las redes de conducci&oacute;n, inform&oacute; Hugo Rivera Duarte.<\/p>\n<p class=\"ecxMsoNormal\">El director del Organismo Operador Municipal de Agua Potable, Alcantarillado y Saneamiento (Oomapas), expres&oacute; que fueron un total de 80 muestras de cloro residual las que se realizaron en lugares estrat&eacute;gicos en esta ciudad.<\/p>\n<p class=\"ecxMsoNormal\">&ldquo;Se realizaron 16 recorridos para verificar la cloraci&oacute;n en diferentes pozos donde se inyecta el cloro residual&rdquo;, explic&oacute;.<\/p>\n<p class=\"ecxMsoNormal\">Rivera Duarte a&ntilde;adi&oacute; que en el pozo ubicado en la calle 15 avenida 21 se purg&oacute; el equipo de cloraci&oacute;n l&iacute;quida y en el de la calle 10 avenida 4 se conect&oacute; el equipo de cloraci&oacute;n l&iacute;quida porque se encontraba desconectada la extensi&oacute;n.<\/p>\n<p class=\"ecxMsoNormal\">&ldquo;En el pozo de calle 18 avenida 23 se purg&oacute; la bomba de ayuda, se visit&oacute; el S&uacute;per de Santa Fe, en calle 6 avenida 41 para verificar la trampa de grasa que estaban sucias, se les requiri&oacute; limpieza a la mayor brevedad posible, ya que emana olores muy fuertes a los locales comerciales que est&aacute;n por la calle 6, se tomaron 34 muestras de cloro residual&rdquo;, detall&oacute;.<\/p>\n<p class=\"ecxMsoNormal\">El funcionario destac&oacute; que en el caso del pozo de calle 31 avenida 20 se prendi&oacute; la bomba de ayuda, en el pozo de calle 38 avenida 6 se purg&oacute; el equipo de cloraci&oacute;n l&iacute;quida; mientras que en el pozo de Aquamundo se purg&oacute; la bomba de ayuda.<\/p>\n<p class=\"ecxMsoNormal\">&ldquo;Se aplicaron 700 gramos de cloro granulado en calle 13 desde la avenida 23 a la 26 por derrame de agua sucia de la reparaci&oacute;n de fuga de agua residual en el alcantarillado municipal; se arregl&oacute; una fuga en el lava manos del m&oacute;dulo de calle 6 avenida 41, se aplic&oacute; producto en la laguna de oxidaci&oacute;n y en la carretera y avenida Ferrocarril, en el puente de la entrada de Agua Prieta para eliminar malos olores&rdquo;, abund&oacute;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director del Organismo Operador Municipal de Agua Potable, Alcantarillado y Saneamiento (Oomapas), expres&oacute; que fueron un total de 80 muestras de cloro residual las que se realizaron en lugares estrat&eacute;gicos en esta ciudad. <\/p>\n","protected":false},"author":1,"featured_media":39600,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[1325],"class_list":["post-39599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-agua-prieta"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1445872251_oomapas3.JPG","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/39599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=39599"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/39599\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/39600"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=39599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=39599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=39599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}