{"id":39262,"date":"2015-10-21T08:55:49","date_gmt":"2015-10-21T08:55:49","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2015\/10\/21\/implementan-en-empalme-conociendo-a-la-contralora-en-dependencias-municipales\/"},"modified":"2015-10-21T08:55:49","modified_gmt":"2015-10-21T08:55:49","slug":"implementan-en-empalme-conociendo-a-la-contralora-en-dependencias-municipales","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2015\/10\/21\/implementan-en-empalme-conociendo-a-la-contralora-en-dependencias-municipales\/","title":{"rendered":"Implementan en Empalme &quot;Conociendo a la Contralor&iacute;a&quot; en dependencias municipales"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\">Empalme.- El Ayuntamiento de Empalme a trav&eacute;s del &Oacute;rgano de Control y Evaluaci&oacute;n Gubernamental arranc&oacute; el programa &ldquo;Conociendo a la Contralor&iacute;a&rdquo; dirigido a los empleados y funcionarios de cada una de las dependencias de la actual administraci&oacute;n.<\/p>\n<p style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\">Por instrucciones del Presidente Municipal, el titular de la dependencia Jos&eacute; Luis Dumas Guti&eacute;rrez indic&oacute; que las dependencias participantes en este primer m&oacute;dulo fueron&nbsp; la direcci&oacute;n de Obras P&uacute;blicas, la subdirecci&oacute;n de Desarrollo Urbano y Desarrollo Econ&oacute;mico, las coordinaciones de Desarrollo Rural, Ecolog&iacute;a y Protecci&oacute;n Civil.<\/p>\n<p style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\">Esto con el fin de capacitar a funcionarios y servidores p&uacute;blicos, para que sea de su pleno conocimiento las funciones y acciones de Contralor&iacute;a Municipal, as&iacute; como el entendimiento en los reglamentos de la ley de Gobierno y Administraci&oacute;n Municipal y la ley de Responsabilidad de los Servidores P&uacute;blicos, se&ntilde;al&oacute; Dumas Guti&eacute;rrez.<\/p>\n<p style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\">Se debe trabajar acorde a la ley y con el compromiso de beneficiar de los ciudadanos, porque es deber de los servidores p&uacute;blico actuar en base a ello, es por eso la importancia de aplicar este programa como parte del compromiso fincado por el primer edil, Carlos Enrique G&oacute;mez Cota.<\/p>\n<p style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\">Tambi&eacute;n el funcionario municipal se&ntilde;al&oacute; que posteriormente se estar&aacute; realizando las capacitaciones para las dem&aacute;s dependencias para as&iacute; seguir trabajando en un gobierno eficiente y responsable con apego a la legalidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>  El Ayuntamiento de Empalme a trav&eacute;s del &Oacute;rgano de Control y Evaluaci&oacute;n Gubernamental arranc&oacute; el programa &quot;Conociendo a la Contralor&iacute;a&quot; dirigido a los empleados y funcionarios de cada una de las dependencias de la actual administraci&oacute;n.<\/p>\n","protected":false},"author":1,"featured_media":39263,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[3985],"class_list":["post-39262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-ayuntamiento-empalme"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1445443106_330712554.JPG","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/39262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=39262"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/39262\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/39263"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=39262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=39262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=39262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}