{"id":3853,"date":"2014-01-14T07:45:13","date_gmt":"2014-01-14T07:45:13","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2014\/01\/14\/reconoce-presidente-de-hermosillo-al-emprendedor-del-ao-2013\/"},"modified":"2014-01-14T07:45:13","modified_gmt":"2014-01-14T07:45:13","slug":"reconoce-presidente-de-hermosillo-al-emprendedor-del-ao-2013","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2014\/01\/14\/reconoce-presidente-de-hermosillo-al-emprendedor-del-ao-2013\/","title":{"rendered":"Reconoce presidente de Hermosillo al Emprendedor del A&ntilde;o 2013"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><strong><span lang=\"ES-TRAD\">Hermosillo, Sonora; 14 de enero de 2014.-<\/span><\/strong><span lang=\"ES-TRAD\"> El alcalde Alejandro L&oacute;pez Caballero entreg&oacute; reconocimiento al Emprendedor del A&ntilde;o 2013 a Jos&eacute; Antonio Pacheco S&aacute;nchez, de la empresa facilitadora de alta tecnolog&iacute;a Teknol, a ra&iacute;z de la convocatoria realizada por la Comisi&oacute;n de Fomento Econ&oacute;mico, Universidad Tec Milenio y el Instituto Hermosillense de la Juventud.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">L&oacute;pez Caballero se&ntilde;al&oacute; que al distinguir a las personas que destacan al tener la iniciativa de formar proyectos empresariales, se fomenta a que m&aacute;s ciudadanos se animen a crear su propia empresa, las cuales ayudar&aacute;n a mejorar la calidad de vida de sus familias y a la vez, de la sociedad hermosillense.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">&ldquo;Ser emprendedor es una parte del camino hacia el &eacute;xito, porque toda gran empresa comienza con un sue&ntilde;o, al que se le da forma, se desarrolla y con este se tocan las puertas necesarias para que vaya creciendo&rdquo;, indic&oacute; el mun&iacute;cipe.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">Por su parte la directora de la CFEH, Lyzeth Salcedo Salinas, explic&oacute; que la convocatoria al emprendedor del a&ntilde;o fue lanzada por la dependencia, la Universidad Tec Milenio y el IHJ, con el objetivo de reconocer a las micro y peque&ntilde;as empresas del municipio, en la que los requisitos eran ser una empresa con ideas creativas, modelo de negocio innovador, con valor agregado y visi&oacute;n&nbsp; a largo plazo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">Salcedo Salinas dijo que es indispensable resaltar los casos de &eacute;xito como modelos inspiradores que socialicen una cultura emprendedora, misma que motive la creaci&oacute;n de nuevos negocios exitosos generadores de inversi&oacute;n y empleo, para incentivar el crecimiento econ&oacute;mico de la capital del Estado.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">Para esta convocatoria se registraron m&aacute;s de 50 empresas, en donde el comit&eacute; evaluador conformado por las instituciones mencionadas nombr&oacute; como ganador a Pacheco S&aacute;nchez, de 33 a&ntilde;os de edad, cofundador y actual director de la empresa Teknol, que ha generado quince empleos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">Teknol es la primera empresa en M&eacute;xico en ofrecer soluciones integrales para la visualizaci&oacute;n y gesti&oacute;n de datos geogr&aacute;ficos, geol&oacute;gicos, arquitect&oacute;nicos, educativos, industriales y estad&iacute;sticos, por medio de alta tecnolog&iacute;a para ver y manipular grandes cantidades de informaci&oacute;n relevante para una mejor toma de decisiones<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">En el segundo lugar fue reconocido Javier Yadir Alcal&aacute; Dur&oacute;n y su compa&ntilde;ero Eduardo Navarro, por la innovadora empresa Servicios M&eacute;dicos Vivir Sano, la cual cuenta con m&eacute;dicos altamente calificados en medicina general, pediatr&iacute;a, patolog&iacute;a, cirug&iacute;a general, ginecolog&iacute;a y nutrici&oacute;n, quienes atienden a peque&ntilde;as y medianas empresas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">En tercer lugar fue seleccionado David Cadena Ochoa, por la empresa Pistones Food and Drink Garage, el cual es un comercio &nbsp;familiar, formado por j&oacute;venes, que genera 60 empleos y se dedica a ofrecer servicios de alimentaci&oacute;n y entretenimiento a todos los segmentos de mercado.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">En representaci&oacute;n del galardonado, recibi&oacute; el reconocimiento el gerente de operaciones de Pistones, Luis Eduardo Gallego.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"text-align: justify\"><span lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p><span lang=\"ES-TRAD\">El director de Tec Milenio campus Hermosillo, Javier de la Fuente Flores, mencion&oacute; que la instituci&oacute;n est&aacute; muy interesada en apoyar a los j&oacute;venes, porque saben que la forma de ser exitosos en el &aacute;mbito empresarial, es tener el conocimiento y ser innovador, y es as&iacute; como detonar&aacute;n la econom&iacute;a en la regi&oacute;n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&oacute;pez Caballero se&ntilde;al&oacute; que al distinguir a las personas que destacan al tener la iniciativa de formar proyectos empresariales, se fomenta a que m&aacute;s ciudadanos se animen a crear su propia empresa, las cuales ayudar&aacute;n a mejorar la calidad de vida de su<\/p>\n","protected":false},"author":1,"featured_media":19849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[244],"class_list":["post-3853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-alc"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2014\/01\/1389710713_1389645516image1.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/3853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=3853"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/3853\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/19849"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=3853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=3853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=3853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}