{"id":37925,"date":"2015-09-25T13:50:50","date_gmt":"2015-09-25T13:50:50","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2015\/09\/25\/desfogan-agua-de-4-presas-en-sonora-por-excedentes\/"},"modified":"2015-09-25T13:50:50","modified_gmt":"2015-09-25T13:50:50","slug":"desfogan-agua-de-4-presas-en-sonora-por-excedentes","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2015\/09\/25\/desfogan-agua-de-4-presas-en-sonora-por-excedentes\/","title":{"rendered":"Desfogan agua de 4 presas en Sonora por excedentes"},"content":{"rendered":"<p>Por Redacci&ograve;n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">Son hasta el momento cuatro las presas que desfogan agua por excedentes en Sonora debido a la captaci&oacute;n por lluvias en Sonora, por lo que el sistema de presas en Sonora se encuentra al 93.2 por ciento de su capacidad total, con un almacenamiento de 7,504.0 millones de metros c&uacute;bicos (Hm3), el a&ntilde;o pasado a esta misma fecha almacenaba 91.0 por ciento, inform&oacute; C&eacute;sar Lagarda Lagarda, director general del Organismo de Cuenca Noroeste (OCNO) de la Comisi&oacute;n Nacional del Agua (Conagua).<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">&nbsp;<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">El d&iacute;a de hoy en punto de las 9:00 horas la presa &Aacute;lvaro Obreg&oacute;n &ldquo;Ovi&aacute;chic&rdquo;, inici&oacute; con desfogues por 100 metros c&uacute;bicos por segundo (m3\/s), 2,913.3, lo que representa el 96.4 por ciento de su capacidad.<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">&nbsp;<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">Hasta el momento se mantienen tres presas por encima de su capacidad de almacenamiento normal, una de ellas es la L&aacute;zaro C&aacute;rdenas &ldquo;La Angostura&rdquo;, ubicada en los l&iacute;mites de los municipios de Villa Hidalgo y Nacozari de Garc&iacute;a tiene un almacenamiento del 109.9por ciento, lo que se traduce en 749.4 millones de metros c&uacute;bicos (Hm3), por lo que vierte 68.3 metros c&uacute;bicos por segundo (m3\/s).<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">&nbsp;<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">Mientras que la presa Abraham Gonz&aacute;lez, perteneciente al sistema de presas del R&iacute;o Yaqui se encuentra al 101.1 por ciento de su almacenamiento total, con 89.4 Hm3&nbsp;y vierte 11.8 m3\/s, por &uacute;ltimo la presa Adolfo Ruiz Cortines &ldquo;Moc&uacute;zari&rdquo;, ubicada en &Aacute;lamos est&aacute; al 104.5 por ciento de su almacenamiento, con 998.0Hm3&nbsp;por lo que vierte 150 m3\/s.<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">&nbsp;<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">&nbsp;<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">En Hermosillo, la presa Abelardo Rodr&iacute;guez L. acumula 30.7 Hm3&nbsp;del vital l&iacute;quido, lo que significa 14.0 por ciento de su capacidad total, mientras que El Molinito mantiene un almacenamiento de 20.2 por ciento es decir, 26.3Hm3.<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">&nbsp;<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">&nbsp;<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline;line-height: 21.3px\">Pron&oacute;stico del Tiempo<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">&nbsp;<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">Este d&iacute;a persiste la afluencia moderada de humedad y la circulaci&oacute;n anticicl&oacute;nica media y superior en el noroeste del pa&iacute;s y se observa un &aacute;rea de difluencia en niveles medios en el centro y sur de Sonora, con bajos &iacute;ndices de convecci&oacute;n, por lo que se espera tiempo despejado en la ma&ntilde;ana.<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">&nbsp;<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">Por la tarde se observar&aacute;n nublados dispersos de poco a moderado desarrollo vertical en el sur de Sonora y en la Sierra Madre Occidental, siendo posible el desarrollo de unas pocas tormentas, con potencial de precipitaciones ligeras, actividad el&eacute;ctrica y vientos en rachas fuertes principalmente en las sierras elevadas.<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">&nbsp;<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">Tambi&eacute;n se prev&eacute; viento variable, con rachas de corta duraci&oacute;n de hasta 50 kil&oacute;metros por hora (km\/h) en el norte de Sonora y en la Sierra Madre Occidental y de hasta 35 km\/h en el resto de la regi&oacute;n.<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">&nbsp;<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">Continuar&aacute; el ambiente caluroso en el d&iacute;a, con temperaturas m&aacute;ximas cercanas a 40&deg;C en los valles de la entidad.<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">&nbsp;<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">Como muestra la imagen de la izquierda, en el Pac&iacute;fico hay dos disturbios tropicales, uno se ubica a unos 600 km al sur de las costas de Oaxaca y Guerrero y tiene 80 por ciento de posibilidad de convertirse en cicl&oacute;n tropical en los siguientes cinco d&iacute;as.<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">&nbsp;<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"border: 0px;margin: 0px 0px 1.35em;padding: 0px;vertical-align: baseline;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.3px\"><strong style=\"border: 0px;margin: 0px;padding: 0px;vertical-align: baseline\">El otro, se localiza a menos de 200 km al Sur de las costas de Chiapas y tiene 30% de posibilidad de convertirse en cicl&oacute;n tropical en los siguientes cinco d&iacute;as.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d&iacute;a de hoy en punto de las 9:00 horas la presa &Aacute;lvaro Obreg&oacute;n &quot;Ovi&aacute;chic&quot;, inici&oacute; con desfogues por 100 metros c&uacute;bicos por segundo (m3\/s), 2,913.3, lo que representa el 96.4 por ciento de su capacidad.<\/p>\n","protected":false},"author":1,"featured_media":37926,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[224],"class_list":["post-37925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-conagua"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1443214250_cona.JPG","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/37925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=37925"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/37925\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/37926"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=37925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=37925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=37925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}