{"id":37629,"date":"2015-09-18T13:29:32","date_gmt":"2015-09-18T13:29:32","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2015\/09\/18\/contina-ieeypc-mesas-de-reflexin-sobre-proceso-electoral-con-partidos-poltico\/"},"modified":"2015-09-18T13:29:32","modified_gmt":"2015-09-18T13:29:32","slug":"contina-ieeypc-mesas-de-reflexin-sobre-proceso-electoral-con-partidos-poltico","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2015\/09\/18\/contina-ieeypc-mesas-de-reflexin-sobre-proceso-electoral-con-partidos-poltico\/","title":{"rendered":"Contin&uacute;a IEEyPC mesas de reflexi&oacute;n sobre proceso electoral con Partidos Pol&iacute;tico"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><span style=\"line-height: 18.4px;font-size: 12pt;font-family: Arial, sans-serif\">En seguimiento al trabajo de reflexi&oacute;n sobre la organizaci&oacute;n y desarrollo del proceso electoral 2014-2015; los Consejeros Electorales, del Instituto Estatal Electoral y de Participaci&oacute;n Ciudadana (IEEyPC);&nbsp; continuaron las mesas de an&aacute;lisis con representantes de los partidos pol&iacute;ticos.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><span style=\"line-height: 18.4px;font-size: 12pt;font-family: Arial, sans-serif\">En la reuni&oacute;n celebrada el d&iacute;a de ayer en la sala de juntas del &oacute;rgano electoral, particip&oacute; la Consejera Presidenta Guadalupe Taddei Zavala; los consejeros Ana Patricia Brise&ntilde;o Torres, Marisol Cota Cajigas, Ana Maribel Salcido Jashimoto y Vladimir G&oacute;mez Anduro.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><span style=\"line-height: 18.4px;font-size: 12pt;font-family: Arial, sans-serif\">De la misma forma, estuvieron los representantes del PAN, PRD, PVEM, &nbsp;Movimiento Ciudadano, Nueva Alianza, Morena, Encuentro Social y Humanista.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><span style=\"line-height: 18.4px;font-size: 12pt;font-family: Arial, sans-serif\">Los temas que se est&aacute;n abordando en estas mesas de reflexi&oacute;n son: capacitaci&oacute;n, consejos distritales y municipales, partidos pol&iacute;ticos, reforma a la Ley de Instituciones y Procedimientos Electorales para el Estado de Sonora, reglamentos&nbsp; y participaci&oacute;n pol&iacute;tica de la mujer, entre otros.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><span style=\"line-height: 18.4px;font-size: 12pt;font-family: Arial, sans-serif\">Al concluir este ejercicio, se realizar&aacute; una relator&iacute;a con las conclusiones que los representantes de los partidos y consejeros han planteado, para enriquecer el trabajo&nbsp; que realiza el IEEyPC, as&iacute; como trabajar en aquellos que requieren de coordinaci&oacute;n con otras instancias y autoridades para su cumplimiento.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la reuni&oacute;n celebrada el d&iacute;a de ayer en la sala de juntas del &oacute;rgano electoral, particip&oacute; la Consejera Presidenta Guadalupe Taddei Zavala; los consejeros Ana Patricia Brise&ntilde;o Torres, Marisol Cota Cajigas, Ana Maribel Salcido Jashimoto y Vladimir G&oacute;<\/p>\n","protected":false},"author":1,"featured_media":37630,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[2203],"class_list":["post-37629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-iee"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1442608172_B_2015_09_18_079.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/37629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=37629"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/37629\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/37630"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=37629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=37629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=37629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}