{"id":37579,"date":"2015-09-18T09:52:48","date_gmt":"2015-09-18T09:52:48","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2015\/09\/18\/realiza-consejo-general-del-ieeypc-sesin-ordinaria\/"},"modified":"2015-09-18T09:52:48","modified_gmt":"2015-09-18T09:52:48","slug":"realiza-consejo-general-del-ieeypc-sesin-ordinaria","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2015\/09\/18\/realiza-consejo-general-del-ieeypc-sesin-ordinaria\/","title":{"rendered":"Realiza Consejo General del IEEyPC Sesi&oacute;n Ordinaria"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\">En la sesi&oacute;n ordinaria correspondiente al mes de Septiembre, realizada este d&iacute;a, el Consejo General del Instituto Estatal Electoral y de Participaci&oacute;n Ciudadana (IEEyPC), aprob&oacute; diversas resoluciones del Procedimiento Ordinario y Especial Sancionador interpuestas por los partidos y candidatos.<\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\">Los consejeros electorales resolvieron de esta forma, las denuncias&nbsp; identificadas con los expedientes IEEPC\/CG\/319\/15 al IEEPC\/CG\/329\/15; relativas a actos relacionados con violaciones la normatividad electoral, en las etapas de pre campa&ntilde;a y campa&ntilde;a, de Gobernador, Alcald&iacute;as y Diputados Locales.<\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\">En total fueron 10 los procedimientos resueltos como infundados en esta sesi&oacute;n, donde la Secretar&iacute;a Ejecutiva rindi&oacute; al Pleno del Consejo General del IEEyPC, la cuenta de peticiones y consultas adem&aacute;s de la cuenta de los medios de impugnaci&oacute;n y resoluciones emitidas por los tribunales electorales, de acuerdo a lo establecido en las fracciones VI y VII del art&iacute;culo 123&nbsp; de la Ley de Instituciones y Procedimientos Electorales para el Estado de Sonora.<\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\">La totalidad de los asuntos aprobados por el Consejo General del IEEyPC,&nbsp; est&aacute; disponible para su consulta en la p&aacute;gina electr&oacute;nica&nbsp;<a style=\"line-height: 21.3px;font-weight: inherit;color: #0068cf;cursor: pointer\" href=\"http:\/\/www.ieesonora.org.mx\/\" target=\"_blank\" rel=\"noopener\">www.ieesonora.org.mx<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Realiza Consejo General del IEEyPC Sesi&oacute;n Ordinaria<\/p>\n","protected":false},"author":1,"featured_media":37580,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[2203],"class_list":["post-37579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-iee"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1442595168_B_2015_09_17_078.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/37579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=37579"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/37579\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/37580"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=37579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=37579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=37579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}