{"id":36845,"date":"2015-09-01T09:25:09","date_gmt":"2015-09-01T09:25:09","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2015\/09\/01\/anuncia-lmp-la-fiesta-mexicana-de-bisbol\/"},"modified":"2015-09-01T09:25:09","modified_gmt":"2015-09-01T09:25:09","slug":"anuncia-lmp-la-fiesta-mexicana-de-bisbol","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2015\/09\/01\/anuncia-lmp-la-fiesta-mexicana-de-bisbol\/","title":{"rendered":"&quot;Anuncia LMP la Fiesta Mexicana de B&eacute;isbol&quot;"},"content":{"rendered":"<p class=\"MsoNormal\"><strong><span>Por Rafael Renter&iacute;a<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span>&nbsp;<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span>Por quinto a&ntilde;o consecutivo, la Liga Mexicana del Pacifico llevar&aacute; a cabo un evento deportivo que ya se est&aacute; volviendo tradicional en los Estados Unidos con la llamada &ldquo;Fiesta Mexicana de Beisbol 2015&rdquo;.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span>&nbsp;<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span>En las oficinas de la LMP se llev&oacute; a cabo la presentaci&oacute;n de este corto torneo de beisbol por parte del coordinador del mismo Francisco G&aacute;mez y quien acompa&ntilde;ado de Juan&nbsp; Aguirre, gerente de Naranjeros as&iacute; como de representantes de Yaquis de CO, Ca&ntilde;eros de los Mochis y &Aacute;guilas de Mexicali se hizo el anuncio oficial del evento para este a&ntilde;o.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Precisamente estos 4 equipos que pertenecen a la Liga Mexicana del Pacifico ver&aacute;n acci&oacute;n de pretemporada y de participaci&oacute;n en este peque&ntilde;o torneo en las ciudades de Tucson y Mesa en Arizona as&iacute; como en el Paso Texas desde los d&iacute;as 18 de septiembre hasta el 4 de octubre. Precisamente a unos d&iacute;as de que arranque la temporada 2015-2016 de este beisbol de invierno.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Adem&aacute;s de estas escuadras se contar&aacute; con la participaci&oacute;n de los equipos de Grandes ligas de Reales de Kansas City y Diamondbacks de Arizona que mandar&aacute;n a sus mejores prospectos para formar parte del mismo y medirse con las escuadras mexicanas.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Sin duda este evento cada a&ntilde;o est&aacute; tomando m&aacute;s fuerza para benepl&aacute;cito de los aficionados que viven en esos estados y en esas ciudades en especial y m&aacute;s tomando en cuenta que aprovechan esta oportunidad para ver de cerca a sus equipos favoritos o de sus ciudades de origen. Incluso el mismo Francisco G&aacute;mez nos dec&iacute;a que f&aacute;cilmente se cuenta con un gran porcentaje de aficionados que acuden a los juegos durante este torneo de Fiesta Mexicana de Beisbol.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Adem&aacute;s para esta edici&oacute;n 2015 de esta fiesta beisbolera que incluso para el otro a&ntilde;o nos comentaban tambi&eacute;n podr&iacute;a tener como sedes a las ciudades de San Diego y las Vegas, se tendr&aacute; la presencia de las categor&iacute;as infantiles y juveniles de los equipos de la LMP y as&iacute; poder foguearlos m&aacute;s en la v&iacute;spera de su pronta llegada al equipo mayor. <\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>A como nos la pintaron este 2015 estar&aacute; bastante interesante este torneo por la calidad de equipos y de jugadores que estar&aacute;n, incluso la mayor&iacute;a de las escuadras llegar&aacute; con equipo completo y otros casi casi completos. Como dato interesante, nos dec&iacute;an que quienes han formado parte de las anteriores ediciones de la Fiesta Mexicana de Beisbol han salido a los meses siguientes campeones de la LMP. Esto quiere decir que Naranjeros,Yaquis, Ca&ntilde;eros o &Aacute;guilas ser&aacute;n los nuevos monarcas destronando del mismo puesto al actual campe&oacute;n Tomateros de Culiac&aacute;n?<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Y como ya faltan pocos d&iacute;as para que de inicio este torneo los organizadores est&aacute;n poniendo los boletos a la venta con costos de entre los 9 a los 13 d&oacute;lares y para mayores informes los interesados nos dec&iacute;an pueden ingresar a la p&aacute;gina www.mexicanbaseballfiesta.com.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 9.4pt\"><span>&nbsp;&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span>ROL DE JUEGOS<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 9.4pt\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span>Mesa, Arizona<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span>Viernes 18 de septiembre<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>7:30 P.M. Hermosillo vs. Mexicali<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span>S&aacute;bado 19 de septiembre<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>7:00 P.M. Mexicali vs. Hermosillo<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 9.4pt\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span>El Paso, Texas<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span>Viernes 25 de septiembre<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>7:05 P.M Hermosillo vs. Mexicali<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span>S&aacute;bado 26 de septiembre<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>1:05 P.M. Mexicali vs. Hermosillo<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 9.4pt\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span>Tucson, Arizona<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span>Jueves 1 de octubre<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>5.30 P.M. Hermosillo vs. Kansas City<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Obreg&oacute;n vs. Mexicali<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span>Viernes 2 de octubre<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>5:30 P.M. Obreg&oacute;n vs. Diamondbacks<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Hermosillo vs. Los Mochis<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span>S&aacute;bado 3 de octubre *<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>5:30&nbsp;P.M. Los Mochis vs. Mexicali<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Hermosillo vs. Obreg&oacute;n<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span>Domingo 4 de octubre *<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>2:00 P.M. Obreg&oacute;n vs. Los Mochis<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Hermosillo vs. Mexicali<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 9.4pt\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>*Doble cartelera con inicio a las 5:30P.M.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>As&iacute; es que quien tenga pensado acudir a este mini torneo m&aacute;s vale que se preparen y vivan la experiencia de la Fiesta Mexicana de Beisbol 2015 ya sea en Tucson, Mesa o el Paso en donde se tendr&aacute;n encuentros de muy buen nivel para toda la fanaticada que ver&aacute; de cerca a sus jugadores y equipos preferidos&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span>&nbsp;<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span>Por &uacute;ltimo y en tema de futbol el d&iacute;a de ayer lunes fue algo especial para los futbolistas mexicanos ya que 3 jugadores cambiaron de equipo en Europa.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span>&nbsp;<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>El Chicharito Hern&aacute;ndez fue vendido del Manchester United al Bayer Leverkusen de Alemania y Jes&uacute;s Tecatito Corona tambi&eacute;n fue vendido del Tweente de Holanda al Porto de Portugal, quien tambi&eacute;n obtuvo v&iacute;a pr&eacute;stamo a Migue Layun del Watford de Inglaterra.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt\"><span>En lo personal no recuerdo un d&iacute;a as&iacute; para la legi&oacute;n de futbolistas mexicanos en Europa en donde en una misma fecha se den esos traspasos. El caso del Chicharito por fin se termin&oacute; con el Man U y se supone que ahora si podr&aacute; tener regularidad para mostrar ese talento que el equipo alem&aacute;n vio en &eacute;l. Por otro lado, la venta del hermosillense Corona a un equipo portugu&eacute;s experto en comprar barato y vender caro es tambi&eacute;n muy importante porque se confirma que sus cazatalentos tiene muy buen tino con jugadores nacidos en M&eacute;xico. Estoy seguro que de seguir jugando al ritmo que se le vio con el Tweente ser&aacute; vendido a los mejores equipos del mundo.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt\"><span>Y por &uacute;ltimo el pr&eacute;stamo de Layun tambi&eacute;n al Porto es m&aacute;s de llamar la atenci&oacute;n porque a pesar que no es un crack, debi&oacute; de haber tenido algo especial para que el conjunto de los dragones lo pidiera cedido con opci&oacute;n a comprarlo.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt\"><span><br \/> <!--[if !supportLineBreakNewLine]--><br \/> <!--[endif]--><\/span><\/p>\n<p class=\"MsoNormal\"><strong><span>Sugerencias y comentarios los pueden enviar&nbsp; a mi correo electr&oacute;nico: <\/span><\/strong><a href=\"mailto:renteria_rafael@hotmail.com\"><span style=\"font-size: 14.0pt;line-height: 115%\">renteria_rafael@hotmail.com<\/span><\/a><strong><span>, Twitter: rafarenteria11 o a Facebook a Rafael Renter&iacute;a R.<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt\"><span>&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por quinto a&ntilde;o consecutivo, la Liga Mexicana del Pacifico llevar&aacute; a cabo un evento deportivo que ya se est&aacute; volviendo tradicional en los Estados Unidos con la llamada &quot;Fiesta Mexicana de Beisbol 2015&quot;.<\/p>\n","protected":false},"author":1,"featured_media":36846,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[190],"tags":[3806],"class_list":["post-36845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-renteria","tag-columna-1-sept-15"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1441124710_fiestamexicana2015.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/36845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=36845"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/36845\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/36846"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=36845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=36845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=36845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}