{"id":36286,"date":"2015-08-20T09:19:52","date_gmt":"2015-08-20T09:19:52","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2015\/08\/20\/sin-luz-la-codeson-e-instalaciones-deportivas\/"},"modified":"2015-08-20T09:19:52","modified_gmt":"2015-08-20T09:19:52","slug":"sin-luz-la-codeson-e-instalaciones-deportivas","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2015\/08\/20\/sin-luz-la-codeson-e-instalaciones-deportivas\/","title":{"rendered":"&quot;Sin luz la Codeson e instalaciones deportivas&quot;"},"content":{"rendered":"<p class=\"MsoNormal\"><span>Por Rafael Renter&iacute;a<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>La falta de liquidez de parte de Tesorer&iacute;a y la Secretaria de Hacienda Estatal ha llegado ya a muchas dependencias del mismo organigrama del gobierno sonorense, pero en esta ocasi&oacute;n le toc&oacute; a la Comisi&oacute;n del Deporte (Codeson) bailar con la m&aacute;s fea al quedarse sin el servicio de energ&iacute;a el&eacute;ctrica al igual que instalaciones deportivas a su cargo por falta de pago.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>En entrevista que sostuvimos con el titular de la Codeson en Sonora, Vicente Sagrestano Alcaraz nos coment&oacute; que este problema de adeudo con la CFE (que no son precisamente muy caritativos que digamos) de 550 mil pesos fue lo que provoc&oacute; desde el pasado lunes que todas las instalaciones que se encuentran en el CUM se encuentren sin el servicio de energ&iacute;a el&eacute;ctrica as&iacute; como varias unidades como la de Hermosillo, el poli funcional Ana Gabriela Guevara y la misma unidad del noroeste donde albergan una cantidad importante de disciplinas deportivas.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>El mismo Vinco cont&oacute; que esa situaci&oacute;n ya se le hizo saber a Tesorer&iacute;a del estado encargada de enviar ese tipo de ministraciones a las diversas dependencias del gobierno, pero ante circunstancias recalc&oacute; que seguir&aacute;n pugnando porque a la mayor brevedad posible se pueda solucionar esta situaci&oacute;n hasta cierto punto anormal de cortar el suministro de la luz por falta de pago a una rama de la nomenclatura estatal que brinda muchos servicios a los ciudadanos que forman parte de alguna disciplina deportiva.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Reiter&oacute; que toda la documentaci&oacute;n requerida sobre este asunto ya est&aacute; en manos de la dependencia encargada del manejo y destino de los recursos p&uacute;blicos, pero todo parece indicar que por la situaci&oacute;n de los procesos de entrega recepci&oacute;n que se est&aacute;n llevando a cabo entre la administraci&oacute;n que llega y la que se va pues pudo haberse dado ese retardo para el dep&oacute;sito de esos 550 mil pesos para pagar el concepto de energ&iacute;a el&eacute;ctrica y que atiende a todas las instalaciones deportivas y a las mismas oficinas de la Codeson.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Finalmente el Vinco Sagrestano le solicit&oacute; a todas las personas que regularmente acuden a las instalaciones deportivas a realizar alg&uacute;n deporte o simplemente a hacer ejercicio, su comprensi&oacute;n por esta lamentable situaci&oacute;n y en donde ellos como encargados del deporte sonorense no pudieron controlar al no recibir en tiempo y forma ese recurso para cubrir el pago de servicios prestados. Confi&oacute; que muy pronto pueda restablecerse el servicio de la luz y realizar de nuevo con normalidad cada una de las actividades diarias de esos lugares. Sin duda dijo sentirse muy apenado por todo esto que estaba pasando.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Por lo pronto cientos de hermosillenses al ver la oscuridad de esos sitios deben estar optando por acudir a otras instalaciones a realizar sus actividades deportivas regulares, pero por otra parte es urgente que tanto Codeson con el mismo gobierno del estado puedan arreglar este grave problema y reactivar esos sitios que contribuyen con el desarrollo de una sociedad de una forma tranquila y sobre todo saludable.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>550 mil pesos no pudieran ser mucho para el gobierno del estado, aunque para los ciudadanos s&iacute;, pero pues ineludible no ver que este mismo tema de la falta de dinero que no ha llegado tambi&eacute;n de la federaci&oacute;n pues ha hecho esta gran bola de nieve, que al final a los &uacute;nicos que perjudica es a los sonorenses mismos.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\"><strong><span>Sugerencias y comentarios los pueden enviar&nbsp; a mi correo electr&oacute;nico: <\/span><\/strong><a href=\"mailto:renteria_rafael@hotmail.com\"><span style=\"font-size: 14.0pt;line-height: 115%\">renteria_rafael@hotmail.com<\/span><\/a><strong><span>, Twitter: rafarenteria11 o a Facebook a Rafael Renter&iacute;a R.<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La falta de liquidez de parte de Tesorer&iacute;a y la Secretaria de Hacienda Estatal ha llegado ya a muchas dependencias del mismo organigrama del gobierno sonorense, pero en esta ocasi&oacute;n le toc&oacute; a la Comisi&oacute;n del Deporte (Codeson) bailar con la m&aacute;s fea <\/p>\n","protected":false},"author":1,"featured_media":36287,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[190],"tags":[3758],"class_list":["post-36286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-renteria","tag-columna-20-agosto-15"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1440087593_20150819_195359.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/36286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=36286"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/36286\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/36287"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=36286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=36286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=36286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}