{"id":3546,"date":"2013-12-31T12:10:51","date_gmt":"2013-12-31T12:10:51","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2013\/12\/31\/entrega-resultados-en-7-programas-la-direccin-de-prevencin-y-atencin-ciudadan\/"},"modified":"2013-12-31T12:10:51","modified_gmt":"2013-12-31T12:10:51","slug":"entrega-resultados-en-7-programas-la-direccin-de-prevencin-y-atencin-ciudadan","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2013\/12\/31\/entrega-resultados-en-7-programas-la-direccin-de-prevencin-y-atencin-ciudadan\/","title":{"rendered":"Entrega resultados en 7 programas la direcci&oacute;n de Prevenci&oacute;n y Atenci&oacute;n Ciudadan"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\"><strong><span style=\"line-height: 18px;font-size: 12pt;font-family: Arial, sans-serif\">Hermosillo, Sonora; 31 de diciembre de 2013.-<\/span><\/strong><span style=\"line-height: 18px;font-size: 12pt;font-family: Arial, sans-serif\">&nbsp;Jes&uacute;s Armando Aguilar Ibarra, titular del Departamento de Prevenci&oacute;n y Atenci&oacute;n Ciudadana de la Jefatura de Polic&iacute;a Preventiva y Tr&aacute;nsito Municipal, present&oacute; esta ma&ntilde;ana un informe de actividades de 7 programas que el departamento que encabeza ha realizado desde marzo hasta mediados del mes de diciembre.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\"><span style=\"line-height: 18px;font-size: 12pt;font-family: Arial, sans-serif\">Estos programas que maneja consigo la direcci&oacute;n son de impacto social directo, tendiendo entre estos el manejo del grupo + Trepes, a trav&eacute;s del equipo de&nbsp;<strong style=\"line-height: 22px\">Asuntos Juveniles<\/strong>.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\"><span style=\"line-height: 18px;font-size: 12pt;font-family: Arial, sans-serif\">Este grupo atiende a 60 j&oacute;venes que durante el periodo comprendido entre marzo y diciembre lograron pintar m&aacute;s de 21 mil metro cuadrados de bardas y paredes &ldquo;valdalizadas&rdquo;, adem&aacute;s de rehabilitar 14 espacios p&uacute;blicos como parques o canchas deportivas, adem&aacute;s &nbsp;de realizar 8 reuniones con j&oacute;venes, dos con padres de familia y fomentar el deporte y la cultura a trav&eacute;s de 2 torneos y 4 actividades recreativas.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\"><span style=\"line-height: 18px;font-size: 12pt;font-family: Arial, sans-serif\">El&nbsp;<strong style=\"line-height: 22px\">M&oacute;dulo de Licencias<\/strong>&nbsp;brind&oacute; un total de 13 mil 253 servicios entre los que se encuentran cursos, ex&aacute;menes y revisiones m&eacute;dicas, adem&aacute;s del extrav&iacute;o de placas. Adem&aacute;s autoriz&oacute; 6 mil 131 licencias de conducir tras cumplir con los ex&aacute;menes y requisitos obligatorios.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\"><span style=\"line-height: 18px;font-size: 12pt;font-family: Arial, sans-serif\">A trav&eacute;s del programa&nbsp;<strong style=\"line-height: 22px\">Comercio Seguro<\/strong>, se brindaron pl&aacute;ticas a grandes, medianos y peque&ntilde;os comerciantes sobre el reforzamiento de la seguridad en sus locales, a trav&eacute;s de visitas y volantes, los cuales sumaron un total de 3 mil 006 comercios visitados y 5 mil 781 volantes y tr&iacute;pticos entregados.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\"><span style=\"line-height: 18px;font-size: 12pt;font-family: Arial, sans-serif\">El&nbsp;<strong style=\"line-height: 22px\">programa DARE<\/strong>&nbsp;imparti&oacute; 186 cursos en diversas escuelas primarias de la entidad, y asesor&oacute; y apoy&oacute; a 6 empresas locales para reforzar el desarrollo de los ni&ntilde;os y blindarlos contra el consumo de drogas.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\"><span style=\"line-height: 18px;font-size: 12pt;font-family: Arial, sans-serif\">El grupo de&nbsp;<strong style=\"line-height: 22px\">Educaci&oacute;n Vial<\/strong>&nbsp;llev&oacute; el conocimiento de la Ley de Tr&aacute;nsito a 135 escuelas de la ciudad y &aacute;rea rural, formando mejores ciudadanos en el respeto a las normas viales, adem&aacute;s imparti&oacute; cursos en 3 importantes empresas para el personal operativo y de repartici&oacute;n.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\"><span style=\"line-height: 18px;font-size: 12pt;font-family: Arial, sans-serif\">El&nbsp;<strong style=\"line-height: 22px\">Grupo Especializado en Atenci&oacute;n a V&iacute;ctimas de Violencia Intrafamiliar (Geavi)<\/strong>&nbsp;atendi&oacute; un total de 514 reportes de violencia dom&eacute;stica, a los cuales se les dio seguimiento tanto de la parte afectada como de la parte agresora, con el firme prop&oacute;sito de tener hogares libres de violencia dom&eacute;stica en Hermosillo.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\"><span style=\"line-height: 18px;font-size: 12pt;font-family: Arial, sans-serif\">Otros resultados que anunci&oacute; el director de Prevenci&oacute;n y Atenci&oacute;n Ciudadana fueron el arrojado por la implementaci&oacute;n desde el pasado 18 de diciembre del programa&nbsp;<strong style=\"line-height: 22px\">Operativo Anti-alcohol<\/strong>, donde se instalaron 11 filtros preventivos de revisi&oacute;n en las calles de la ciudad,&nbsp; con entrega de m&aacute;s de26 mil volantes que invitan a los ciudadanos a usar el cintur&oacute;n de seguridad y evitar manejar bajo los efectos del alcohol.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estos programas que maneja consigo la direcci&oacute;n son de impacto social directo, tendiendo entre estos el manejo del grupo + Trepes, a trav&eacute;s del equipo de Asuntos Juveniles.<\/p>\n","protected":false},"author":1,"featured_media":19554,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[200],"class_list":["post-3546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-seguridad-publica"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2013\/12\/1388517051_IMG_0046.JPG","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/3546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=3546"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/3546\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/19554"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=3546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=3546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=3546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}