{"id":3388,"date":"2013-12-23T12:04:35","date_gmt":"2013-12-23T12:04:35","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2013\/12\/23\/muere-mijal-kalshnikov-creador-del-cuerno-de-chivo\/"},"modified":"2013-12-23T12:04:35","modified_gmt":"2013-12-23T12:04:35","slug":"muere-mijal-kalshnikov-creador-del-cuerno-de-chivo","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2013\/12\/23\/muere-mijal-kalshnikov-creador-del-cuerno-de-chivo\/","title":{"rendered":"Muere Mija&iacute;l Kal&aacute;shnikov, creador del &quot;cuerno de chivo&quot;"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mija&iacute;l Kal&aacute;shnikov<\/strong>, creador de una de las armas m&aacute;s famosas en el mundo, el fusil de asalto AK-47, apodado &#8220;cuerno de chivo&#8221;, falleci&oacute; a la edad de 94 a&ntilde;os.<\/p>\n<p>Kal&aacute;shnikov muri&oacute; en un hospital de la ciudad de Izhevsk, seg&uacute;n un reporte del portavoz del presidente de la rep&uacute;blica rusa de Udmurtia, V&iacute;ktor Chulkov. F<span style=\"line-height: 1.6\">ue hospitalizado&nbsp;<\/span><span style=\"line-height: 1.6\">17 de noviembre&nbsp;<\/span><span style=\"line-height: 1.6\">debido a una hemorragia g&aacute;strica.<\/span><\/p>\n<p><span style=\"line-height: 1.6\">El inventor ruso, que fue&nbsp;<\/span><span style=\"line-height: 1.6\">teniente general,<\/span><span style=\"line-height: 1.6\">&nbsp;tuvo una exitosa carrera militar. Obtuvo numerosos premios y t&iacute;tulos por sus invenciones, entre los cuales est&aacute;n el de&nbsp;<strong>H&eacute;roe de la Federaci&oacute;n de Rusia<\/strong>, la Orden de la Bandera Roja del Trabajo, la Orden Patri&oacute;tica de la Guerra de Primera Clase y la Orden de la Estrella Roja.<\/span><\/p>\n<p>Su fusil de asalto AK-47, que ya tiene m&aacute;s de 60 a&ntilde;os, est&aacute; considerado el mejor del mundo en su categor&iacute;a.<\/p>\n<p><strong>&bull;&nbsp;<a style=\"text-decoration: none;border: 0px\" href=\"http:\/\/www.sdpnoticias.com\/sorprendente\/2013\/11\/26\/video-lleva-ak-47-a-una-boda-termina-en-tragedia-al-bailar-el-gangnam-style\" target=\"_blank\" rel=\"noopener\"><span style=\"font-size: large\">VIDEO: Lleva AK-47 a una boda; termina en tragedia al bailar el Gangnam Style<\/span><\/a><\/strong><\/p>\n<p><strong>Fue dise&ntilde;ado en 1947<\/strong>&nbsp;y dos a&ntilde;os m&aacute;s tarde se inici&oacute; su fabricaci&oacute;n a gran escala. Muy pronto se convirti&oacute; en la principal arma ligera del Ej&eacute;rcito sovi&eacute;tico.<\/p>\n<p><span style=\"line-height: 1.6\">El &#8220;cuerno de chivo&#8221;, que&nbsp;se puede sumergir en el agua&nbsp;sin verse afectado en el funcionamiento, adquiri&oacute; gran popularidad en todo el mundo y supuso el inicio de una nueva &eacute;poca en la fabricaci&oacute;n de armas.<\/span><\/p>\n<p>Cabe destacar que el AK-47 es el &uacute;nico fusil de asalto que figura en la bandera y escudo nacionales de un pa&iacute;s, siendo el de Mozambique, ya que&nbsp;<strong>gracias a esta arma el pa&iacute;s logr&oacute; su independencia<\/strong>.<\/p>\n<p>Su silueta tambi&eacute;n aparece en el escudo de Zimbabue y en el de Timor Oriental desde el a&ntilde;o 2007. El AK-47 aparece igualmente en la bandera de la organizaci&oacute;n islamista chii Hezbol&aacute;.<\/p>\n<p><strong>El fusil se ha extendido tanto por todo el mundo que es el que m&aacute;s v&iacute;ctimas ha causado en la historia de la humanidad<\/strong>.<\/p>\n<p>&#8220;A menudo me preguntan si estoy contento con lo que me ha deparado la vida. Estoy contento. Estoy contento de haber dedicado toda la vida a algo que era necesario para el pueblo. Claro, un arma no es un tractor, una sembradora o un arado. Con un arma no se puede arar la tierra ni cultivar cereales. Pero sin ella uno no podr&aacute; defender su tierra natal, no podr&aacute; proteger la patria y a su pueblo&#8221;, expres&oacute;&nbsp;Kal&aacute;shnikov en sus memorias.<\/p>\n<p>El aut&eacute;ntico AK-47 pesa 4.3 kilogramos, su longitud es de 870 mil&iacute;metros (mm), la longitud del ca&ntilde;&oacute;n es de 415 mm y el calibre es 7.62 mm. La cadencia de tiro es de&nbsp;<strong>600 disparos por minuto<\/strong>&nbsp;y el cargador extra&iacute;ble curvo tiene capacidad para 30 cartuchos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>100 millones de fusiles AK-47 han sido elaborados desde su invenci&oacute;n. Ten&iacute;a 94 a&ntilde;os de edad.<\/p>\n","protected":false},"author":1,"featured_media":19446,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[182],"tags":[1156],"class_list":["post-3388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-cuerno-chivo"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2013\/12\/1387825475_MijailKalashnikov.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/3388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=3388"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/3388\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/19446"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=3388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=3388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=3388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}