{"id":33838,"date":"2015-06-12T13:06:27","date_gmt":"2015-06-12T13:06:27","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2015\/06\/12\/ine-entrega-constancia-de-mayora-a-ulises-cristpulos-ros\/"},"modified":"2015-06-12T13:06:27","modified_gmt":"2015-06-12T13:06:27","slug":"ine-entrega-constancia-de-mayora-a-ulises-cristpulos-ros","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2015\/06\/12\/ine-entrega-constancia-de-mayora-a-ulises-cristpulos-ros\/","title":{"rendered":"INE entrega constancia de mayor&iacute;a a Ulises Crist&ograve;pulos R&iacute;os"},"content":{"rendered":"<p>Por Redacci&ograve;n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span>Hermosillo, Son., 12 de junio de 2015<\/span><\/strong><span>.- Luego de contabilizarse el 100 por ciento de las casillas, el Instituto Nacional Electoral entreg&oacute; constancia de mayor&iacute;a a Ulises Crist&oacute;pulos R&iacute;os que lo acredita como Diputado Federal Electo por el 05 Distrito. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>El Consejero Presidente del &nbsp;05 Consejo Distrital en el Estado, Higinio P&eacute;rez Gonz&aacute;lez fue quien hizo entrega del documento a Crist&oacute;pulos R&iacute;os con el que avala su triunfo con cerca de 6 mil votos de diferencia sobre su m&aacute;s cercano adversario. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>El ahora Diputado Electo agradeci&oacute; a los miles de hermosillenses que depositaron la confianza en su proyecto y que se tradujo en m&aacute;s de 57 mil 216 votos durante la jornada electoral del domingo pasado. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&ldquo;Este triunfo es un verdadero compromiso con las familias hermosillenses, voy a trabajar para sacar adelante cada uno de los proyectos que junto con los ciudadanos, dise&ntilde;amos para elaborar mi plataforma legislativa&rdquo;, asegur&oacute; Crist&oacute;pulos R&iacute;os. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>Reiter&oacute; que temas como seguridad p&uacute;blica, empleo, salud, educaci&oacute;n, entre otros ser&aacute;n prioritarios como integrante de la C&aacute;mara de Diputados, luego que rinda protesta como Diputado Federal el pr&oacute;ximo primero de septiembre.&nbsp; <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de contabilizarse el 100 por ciento de las casillas, el Instituto Nacional Electoral entreg&oacute; constancia de mayor&iacute;a a Ulises Crist&oacute;pulos R&iacute;os que lo acredita como Diputado Federal Electo por el 05 Distrito.<\/p>\n","protected":false},"author":1,"featured_media":33839,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[2204],"class_list":["post-33838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-ulises-cristopulos"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1434139587_Entregadeconstancia.JPG","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/33838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=33838"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/33838\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/33839"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=33838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=33838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=33838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}