{"id":33339,"date":"2015-06-01T18:05:28","date_gmt":"2015-06-01T18:05:28","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2015\/06\/01\/carlos-navarro-rene-el-apoyo-de-ms-de-diez-mil-etchojoenses-2\/"},"modified":"2015-06-01T18:05:28","modified_gmt":"2015-06-01T18:05:28","slug":"carlos-navarro-rene-el-apoyo-de-ms-de-diez-mil-etchojoenses-2","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2015\/06\/01\/carlos-navarro-rene-el-apoyo-de-ms-de-diez-mil-etchojoenses-2\/","title":{"rendered":"Carlos Navarro re&uacute;ne el apoyo de m&aacute;s de diez mil etchojoenses"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"font-family: Tahoma,sans-serif\">Etchojoa, Sonora; 01 de junio de 2015.-<\/span><\/strong><span style=\"font-family: Tahoma,sans-serif\"> Un gobierno de puertas abiertas para el pueblo, es lo que ofrece Carlos Navarro L&oacute;pez, aspirante a gobernar Sonora por el Partido de la Revoluci&oacute;n Democr&aacute;tica (PRD), a miles de sonorenses que necesitan la ayuda de sus gobernantes.<\/span><\/p>\n<p><span style=\"font-family: Tahoma,sans-serif\">&nbsp;<\/span><\/p>\n<p><span style=\"font-family: Tahoma,sans-serif\">En su gran cierre de campa&ntilde;a que tuvo lugar en el coraz&oacute;n del Valle del Mayo, Navarro fue acompa&ntilde;ado de la f&oacute;rmula perredista del mismo municipio, quienes le brindaron su incondicional apoyo teniendo como testigo a miles de sonorenses que asistieron por su propio pie para escuchar el mensaje del pr&oacute;ximo gobernador de Sonora.<\/span><\/p>\n<p><span style=\"font-family: Tahoma,sans-serif\">&nbsp;<\/span><\/p>\n<p><span style=\"font-family: Tahoma,sans-serif\">El ingeniero agradeci&oacute; el respaldo a todas las candidaturas del PRD en el Estado de Sonora, y asegur&oacute; que otra vez va creciendo esa ola amarilla que trae consigo el resurgimiento electoral del PRD, invitando a los ciudadanos a que no hagan caso a unos pocos mercenarios que se fueron por sus propios intereses a otro lado.<\/span><\/p>\n<p><span style=\"font-family: Tahoma,sans-serif\">&nbsp;<\/span><\/p>\n<p><span style=\"font-family: Tahoma,sans-serif\">&ldquo;No quiero que exista ninguna confusi&oacute;n, el PRD no va con el PAN ni con ning&uacute;n otro partido, por eso todo el amarillo es nuestro color, nuestra identidad y quienes porten esas playeras azules diciendo que son perredistas pero que apoyan al PAN, no son del PRD, c&oacute;rranlos, y como en Nogales denles su repudio a esos que se metieron al gobierno y creen que nos van a da&ntilde;ar a nosotros, cuando le van a afectar al PAN, y que se agarren la billetera los panistas porque algunos vividores ya se fueron de aqu&iacute;&rdquo;, expres&oacute;.<\/span><\/p>\n<p><span style=\"font-family: Tahoma,sans-serif\">&nbsp;<\/span><\/p>\n<p><span style=\"font-family: Tahoma,sans-serif\">Entre gritos de entusiasmo por aquellos que desean el giro que Carlos Navarro puede darle a nuestro estado, la gente coreando dec&iacute;a &ldquo;<\/span><span style=\"font-family: Tahoma,sans-serif;background-image: initial;background-repeat: initial\">Navarro, amigo, el pueblo est&aacute; contigo&rdquo;, aumentando las fuerzas del candidato para seguir adelante y luchar con todo para mejorar la calidad de vida de todos y cada uno de los sonorenses.<\/span><\/p>\n<p><span style=\"font-family: Tahoma,sans-serif;background-image: initial;background-repeat: initial\">&nbsp;<\/span><\/p>\n<p><span style=\"font-family: Tahoma,sans-serif;background-image: initial;background-repeat: initial\">Siempre pensando en el beneficio del pueblo, el aspirante del &ldquo;sol azteca&rdquo;, se comprometi&oacute; en que llegando a la gubernatura reactivar&aacute; la econom&iacute;a a lo largo y ancho del estado, enfatizando que en su gobierno no existir&aacute; la corrupci&oacute;n, y el presupuesto llegar&aacute; intacto a su destino, dando prioridad a los m&aacute;s vulnerables y desprotegidos.<\/span><\/p>\n<p><span style=\"font-family: Tahoma,sans-serif;background-image: initial;background-repeat: initial\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;background-image: initial;background-repeat: initial\">&nbsp;<\/p>\n<p><span style=\"font-family: Tahoma,sans-serif;background-image: initial;background-repeat: initial\">Por otra parte en su propuesta n&uacute;mero 56, Carlos Navarro prev&eacute; para su gobierno una fuerte apuesta para el rescate del campo sonorense, pero no solo en los Valles del Yaqui y de Mayo, sino tambi&eacute;n en los valles de Caborca, Sonoyta y San Luis R&iacute;o Colorado, y para ello adoptar&aacute; el compromiso de reconstruir las carreteras y caminos vecinales de estos valles, as&iacute; como la reconstrucci&oacute;n y ampliaci&oacute;n de la carretera Caborca &ndash; Puerto Pe&ntilde;asco.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En su gran cierre de campa&ntilde;a que tuvo lugar en el coraz&oacute;n del Valle del Mayo, Navarro fue acompa&ntilde;ado de la f&oacute;rmula perredista del mismo municipio, quienes le brindaron su incondicional apoyo teniendo como testigo a miles de sonorenses que asistieron<\/p>\n","protected":false},"author":1,"featured_media":33340,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[202],"class_list":["post-33339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-carlos-navarro"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1433207128_11391542_10203135012331309_569927631271206843_n.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/33339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=33339"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/33339\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/33340"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=33339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=33339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=33339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}