{"id":264048,"date":"2026-07-15T10:56:37","date_gmt":"2026-07-15T17:56:37","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/?p=264048"},"modified":"2026-07-15T10:56:37","modified_gmt":"2026-07-15T17:56:37","slug":"gobierno-de-sonora-impulsa-la-educacion-superior-en-la-zona-del-rio-altar","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2026\/07\/15\/gobierno-de-sonora-impulsa-la-educacion-superior-en-la-zona-del-rio-altar\/","title":{"rendered":"Gobierno de Sonora impulsa la educaci\u00f3n superior en la zona del R\u00edo Altar"},"content":{"rendered":"<p align=\"left\">Altar, Sonora; 15 de julio de 2026.- Con el prop\u00f3sito de fortalecer la vinculaci\u00f3n entre la educaci\u00f3n superior y el desarrollo regional en toda la entidad, el Gobierno de Sonora, a trav\u00e9s de la Universidad Tecnol\u00f3gica de Hermosillo (UTH), llev\u00f3 a cabo la reuni\u00f3n para la conformaci\u00f3n del Patronato de su Extensi\u00f3n Altar, en compa\u00f1\u00eda de presidentes, empresarios y representantes del sector educativo.<\/p>\n<p align=\"left\">Autoridades universitarias presentaron la visi\u00f3n institucional para la Extensi\u00f3n R\u00edo Altar, destacando un modelo educativo innovador basado en laboratorios especializados, aprendizaje pr\u00e1ctico y una estrecha vinculaci\u00f3n con los sectores productivos y alcald\u00edas de la regi\u00f3n.<\/p>\n<p align=\"left\">El rector de la UTH, Abel Leyva Castellanos, declar\u00f3 que la Extensi\u00f3n Altar representa un proyecto estrat\u00e9gico que ampliar\u00e1 las oportunidades de inserci\u00f3n laboral en la zona, destacando los avances del proyecto con la inauguraci\u00f3n de la oficina de atenci\u00f3n a estudiantes para inscripciones al ciclo 2026-2027 de la UTH, as\u00ed como de una sala de negocios para reuniones con empresarios de la zona del R\u00edo Altar.<\/p>\n<p align=\"left\">Por su parte, Carlos Castillo, director de los programas educativos en Mantenimiento Industrial y Energ\u00eda y Desarrollo Sostenible de UTH, explic\u00f3 que actualmente se est\u00e1 colaborando con instituciones de Nuevo M\u00e9xico especializadas en energ\u00edas sustentables, mejorando as\u00ed la oferta educativa que se les proporcionar\u00e1 a las y los futuros alumnos.<\/p>\n<p align=\"left\">Aunado a esto, Sergio Hallack Sotomayor, director del programa educativo en Miner\u00eda de UTH, inform\u00f3 que se da seguimiento permanente al sector minero y a los proyectos regionales, afianzando as\u00ed los v\u00ednculos entre la universidad y las empresas, punto que tambi\u00e9n se est\u00e1 reforzando a trav\u00e9s de las carreras en Mec\u00e1nica, Mecatr\u00f3nica y Aeron\u00e1utica en Manufactura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Altar, Sonora; 15 de julio de 2026.- Con el prop\u00f3sito de fortalecer la vinculaci\u00f3n entre la educaci\u00f3n superior y el desarrollo regional en toda la entidad, el Gobierno de Sonora, a trav\u00e9s de la Universidad Tecnol\u00f3gica de Hermosillo (UTH), llev\u00f3 a cabo la reuni\u00f3n para la conformaci\u00f3n del Patronato de su Extensi\u00f3n Altar, en compa\u00f1\u00eda [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":264049,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12870,174],"tags":[12865,12873],"class_list":["post-264048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-estatal","tag-destacadas","tag-estatal"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2026\/07\/unnamed-19-8.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/264048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=264048"}],"version-history":[{"count":1,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/264048\/revisions"}],"predecessor-version":[{"id":264050,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/264048\/revisions\/264050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/264049"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=264048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=264048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=264048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}