{"id":263931,"date":"2026-07-14T20:57:53","date_gmt":"2026-07-15T03:57:53","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/?p=263931"},"modified":"2026-07-14T20:57:53","modified_gmt":"2026-07-15T03:57:53","slug":"gilberto-mora-gran-ausente-en-lista-de-mexico-para-preolimpico-y-premundial-de-concacaf","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2026\/07\/14\/gilberto-mora-gran-ausente-en-lista-de-mexico-para-preolimpico-y-premundial-de-concacaf\/","title":{"rendered":"Gilberto Mora, gran ausente en lista de M\u00e9xico para preol\u00edmpico y premundial de Concacaf"},"content":{"rendered":"<p><strong>Gilberto Mora<\/strong>, mundialista de 17 a\u00f1os, es el gran ausente en la convocatoria que este lunes dio a conocer la\u00a0<strong>selecci\u00f3n mexicana Sub-20 para participar en el preol\u00edmpico y premundial de la Concacaf de julio pr\u00f3ximo.<\/strong><\/p>\n<p>Mora, la reciente joya del f\u00fatbol mexicano,<strong>\u00a0tuvo una destacada participaci\u00f3n en la pasada Copa del Mundo 2026 en la que fue titular en tres de los cuatro partidos en los que particip\u00f3 hasta la eliminaci\u00f3n del Tri en octavos de final ante Inglaterra.<\/strong><\/p>\n<p>Ante la ausencia de Gilberto Mora, Diego Reyes, delantero de 18 a\u00f1os que juega en el Flamengo de Brasil,\u00a0<strong>es una de las principales estrellas en el equipo del seleccionador \u00c1lex Diego.<\/strong><\/p>\n<p>Tambi\u00e9n se destacan Henrique Simeone, centrocampista mexico-brasile\u00f1o de 19 a\u00f1os procedente de las fuerzas b\u00e1sicas del Botafogo de Brasil, que hoy juega para los Tigres UANL, y el guardameta Artemio Olvera, del San Luis.<\/p>\n<p>Este torneo, que se realizar\u00e1 del 24 de julio al 9 de agosto pr\u00f3ximos,\u00a0<strong>servir\u00e1 como clasificatorio para la Copa Mundial Sub-20 de la FIFA 2027 y los Juegos Ol\u00edmpicos de Verano 2028.<\/strong><\/p>\n<p>Las cuatro selecciones que alcancen las<strong>\u00a0semifinales avanzar\u00e1n al Mundial a disputarse en Azerbaiy\u00e1n y Uzbekist\u00e1n 2027<\/strong>. El campe\u00f3n del torneo obtendr\u00e1 su boleto a los Juegos Ol\u00edmpicos de Los \u00c1ngeles 2028.<\/p>\n<p><strong>M\u00e9xico comparte el grupo B con Guatemala, Costa Rica y Antigua y Barbuda. En el sector A est\u00e1n Estados Unidos, Cuba, El Salvador y Hait\u00ed, y el grupo C lo conforman Honduras, Panam\u00e1, Canad\u00e1 y Jamaica.<\/strong><\/p>\n<p>&#8211; Lista de la selecci\u00f3n mexicana sub-20 para el premundial y preol\u00edmpico de Concacaf:<\/p>\n<ul>\n<li>Guardametas:<strong>\u00a0Artemio Olvera (San Luis), Cristo Navarrete y Juan Liceaga (Guadalajara).<\/strong><\/li>\n<li>Defensas:\u00a0<strong>Juan Echilvestre (Santos Laguna), Crist\u00f3bal Alfaro (Atlante), Luis Carmona (Ju\u00e1rez), Carlos Hern\u00e1ndez y Yohan Orozco (Guadalajara), Esteban Soto (Pachuca).<\/strong><\/li>\n<li>Centrocampistas:\u00a0<strong>Diego Covarrubias (Guadalajara), Nelson Cedillo (Santos Laguna), Cristian Inda (Guadalajara), Henrique Simeone (Tigres UANL), Juan S\u00edgala (Ju\u00e1rez), Luis G\u00f3mez (Santos Laguna), Santiago Sandoval (Guadalajara).<\/strong><\/li>\n<li>Delanteros:\u00a0<strong>Luis Gamboa (Atlas), Hugo Camberos (Guadalajara), Diego Reyes (Flamengo-BRA), Diego Ram\u00edrez (Tigres) y Aldahir Valenzuela (Monterrey). \u00a0\u00a0\u00a0<\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Gilberto Mora, mundialista de 17 a\u00f1os, es el gran ausente en la convocatoria que este lunes dio a conocer la\u00a0selecci\u00f3n mexicana Sub-20 para participar en el preol\u00edmpico y premundial de la Concacaf de julio pr\u00f3ximo. Mora, la reciente joya del f\u00fatbol mexicano,\u00a0tuvo una destacada participaci\u00f3n en la pasada Copa del Mundo 2026 en la que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":263932,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188,12870],"tags":[5231,12865],"class_list":["post-263931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-destacadas","tag-deportes","tag-destacadas"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2026\/07\/gilberto-mora-seleccion-mexicana.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/263931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=263931"}],"version-history":[{"count":1,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/263931\/revisions"}],"predecessor-version":[{"id":263933,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/263931\/revisions\/263933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/263932"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=263931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=263931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=263931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}