{"id":255726,"date":"2026-05-12T20:41:09","date_gmt":"2026-05-13T03:41:09","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/?p=255726"},"modified":"2026-05-12T20:41:09","modified_gmt":"2026-05-13T03:41:09","slug":"obtiene-fgjes-vinculacion-a-proceso-contra-imputado-por-tentativa-de-homicidio-en-hermosillo","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2026\/05\/12\/obtiene-fgjes-vinculacion-a-proceso-contra-imputado-por-tentativa-de-homicidio-en-hermosillo\/","title":{"rendered":"Obtiene FGJES vinculaci\u00f3n a proceso contra imputado por tentativa de homicidio en Hermosillo"},"content":{"rendered":"<p>Hermosillo, Sonora, 12 de mayo de 2026.- La Fiscal\u00eda General de Justicia del Estado de Sonora (FGJES) obtuvo la vinculaci\u00f3n a proceso de Alexis \u201cN\u201d, se\u00f1alado como probable responsable del delito de tentativa de homicidio calificado con premeditaci\u00f3n y ventaja, cometido en perjuicio de Eduardo \u201cN\u201d, en Hermosillo.<\/p>\n<p>La audiencia inicial se realiz\u00f3 tras la ejecuci\u00f3n de una orden de aprehensi\u00f3n cumplimentada por elementos de la Agencia Ministerial de Investigaci\u00f3n Criminal (AMIC) al interior de un centro de reclusi\u00f3n, donde el imputado permanece interno por diverso delito relacionado con narcomenudeo.<\/p>\n<p>De acuerdo con los datos de prueba integrados en la carpeta de investigaci\u00f3n, los hechos ocurrieron el pasado 24 de abril, cuando Alexis \u201cN\u201d, identificado como integrante de un grupo generador de violencia, arrib\u00f3 a un domicilio ubicado en la colonia 5 de Mayo, se\u00f1alado como presunto punto de venta de droga.<\/p>\n<p>Las investigaciones establecen que el imputado accion\u00f3 un arma de fuego en contra de la v\u00edctima, logrando lesionarla para posteriormente retirarse del lugar.<\/p>\n<p>Durante la audiencia, el agente del Ministerio P\u00fablico formul\u00f3 imputaci\u00f3n y expuso los elementos de prueba recabados, mismos que fueron valorados por el Juez, quien resolvi\u00f3 vincular a proceso al imputado en los t\u00e9rminos solicitados por esta representaci\u00f3n social.<\/p>\n<p>Adem\u00e1s, la autoridad judicial impuso la medida cautelar de prisi\u00f3n preventiva justificada, por lo que Alexis \u201cN\u201d permanecer\u00e1 interno mientras contin\u00faan las investigaciones complementarias.<\/p>\n<p>La Fiscal\u00eda General de Justicia del Estado de Sonora mantiene acciones permanentes para investigar y combatir hechos violentos relacionados con grupos generadores de violencia, fortaleciendo las labores de inteligencia y procuraci\u00f3n de justicia para garantizar la seguridad de la poblaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora, 12 de mayo de 2026.- La Fiscal\u00eda General de Justicia del Estado de Sonora (FGJES) obtuvo la vinculaci\u00f3n a proceso de Alexis \u201cN\u201d, se\u00f1alado como probable responsable del delito de tentativa de homicidio calificado con premeditaci\u00f3n y ventaja, cometido en perjuicio de Eduardo \u201cN\u201d, en Hermosillo. La audiencia inicial se realiz\u00f3 tras la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":255727,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[12869],"class_list":["post-255726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-local"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-2.02.35-PM.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/255726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=255726"}],"version-history":[{"count":1,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/255726\/revisions"}],"predecessor-version":[{"id":255728,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/255726\/revisions\/255728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/255727"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=255726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=255726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=255726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}