{"id":255723,"date":"2026-05-12T20:39:57","date_gmt":"2026-05-13T03:39:57","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/?p=255723"},"modified":"2026-05-12T20:39:57","modified_gmt":"2026-05-13T03:39:57","slug":"fgjes-formula-imputacion-y-obtiene-prision-preventiva-contra-detenido-por-agresion-ocurrida-en-la-expogan-de-hermosillo","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2026\/05\/12\/fgjes-formula-imputacion-y-obtiene-prision-preventiva-contra-detenido-por-agresion-ocurrida-en-la-expogan-de-hermosillo\/","title":{"rendered":"FGJES formula imputaci\u00f3n y obtiene prisi\u00f3n preventiva contra detenido por agresi\u00f3n ocurrida en la ExpoGan de Hermosillo"},"content":{"rendered":"<p>Hermosillo, Sonora, 12 de mayo de 2026.- La Fiscal\u00eda General de Justicia del Estado de Sonora (FGJES) formul\u00f3 imputaci\u00f3n en contra de Javier Ignacio \u201cN\u201d, se\u00f1alado como probable responsable del delito de lesiones que tardan m\u00e1s de 15 d\u00edas en sanar y ponen en peligro la vida, calificadas con ventaja, en perjuicio de Jes\u00fas Manuel \u201cN\u201d.<\/p>\n<p>La audiencia inicial se realiz\u00f3 derivado de la orden de aprehensi\u00f3n reci\u00e9n ejecutada por elementos de la Agencia Ministerial de Investigaci\u00f3n Criminal (AMIC), en coordinaci\u00f3n con la Polic\u00eda Estatal de Seguridad P\u00fablica (PESP), quienes ubicaron y capturaron al imputado en el municipio de Empalme.<\/p>\n<p>Durante la diligencia judicial, la Audiencia registr\u00f3 un retraso aproximado de media hora debido a la incorporaci\u00f3n de una defensa particular, motivo por el cual el Juez decret\u00f3 un receso de una hora para que la representaci\u00f3n legal del imputado tuviera acceso e impusiera de la carpeta de investigaci\u00f3n.<\/p>\n<p>Concluido el receso, el agente del Agente del Ministerio P\u00fablico formul\u00f3 imputaci\u00f3n y solicit\u00f3 la vinculaci\u00f3n a proceso del imputado, mientras que la defensa solicit\u00f3 la ampliaci\u00f3n del t\u00e9rmino constitucional, fij\u00e1ndose un plazo de 72 horas para la continuaci\u00f3n de la audiencia donde se resolver\u00e1 la situaci\u00f3n jur\u00eddica del se\u00f1alado.<\/p>\n<p>Tras el debate entre las partes respecto a las medidas cautelares, el Juez resolvi\u00f3 imponer prisi\u00f3n preventiva justificada, por lo que Javier Ignacio \u201cN\u201d permanecer\u00e1 interno mientras contin\u00faa el procedimiento penal.<\/p>\n<p>Los hechos que se le imputan ocurrieron durante la madrugada del pasado 3 de mayo en el exterior de la ExpoGan, sobre el bulevar De los Ganaderos, en la colonia Las Lomas, en Hermosillo.<\/p>\n<p>De acuerdo con las investigaciones, la v\u00edctima Jes\u00fas Manuel \u201cN\u201d, de 35 a\u00f1os, se encontraba acompa\u00f1ado de un sobrino cuando presuntamente fue agredido f\u00edsica y verbalmente por un grupo aproximado de seis masculinos.<\/p>\n<p>Durante la agresi\u00f3n cay\u00f3 al suelo y continu\u00f3 siendo golpeado, resultando con traumatismo craneoencef\u00e1lico severo que puso en peligro su vida, por lo que requiri\u00f3 atenci\u00f3n m\u00e9dica especializada e intubaci\u00f3n hospitalaria.<\/p>\n<p>La Fiscal\u00eda General de Justicia del Estado de Sonora mantiene acciones permanentes para investigar hechos de violencia y llevar ante la justicia a quienes atenten contra la integridad f\u00edsica y la vida de las personas, fortaleciendo el trabajo coordinado entre corporaciones de seguridad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora, 12 de mayo de 2026.- La Fiscal\u00eda General de Justicia del Estado de Sonora (FGJES) formul\u00f3 imputaci\u00f3n en contra de Javier Ignacio \u201cN\u201d, se\u00f1alado como probable responsable del delito de lesiones que tardan m\u00e1s de 15 d\u00edas en sanar y ponen en peligro la vida, calificadas con ventaja, en perjuicio de Jes\u00fas Manuel [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":255724,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12870,178],"tags":[12865,12869],"class_list":["post-255723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-local","tag-destacadas","tag-local"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2026\/05\/3233.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/255723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=255723"}],"version-history":[{"count":1,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/255723\/revisions"}],"predecessor-version":[{"id":255725,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/255723\/revisions\/255725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/255724"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=255723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=255723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=255723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}