{"id":255674,"date":"2026-05-12T16:26:29","date_gmt":"2026-05-12T23:26:29","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/?p=255674"},"modified":"2026-05-12T16:26:29","modified_gmt":"2026-05-12T23:26:29","slug":"florentino-perez-descarta-renunciar-y-buscara-la-reeleccion-en-real-madrid","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2026\/05\/12\/florentino-perez-descarta-renunciar-y-buscara-la-reeleccion-en-real-madrid\/","title":{"rendered":"Florentino P\u00e9rez descarta renunciar y buscar\u00e1 la reelecci\u00f3n en Real Madrid"},"content":{"rendered":"<p><strong>Florentino P\u00e9rez<\/strong>\u00a0ofreci\u00f3 este martes una conferencia de prensa en la\u00a0<strong>Ciudad Deportiva de Valdebebas<\/strong>, donde dej\u00f3 clara su intenci\u00f3n de mantenerse al frente del\u00a0<strong>Real Madrid<\/strong>\u00a0al anunciar que\u00a0<mark>no presentar\u00e1 su dimisi\u00f3n<\/mark>\u00a0y que\u00a0<mark>convocar\u00e1 a elecciones<\/mark>, proceso en el que se presentar\u00e1 como candidato para buscar\u00a0<mark>la renovaci\u00f3n de su mandato<\/mark>.<\/p>\n<p>&#8220;Lamento decirles que no voy a dimitir. He pedido a la Junta Electoral que inicie el proceso electoral a las elecciones a la Junta Directiva a la que nos vamos a presentar. \u00bfPor qu\u00e9 convoco las elecciones? Porque trabaj\u00e9 desde el a\u00f1o 2000 para que los due\u00f1os del club fueran los socios, a diferencia de los otros clubes&#8221;.<\/p>\n<p>&#8220;<mark>En el Madrid no hay un solo due\u00f1o. He tomado esta decisi\u00f3n porque se ha creado una situaci\u00f3n absurda para generar una corriente de opini\u00f3n contra los intereses del Real Madrid<\/mark>&#8220;, se\u00f1al\u00f3 P\u00e9rez.<\/p>\n<p>El presidente no permiti\u00f3 cuestionamientos relacionados con el futuro del banquillo merengue, asunto que ha generado especulaci\u00f3n en semanas recientes. Tampoco quiso entrar en detalles sobre fichajes, salidas o planificaci\u00f3n deportiva, insistiendo en que la comparecencia ten\u00eda \u00fanicamente fines institucionales.<\/p>\n<p>&nbsp;<\/p>\n<h2>Caso Valverde-Tchouam\u00e9ni<\/h2>\n<p>Uno de los momentos m\u00e1s llamativos lleg\u00f3 cuando fue consultado por la presunta pelea entre Federico Valverde y Aur\u00e9lien Tchouam\u00e9ni.\u00a0<mark>P\u00e9rez minimiz\u00f3 la situaci\u00f3n al se\u00f1alar que en sus 26 a\u00f1os como presidente no ha existido una sola temporada sin conflictos internos en el vestidor, aunque s\u00ed critic\u00f3 que este tipo de episodios hayan sido filtrados al exterior<\/mark>.<\/p>\n<p>&#8220;Me parece muy mal, pero me parece peor que lo hayan sacado a la luz. Porque yo llevo 26 a\u00f1os, le puedo asegurar que no ha habido un a\u00f1o en estos 26 que no se hayan pegado dos jugadores o cuatro, pero queda dentro de la casa. A mi me parece muy mal que lo hayan sacado, seguro que quienes lo filtraron, no estar\u00e1n contentos porque pensar\u00e1n que van a salir&#8221;, a\u00f1adi\u00f3 el mandam\u00e1s.<\/p>\n<p>&nbsp;<\/p>\n<h2>Negreira y el robo de ligas<\/h2>\n<p><mark><strong>El dirigente tambi\u00e9n aprovech\u00f3 para referirse al denominado caso Negreira, volviendo a se\u00f1alar a FC Barcelona<\/strong><\/mark>. Seg\u00fan explic\u00f3, el club merengue prepara un documento que ser\u00e1 enviado a UEFA con la intenci\u00f3n de que existan repercusiones, pese a que los hechos investigados se remontan a varios a\u00f1os atr\u00e1s.\u00a0<mark>Adem\u00e1s, asever\u00f3 que s\u00f3lo ha ganado siete ligas, porque le han robado otras siete<\/mark>.<\/p>\n<p>&#8220;Hace tres a\u00f1os nos enteramos de un caso de corrupci\u00f3n como el caso Negreira. No hay precedentes en la historia del futbol mundial. Es incomprensible que a\u00fan estemos viendo \u00e1rbitros de aquella \u00e9poca en una competici\u00f3n como LaLiga. Ha durado dos d\u00e9cadas pagando. Son los mismos \u00e1rbitros y estamos haciendo un dossier importante que vamos a presentar de inmediato a la UEFA para que ataje de ra\u00edz y resuelva por el bien del f\u00fatbol mundial el caso Negreira&#8221;.<\/p>\n<p>&#8220;Yo he ganado siete Champions, que s\u00e9 que son pocas, y solo siete ligas, que ah\u00ed es lo malo, porque podr\u00eda haber ganado 14, pero me las han robado. Y yo tengo que meterme con el caso Negreira porque es un tema de corrupci\u00f3n&#8221;, manifest\u00f3 Florentino.<\/p>\n<h2>Barcelona se defiende<\/h2>\n<p>Tras las declaraciones emitidas por Florentino P\u00e9rez,\u00a0<mark>el conjunto blaugrana lanz\u00f3 un comunicado en el que inform\u00f3 que est\u00e1n tomando medidas legales con la intenci\u00f3n de estudiar minuciosamente las palabras del dirigente merengue<\/mark>.<\/p>\n<p>&#8220;En referencia a la rueda de prensa convocada por el presidente del Real Madrid, Florentino P\u00e9rez, informamos de que nuestro departamento legal est\u00e1 estudiando detenidamente sus manifestaciones y acusaciones. En estos momentos se est\u00e1n analizando las mismas y valorando los pr\u00f3ximos pasos a seguir. Cuando se considere oportuno, se informar\u00e1 adecuadamente sobre las posiciones y decisiones que se adopten&#8221;, se lee en la misiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Florentino P\u00e9rez\u00a0ofreci\u00f3 este martes una conferencia de prensa en la\u00a0Ciudad Deportiva de Valdebebas, donde dej\u00f3 clara su intenci\u00f3n de mantenerse al frente del\u00a0Real Madrid\u00a0al anunciar que\u00a0no presentar\u00e1 su dimisi\u00f3n\u00a0y que\u00a0convocar\u00e1 a elecciones, proceso en el que se presentar\u00e1 como candidato para buscar\u00a0la renovaci\u00f3n de su mandato. &#8220;Lamento decirles que no voy a dimitir. He pedido [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":255675,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188,12870],"tags":[5231,12865],"class_list":["post-255674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-destacadas","tag-deportes","tag-destacadas"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2026\/05\/florentino-perez-real-madrid.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/255674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=255674"}],"version-history":[{"count":1,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/255674\/revisions"}],"predecessor-version":[{"id":255676,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/255674\/revisions\/255676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/255675"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=255674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=255674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=255674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}