{"id":255659,"date":"2026-05-12T16:18:23","date_gmt":"2026-05-12T23:18:23","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/?p=255659"},"modified":"2026-05-12T16:18:23","modified_gmt":"2026-05-12T23:18:23","slug":"sinaloa-es-como-venezuela-por-caso-rocha-moya-loret-de-mola","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2026\/05\/12\/sinaloa-es-como-venezuela-por-caso-rocha-moya-loret-de-mola\/","title":{"rendered":"Sinaloa es como Venezuela, por caso Rocha Moya: Loret de Mola"},"content":{"rendered":"<p>El periodista\u00a0<a href=\"https:\/\/www.informador.mx\/carlos-loret-de-mola-t2925\" target=\"_blank\" rel=\"noopener\"><strong>Carlos Loret de Mola<\/strong><\/a>\u00a0compar\u00f3 la situaci\u00f3n pol\u00edtica y social del estado mexicano de\u00a0<a href=\"https:\/\/www.informador.mx\/sinaloa-t1248\" target=\"_blank\" rel=\"noopener\"><strong>Sinaloa<\/strong><\/a>\u00a0con la crisis vivida en Venezuela, al analizar la salida temporal de Rub\u00e9n Rocha Moya de la gubernatura en medio del conflicto de seguridad que afecta al estado desde septiembre de 2024.<\/p>\n<p>En su planteamiento, sostuvo que, as\u00ed\u00a0<mark><strong>como ocurri\u00f3 con la reacci\u00f3n de algunos sectores tras la ca\u00edda de Nicol\u00e1s Maduro, la salida del mandatario sinaloense ha generado reacciones divididas por la forma en que ocurri\u00f3, aunque para parte de la ciudadan\u00eda el fondo del cambio resulta m\u00e1s importante.<\/strong><\/mark><\/p>\n<p>Seg\u00fan expuso Loret, desde que comenz\u00f3 la guerra al interior del\u00a0<a href=\"https:\/\/www.informador.mx\/cartel-de-sinaloa-t5199\" target=\"_blank\" rel=\"noopener\"><strong>C\u00e1rtel de Sinaloa<\/strong><\/a>, dos expresiones con el apellido del gobernador se convirtieron en s\u00edmbolos del descontento ciudadano. La primera fue &#8220;<strong>\u00bfY el Roooocha?&#8221;<\/strong>, frase que, de acuerdo con el an\u00e1lisis, surgi\u00f3 como burla, meme y una forma de cuestionar la ausencia del mandatario frente a la crisis que viv\u00eda la entidad.<\/p>\n<p>La segunda expresi\u00f3n fue\u00a0<strong>&#8220;\u00a1Fuera Rocha!&#8221;<\/strong>, consigna que, seg\u00fan el periodista, dej\u00f3 de ser solamente una protesta para convertirse en un deseo de una parte de la poblaci\u00f3n, principalmente en Culiac\u00e1n, donde se han resentido con mayor intensidad los efectos del conflicto.<\/p>\n<div class=\" b2\"><\/div>\n<h2>La comparaci\u00f3n entre Sinaloa y Venezuela<\/h2>\n<p>En su columna de este 12 de mayo titulada\u00a0<a href=\"https:\/\/www.informador.mx\/ideas\/carlos-loret-de-mola-sinaloa-el-venezuela-mexicano-20260512-0024.html\" target=\"_blank\" rel=\"noopener\"><strong>&#8220;Sinaloa, el Venezuela mexicano&#8221;<\/strong><\/a>, Loret se\u00f1al\u00f3 que entre sectores de la poblaci\u00f3n sinaloense se consolid\u00f3 la percepci\u00f3n de que la salida de Rub\u00e9n Rocha Moya representaba una condici\u00f3n necesaria para iniciar una posible soluci\u00f3n a la crisis de violencia que se ha extendido por un a\u00f1o y medio.<\/p>\n<p>Tambi\u00e9n afirm\u00f3 que la desesperaci\u00f3n ciudadana aument\u00f3 hasta que, seg\u00fan su planteamiento, se dio a conocer que Rocha Moya solicit\u00f3 licencia para separarse temporalmente del cargo.<\/p>\n<p>A partir de ese hecho, el periodista estableci\u00f3\u00a0<mark><strong>una comparaci\u00f3n con Venezuela y record\u00f3 que, en enero de este a\u00f1o, hubo cr\u00edticas internacionales por la forma en que ocurri\u00f3 la ca\u00edda de Nicol\u00e1s Maduro, al atribuirse a una intervenci\u00f3n impulsada por Donald Trump.<\/strong><\/mark><\/p>\n<p>Loret sostuvo que, ante esas cr\u00edticas,\u00a0<mark><strong>algunas voces defendieron que deb\u00eda priorizarse la opini\u00f3n de los venezolanos sobre la forma en que se produjo el cambio.<\/strong><\/mark><\/p>\n<div class=\"div-pos-7\"><\/div>\n<p>Bajo esa misma l\u00f3gica, el periodista plante\u00f3 que la situaci\u00f3n de Sinaloa deb\u00eda analizarse desde la perspectiva de los propios sinaloenses. Se\u00f1al\u00f3 que, aunque hubiera sido preferible que la salida de\u00a0<strong>Rocha Moya<\/strong>\u00a0s<strong>e resolviera internamente, finalmente ocurri\u00f3 en otro contexto.<\/strong><\/p>\n<p>En su an\u00e1lisis, asegur\u00f3 que durante un a\u00f1o y medio la poblaci\u00f3n de Sinaloa vivi\u00f3 bajo condiciones marcadas por el miedo y la inseguridad, lo que, seg\u00fan expuso, impact\u00f3 la vida cotidiana de los habitantes.<\/p>\n<p>El texto sostiene que\u00a0<mark><strong>para muchos ciudadanos exist\u00edan motivos para celebrar la salida del mandatario, aunque tambi\u00e9n hab\u00eda razones para mantener cautela.<\/strong><\/mark><\/p>\n<h2>Investigaci\u00f3n de la FGR y permanencia del grupo pol\u00edtico<\/h2>\n<p>Loret destac\u00f3 que Rub\u00e9n Rocha Moya \u00fanicamente solicit\u00f3 una licencia temporal mientras enfrenta una investigaci\u00f3n por parte de la Fiscal\u00eda General de la Rep\u00fablica\u00a0<a href=\"https:\/\/www.informador.mx\/fiscalia-general-de-la-republica-(fgr)-t17305\" target=\"_blank\" rel=\"noopener\"><strong>(FGR)<\/strong><\/a>.<\/p>\n<p>Asimismo, se\u00f1al\u00f3 que la Presidenta Claudia Sheinbaum ha enviado se\u00f1ales que, desde su interpretaci\u00f3n, apuntan a una eventual exoneraci\u00f3n del gobernador.<\/p>\n<p>El periodista tambi\u00e9n indic\u00f3 que,\u00a0<mark><strong>tras la salida temporal de Rocha, qued\u00f3 al frente una figura perteneciente a su mismo grupo pol\u00edtico, por lo que, en su opini\u00f3n, las estructuras de poder permanecen intactas.<\/strong><\/mark><\/p>\n<p>De acuerdo con su an\u00e1lisis, este escenario ha moderado el entusiasmo inicial de algunos sectores en Sinaloa, dando paso a una percepci\u00f3n de frustraci\u00f3n ante la posibilidad de que no existan cambios de fondo.<\/p>\n<p>Finalmente, Loret sostuvo que, mientras se desarrolla el proceso de investigaci\u00f3n, el estado requiere perfiles con experiencia y capacidad para enfrentar una crisis que, de acuerdo con su planteamiento, contin\u00faa afectando a la poblaci\u00f3n sinaloense.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El periodista\u00a0Carlos Loret de Mola\u00a0compar\u00f3 la situaci\u00f3n pol\u00edtica y social del estado mexicano de\u00a0Sinaloa\u00a0con la crisis vivida en Venezuela, al analizar la salida temporal de Rub\u00e9n Rocha Moya de la gubernatura en medio del conflicto de seguridad que afecta al estado desde septiembre de 2024. En su planteamiento, sostuvo que, as\u00ed\u00a0como ocurri\u00f3 con la reacci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":255660,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12870,172],"tags":[12865,12874],"class_list":["post-255659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-nacional","tag-destacadas","tag-nacional"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2026\/05\/los_chapitos_ayudaron_a_la_eleccixn_de_rubxn_rocha_moya_version1777509949458.jpg_721285311.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/255659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=255659"}],"version-history":[{"count":1,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/255659\/revisions"}],"predecessor-version":[{"id":255661,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/255659\/revisions\/255661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/255660"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=255659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=255659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=255659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}