{"id":239819,"date":"2025-12-29T20:13:11","date_gmt":"2025-12-30T03:13:11","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/?p=239819"},"modified":"2025-12-29T20:20:12","modified_gmt":"2025-12-30T03:20:12","slug":"realiza-programa-hbus-100-mil-traslados-gratuitos-a-estudiantes-universitarios","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2025\/12\/29\/realiza-programa-hbus-100-mil-traslados-gratuitos-a-estudiantes-universitarios\/","title":{"rendered":"Realiza programa HBus 100 mil traslados gratuitos a estudiantes universitarios"},"content":{"rendered":"<p><b data-olk-copy-source=\"MessageBody\">Hermosillo, Sonora; 29 de diciembre, 2025.-<\/b>\u00a0El programa de electromovilidad HBus impulsado por el presidente municipal Antonio Astiazar\u00e1n Guti\u00e9rrez cerr\u00f3 su servicio en 2025 con 100 mil traslados realizados.<\/p>\n<p>De acuerdo a datos de la Agencia Municipal de Energ\u00eda y Cambio Clim\u00e1tico se inici\u00f3 el 17 de febrero y fue creciendo de manera gradual en relaci\u00f3n con los beneficiarios del programa hasta llegar a 2 mil 150 estudiantes beneficiarios en ruta.<\/p>\n<p>El n\u00famero de estudiantes actualmente atendidos se logr\u00f3 gracias a las facilidades que la mayor\u00eda de las universidades participantes otorgaron, as\u00ed como \u00a0de los mismos usuarios, proporcionando la informaci\u00f3n necesaria para mejorar las rutas y horarios que inicialmente se trazaron como resultado del estudio inicial de movilidad de los estudiantes.<\/p>\n<p>Se destaca la participaci\u00f3n de profesores de las diferentes instituciones educativas como la UNISON, UES, ITH, Escuela Normal del Estado, UTH, CEUNO y otras instituciones educativas de nivel superior que se fueron incorporando.<\/p>\n<p>El aumento en el n\u00famero de estudiantes universitarios beneficiados fue notorio a partir del segundo semestre de este a\u00f1o donde fue exponencial su inter\u00e9s incrementando la cantidad de viajes, rutas y mejorando \u00a0la oferta de horarios tanto de entrada como de salida.<\/p>\n<p>Debido al incremento en la cantidad de usuarios se pas\u00f3 a 58 viajes diarios y 8 horarios en 9 diferentes rutas, acompa\u00f1ado de proyectos que hoy son una realidad y que mejoran la experiencia positiva de los usuarios de H Bus, como la nueva web app que otorga mayor practicidad y funcionalidad que la anterior plataforma, o el nuevo sitio de parada de las unidades H Bus a la altura del asilo de ancianos por el Luis Encinas, que da mayor organizaci\u00f3n a las unidades, evitar posibles incidentes con la acumulaci\u00f3n de tr\u00e1fico en horas pico, y principalmente la seguridad de los usuarios.<\/p>\n<p>Las unidades est\u00e1n gobernadas para circular a una velocidad m\u00e1xima de 50 km\/hr, de acuerdo al reglamento de tr\u00e1nsito vigente y la nueva ley de transporte del Estado de Sonora.<\/p>\n<p>El programa H Bus continuar\u00e1 innovando el pr\u00f3ximo a\u00f1o para beneficio de los usuarios y de la comunidad en general.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hermosillo, Sonora; 29 de diciembre, 2025.-\u00a0El programa de electromovilidad HBus impulsado por el presidente municipal Antonio Astiazar\u00e1n Guti\u00e9rrez cerr\u00f3 su servicio en 2025 con 100 mil traslados realizados. De acuerdo a datos de la Agencia Municipal de Energ\u00eda y Cambio Clim\u00e1tico se inici\u00f3 el 17 de febrero y fue creciendo de manera gradual en relaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":239820,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12870,178,1],"tags":[12865,12869,12872],"class_list":["post-239819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-local","category-uncategorized","tag-destacadas","tag-local","tag-uncategorized"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/12\/Realiza-programa-HBus-100-mil-traslados-gratuitos-a-estudiantes-universitarios-4.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/239819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=239819"}],"version-history":[{"count":1,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/239819\/revisions"}],"predecessor-version":[{"id":239821,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/239819\/revisions\/239821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/239820"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=239819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=239819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=239819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}