{"id":218803,"date":"2025-05-19T14:00:45","date_gmt":"2025-05-19T21:00:45","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/?p=218803"},"modified":"2025-05-18T20:52:12","modified_gmt":"2025-05-19T03:52:12","slug":"el-papa-y-la-solidaridad-con-los-periodistas-encarcelados","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2025\/05\/19\/el-papa-y-la-solidaridad-con-los-periodistas-encarcelados\/","title":{"rendered":"El Papa y la solidaridad con los periodistas encarcelados"},"content":{"rendered":"<p>Ante los casi tres mil trabajadores de los medios de comunicaci\u00f3n a quienes recibi\u00f3 en el Aula Pablo VI el lunes 12 de mayo, el Papa Le\u00f3n XIV quiso recordar al mundo una verdad elemental pero dram\u00e1ticamente negada: la libertad de prensa es la primera v\u00edctima de toda guerra, la primera conquista que todo poder autoritario intenta sofocar. Porque detr\u00e1s de ella est\u00e1 la libertad de hablar, de pensar. Y en esa asfixia est\u00e1 la herida no s\u00f3lo de una categor\u00eda profesional, sino de la dignidad humana, de la justicia, de la posibilidad de elegir.<\/p>\n<p><strong>El a\u00f1o pasado fueron asesinados ciento veinticuatro periodistas<\/strong><br \/>\nLas cifras hablan de un problema que est\u00e1 lejos de ser aislado o estar en declive. El Committee to protect journalists (CPJ) informa que ciento veinticuatro periodistas fueron asesinados durante el 2024, la cifra m\u00e1s alta de los \u00faltimos treinta a\u00f1os, incluso desde el r\u00e9cord hist\u00f3rico del 2007 (ciento trece), noventa y cinco han desaparecido en circunstancias todav\u00eda oscuras y, hasta el 1\u00b0 de diciembre del 2024, trescientos sesena y uno est\u00e1n encarcelados, la segunda cifra m\u00e1s alta de la historia. Informe Sin Fronteras (Rsf) habla de quinientos cincuenta periodistas encarcelados, un aumento del 7% con respecto al 2023.<\/p>\n<p>Adem\u00e1s de subrayar el hecho de que al menos 24 periodistas fueron asesinados deliberadamente a causa de su trabajo, el CPJ a\u00f1ade que m\u00e1s de un tercio \u2013 cuarenta y tres \u2013 de todos los periodistas y trabajadores de los medios de comunicaci\u00f3n asesinados el a\u00f1o pasado eran freelance:<\/p>\n<blockquote><p>\u00abOtro nuevo y triste r\u00e9cord para los trabajadores de prensa aut\u00f3nomos, que a menudo se enfrentan a los mayores peligros porque tienen pocos recursos\u00bb y \u00abun aumento constante desde el 2020\u00bb, comenta el comit\u00e9 con sede en Nueva York.<\/p><\/blockquote>\n<p>En el 2024, la Unesco registr\u00f3 el mayor n\u00famero de asesinatos en zonas de guerra de la \u00faltima d\u00e9cada: el 60% de las v\u00edctimas eran trabajadores de los medios de comunicaci\u00f3n dedicados a informar de la verdad desde el frente. N\u00fameros que no son fr\u00edas estad\u00edsticas, sino carne viva: detr\u00e1s de cada cifra hay un rostro, una historia, una vida rota o suspendida.<\/p>\n<p><strong>Las \u00e1reas m\u00e1s afectadas<\/strong><br \/>\nLas zonas geogr\u00e1ficas m\u00e1s peligrosas en el 2024 fueron Oriente Medio, Norte de \u00c1frica, Asia, Am\u00e9rica Latina y \u00c1frica Subsahariana. En estos contextos, el periodismo es una misi\u00f3n. Es una vocaci\u00f3n estar all\u00ed donde no llega la voz de los d\u00e9biles, donde se oculta el sufrimiento.<\/p>\n<p>No necesitamos una comunicaci\u00f3n \u00abmuscular\u00bb, dijo el Papa, sino una comunicaci\u00f3n que escuche, que acoja, que cuente. Que ilumine las periferias de la historia. No es casualidad que el Papa Le\u00f3n XIV llamara ayer testigos a los periodistas.<\/p>\n<p>Y a ellos reconoci\u00f3 el \u00abvalor de quienes defienden la dignidad, la justicia y el derecho de los pueblos a estar informados, porque s\u00f3lo los pueblos informados pueden tomar decisiones libres. El sufrimiento de estos periodistas encarcelados interpela la conciencia de las naciones y de la comunidad internacional, llam\u00e1ndonos a todos a salvaguardar el bien precioso de la libertad de expresi\u00f3n y de prensa\u00bb.<\/p>\n<p><strong>Palabras que desarman<\/strong><br \/>\nLas palabras del Pont\u00edfice invitan a recordar c\u00f3mo en el mundo hay todav\u00eda muchos, demasiados periodistas que trabajan amenazados, viven en la c\u00e1rcel, desaparecen en silencio. A ellos el Papa les pide que no cedan al miedo. Y a todos el Papa les pide que no se acostumbren a su sufrimiento. Porque \u2013 como dec\u00eda Le\u00f3n XIV \u2013 \u00abdesarmar las palabras es el primer paso para desarmar la tierra\u00bb. Y quien dice la verdad es un desarmador de profesi\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante los casi tres mil trabajadores de los medios de comunicaci\u00f3n a quienes recibi\u00f3 en el Aula Pablo VI el lunes 12 de mayo, el Papa Le\u00f3n XIV quiso recordar al mundo una verdad elemental pero dram\u00e1ticamente negada: la libertad de prensa es la primera v\u00edctima de toda guerra, la primera conquista que todo poder [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":218804,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12870,182],"tags":[12865,12871],"class_list":["post-218803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-internacional","tag-destacadas","tag-internacional"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/05\/periodistas.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/218803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=218803"}],"version-history":[{"count":1,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/218803\/revisions"}],"predecessor-version":[{"id":218805,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/218803\/revisions\/218805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/218804"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=218803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=218803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=218803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}