{"id":204514,"date":"2017-07-12T10:44:54","date_gmt":"2017-07-12T10:44:54","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/07\/12\/gano-la-americana-2-carreras-a-una\/"},"modified":"2017-07-12T10:44:54","modified_gmt":"2017-07-12T10:44:54","slug":"gano-la-americana-2-carreras-a-una","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/07\/12\/gano-la-americana-2-carreras-a-una\/","title":{"rendered":"Gano la Americana 2 carreras a una"},"content":{"rendered":"<p>ESTADOS UNIDOS (12\/JUL\/2017).- Robinson Can&oacute;, el astro dominicano de Seattle que fue incluido como sustituto en el roster, abri&oacute; la parte alta del d&eacute;cimo inning con un jonr&oacute;n para darle a la Liga Americana la victoria ayer por la noche por 2-1 sobre la Nacional, el quinto triunfo seguido del joven circuito en el Juego de Estrellas.<\/p>\n<p>&nbsp;<\/p>\n<p>En cuenta de 1-1, el segunda base de los Marineros prendi&oacute; una curva de Wade Davis y deposit&oacute; la bola en el bullpen del jard&iacute;n derecho.<\/p>\n<p>&nbsp;<\/p>\n<p>S&oacute;lo la lesi&oacute;n de su compatriota Starlin Castro permiti&oacute; que Can&oacute;, de 34 a&ntilde;os, fuera seleccionado por octava vez a un Cl&aacute;sico de mitad de temporada, y acab&oacute; como el Jugador M&aacute;s Valioso de esta edici&oacute;n.<\/p>\n<p>&nbsp;<\/p>\n<p>En un juego en el que se promocion&oacute; un cambio generacional, con 24 peloteros debutantes y un total de 30 con 27 a&ntilde;os de edad o menos, las figuras m&aacute;s sobresalientes fueron los jugadores que ten&iacute;an m&aacute;s convocatorias. Fue el caso de Can&oacute; y del puertorrique&ntilde;o Yadier Molina, ambos con ocho participaciones.<\/p>\n<p>&nbsp;<\/p>\n<p>La victoria de la Americana provoc&oacute; un empate en los duelos contra la Nacional: 43-43 y dos empates.<\/p>\n<p>&nbsp;<\/p>\n<p>Por primera vez en 15 a&ntilde;os, el ganador del juego no determin&oacute; la ventaja de local para la pr&oacute;xima Serie Mundial, que se asignar&aacute; al equipo que tenga el mejor r&eacute;cord durante la temporada regular.<\/p>\n<p>&nbsp;<\/p>\n<p>Molina fue el gran protagonista por la Nacional, en particular en el sexto inning. Pero de su aportaci&oacute;n en esa entrada, s&oacute;lo quedar&aacute; grabado en el boxscore el jonr&oacute;n solitario que conect&oacute;.<\/p>\n<p>&nbsp;<\/p>\n<p>El c&aacute;tcher puertorrique&ntilde;o la desapareci&oacute; ante Ervin Santana de Minnesota para poner un empate transitorio 1-1.<\/p>\n<p>&nbsp;<\/p>\n<p>No fue lo &uacute;nico destacable del astro de los Cardenales en ese inning: hizo de receptor, toletero y fot&oacute;grafo.<\/p>\n<p>&nbsp;<\/p>\n<p>En la parte alta, Nelson Cruz fue a batear por la Americana y el dominicano cargaba su tel&eacute;fono en un bolsillo. El toletero de Seattle quer&iacute;a sacarse una foto en el plato con el umpire, y Molina se encarg&oacute; de captar la imagen.<\/p>\n<p>&nbsp;<\/p>\n<p>Molina, quien jug&oacute; con un protector del pecho que encandil&oacute; por ser dorado, se convirti&oacute; en el bateador de mayor edad &mdash;cumplir&aacute; 35 a&ntilde;os ma&ntilde;ana&mdash;que dispara un jonr&oacute;n en el Juego de Estrellas desde 2002. Barry Bonds ten&iacute;a 37 cuando peg&oacute; un cuadrangular en el Cl&aacute;sico escenificado en Milwaukee.<\/p>\n<p>&nbsp;<\/p>\n<p>La Americana peg&oacute; primero en el quinto, en el que Miguel San&oacute; deposit&oacute; un bombito que cay&oacute; en lo corto del jard&iacute;n derecho y en medio de tres jugadores de los Nacionales de Washington. El dominicano San&oacute; pesc&oacute; con la punta del bate un pitcheo de Alex Wood (Dodgers) y la bola cay&oacute; entre el jardinero Bryce Harper, el primera base Ryan Zimmerman y el segunda base Daniel Murphy, permitiendo la anotaci&oacute;n de Jonathan Schoop.<\/p>\n<p>&nbsp;<\/p>\n<p>Homenaje a leyendas latinoamericanas<\/p>\n<p>&nbsp;<\/p>\n<p>El de ayer por la noche fue el primer Juego de Estrellas en Miami y su inicio estuvo precedido por un homenaje a los peloteros latinoamericanos que han sido exaltados al Sal&oacute;n de la Fama. Pedro Mart&iacute;nez, Juan Marichal, Tony P&eacute;rez, Roberto Alomar y Orlando Cepeda estuvieron presentes en la ceremonia previa al partido, as&iacute; como la familia del fallecido Roberto Clemente. Tambi&eacute;n estuvo Iv&aacute;n Rodr&iacute;guez, quien ser&aacute; exaltado a fin de mes.<\/p>\n<p>&nbsp;<\/p>\n<p>El venezolano Luis Aparicio se ausent&oacute;. En un mensaje escrito en Twitter, Aparicio mencion&oacute; la crisis que se vive en su pa&iacute;s: &ldquo;Gracias @MLB por el homenaje en el #ASG2017 pero no puedo celebrar mientras los j&oacute;venes de mi pa&iacute;s mueren luchando por ideales de libertad&rdquo;.<\/p>\n<p>&nbsp;<\/p>\n<p>LOS MOMENTOS<\/p>\n<p>&nbsp;<\/p>\n<p>Para el recuerdo<\/p>\n<p>El veterano umpire de Grandes Ligas Joe West, presente ayer por la noche en el Marlins Park, dir&aacute; adi&oacute;s a los diamantes esta remporada poniendo fin a una larga trayectoria en la Gran Carpa. Durante el Juego de Estrellas el dominicano Nelson Cruz no dej&oacute; pasar la oportunidad y se tom&oacute; la foto del recuerdo con West. El encargado de inmortalizar la imagen fue el catcher Yadier Molina.<\/p>\n<p>&nbsp;<\/p>\n<p>Con causa<\/p>\n<p>Durante el Juego de Estrellas celebrado ayer por la noche en el Marlins Park, jugadores, &aacute;rbitros y aficionados se sumaron a una campa&ntilde;a contra el c&aacute;ncer, en un acto que fue m&aacute;s all&aacute; de lo deportivo. Durante una pausa en el partido, tanto en las tribunas como en en el diamante todos los asistentes al Cl&aacute;sico de media temporada portaron durante un minuto peque&ntilde;as pancartas en apoyo a esta causa.<\/p>\n<p>&nbsp;<\/p>\n<p>El m&aacute;s valioso<\/p>\n<p>En su octava participaci&oacute;n en un Juego de Estrellas de Grandes Ligas, el dominicano Robinson Can&oacute; fue designado como el Jugador M&aacute;s Valioso ayer en el Marlins Park. Can&oacute; fue convocado como sustituto al Cl&aacute;sico de media temporada ante la lesi&oacute;n de Starlin Castro, y respondi&oacute; con creces al conseguir el cuadrangular que le dio la victoria a la Liga Americana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gano la Americana 2 carreras a una<\/p>\n","protected":false},"author":1,"featured_media":204515,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188],"tags":[104],"class_list":["post-204514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-mlb"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2017\/07\/1499881494_robinson-cano.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/204514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=204514"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/204514\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/204515"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=204514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=204514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=204514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}