{"id":201823,"date":"2017-09-25T11:23:35","date_gmt":"2017-09-25T11:23:35","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/09\/25\/aportan-diputados-60-mdp-para-damnificados-susana-corella\/"},"modified":"2017-09-25T11:23:35","modified_gmt":"2017-09-25T11:23:35","slug":"aportan-diputados-60-mdp-para-damnificados-susana-corella","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/09\/25\/aportan-diputados-60-mdp-para-damnificados-susana-corella\/","title":{"rendered":"Aportan Diputados 60 mdp para damnificados: Susana Corella"},"content":{"rendered":"<p class=\"MsoNormal\"><span lang=\"ES-MX\">En apoyo a las personas afectadas por el terremoto del pasado martes en la Ciudad de M&eacute;xico, Morelos y Puebla, los diputados federales aportar&aacute;n 60 millones de pesos, inform&oacute; Susana Corella Platt.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">&ldquo;Hoy m&aacute;s que nunca los mexicanos debemos estar unidos, responder como uno s&oacute;lo para auxiliar a quienes m&aacute;s nos necesitan&rdquo;, manifest&oacute; la legisladora sonorense. <\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Susana Corella explic&oacute; que 50 millones de pesos se destinar&aacute;n al fondo de reconstrucci&oacute;n y los 10 restantes en equipo para apoyo al rescate de las personas atrapadas entre los escombros.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Subray&oacute; que las manifestaciones m&aacute;s sublimes de solidaridad popular <a name=\"_GoBack\"><\/a>se han vuelto a sentir: &ldquo;Es una solidaridad que nos hermana, que nos hace m&aacute;s fuertes como naci&oacute;n&rdquo;.<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span lang=\"ES-MX\">Solidaridad del PRI<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">La diputada dijo sentirse orgullosa de la postura asumida por el PRI, que ayer anunci&oacute; haber destinado el 25 por ciento de sus prerrogativas para los afectados por el sismo.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">El anuncio de nuestro l&iacute;der Enrique Ochoa, que significa donar 250 millones de pesos para los damnificados, demuestra que el partido responde con hechos y no con simulaciones, expres&oacute;.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">&ldquo;Como bien lo dice nuestro coordinador parlamentario C&eacute;sar Camacho, el pri&iacute;smo expresa su solidaridad sin oportunismos pol&iacute;ticos, en consonancia con su compromiso social&rdquo;, manifest&oacute;,<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Al mismo tiempo, Susana Corella abri&oacute; un centro de acopio de v&iacute;veres y medicamentos en su Oficina de Enlace en Guaymas, cabecera del Distrito 04 que representa.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">La diputada federal encabeza personalmente las tareas de recaudaci&oacute;n e, incluso, ha acudido a grupos empresariales y de la sociedad civil para invitarles a contribuir con esta noble causa.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">&ldquo;Cualquier cosa que aportemos nos hace m&aacute;s humanos. Hoy M&eacute;xico vuelve a demostrar que su fuerza reside en la unidad, en que somos una sola familia&rdquo;, apunt&oacute;.&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aportan Diputados 60 mdp para damnificados: Susana Corella<\/p>\n","protected":false},"author":1,"featured_media":201824,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[2994],"class_list":["post-201823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-susana-corella"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2017\/09\/1506363815_nota17959.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/201823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=201823"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/201823\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/201824"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=201823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=201823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=201823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}