{"id":200165,"date":"2017-10-27T14:08:31","date_gmt":"2017-10-27T14:08:31","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/10\/27\/se-define-fecha-para-realizacion-de-sorteo-para-servicio-militar-en-hermosillo\/"},"modified":"2017-10-27T14:08:31","modified_gmt":"2017-10-27T14:08:31","slug":"se-define-fecha-para-realizacion-de-sorteo-para-servicio-militar-en-hermosillo","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/10\/27\/se-define-fecha-para-realizacion-de-sorteo-para-servicio-militar-en-hermosillo\/","title":{"rendered":"Se define fecha para realizacion de sorteo para Servicio Militar en Hermosillo"},"content":{"rendered":"<p>Por Rafael Renteria<\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\"><span>Un total de mil 923 j&oacute;venes nacidos en 1999 y entre los cuales tambi&eacute;n van una cantidad importante de remisos, se inscribieron para prestar su Servicio Militar Nacional en Hermosillo y a su vez, van a formar parte de dicho sorteo el pr&oacute;ximo domingo 12 de noviembre, afirm&oacute; Omar Baz&aacute;n Feliz.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>El Director de la Junta de Servicios de Gobierno del Ayuntamiento de Hermosillo, mencion&oacute; que al cierre de esa convocatoria que fue de 3 mil espacios para el tr&aacute;mite de la Pre Cartilla, se inscribieron mil 923 j&oacute;venes conscriptos clase 1999 y de esa cantidad 640 son remisos.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span>&nbsp;&ldquo;El prop&oacute;sito es que esta vez se enteren los j&oacute;venes y que asistan todos para que sepan cual ser&aacute; su obligaci&oacute;n en el caso que tengan que presentar su servicio militar nacional o quedar exentos. Despu&eacute;s del sorteo los muchachos tendr&aacute;n que acudir a la junta local de reclutamiento para que ah&iacute; les pongan un sello que indiquen el resultado ya sea bola negra o blanca&rdquo;, especific&oacute;.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>La cita para el sorteo recalc&oacute;, ser&aacute; la plaza Alonso Vidal del domingo 12 de noviembre a las 8 de la ma&ntilde;ana y ah&iacute; estar&aacute; presente el Presidente Municipal Manuel Ignacio Acosta, El Secretario del Ayuntamiento Julio Cesar Ulloa Gir&oacute;n, el Comandante de la 4ta Zona militar, Norberto Cortes Rodr&iacute;guez y obviamente de todos los j&oacute;venes y remisos que se inscribieron con el fin que ah&iacute; puedan conocer de viva voz si prestaran o no su servicio militar nacional.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se define fecha para realizacion de sorteo para Servicio Militar en Hermosillo<\/p>\n","protected":false},"author":1,"featured_media":200166,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[3962],"class_list":["post-200165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-smn"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2017\/10\/1509138511_smn.JPG","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/200165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=200165"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/200165\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/200166"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=200165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=200165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=200165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}