{"id":199845,"date":"2017-11-04T11:46:01","date_gmt":"2017-11-04T11:46:01","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/11\/04\/sofa-castro-confirma-su-debut-en-hollywood\/"},"modified":"2017-11-04T11:46:01","modified_gmt":"2017-11-04T11:46:01","slug":"sofa-castro-confirma-su-debut-en-hollywood","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/11\/04\/sofa-castro-confirma-su-debut-en-hollywood\/","title":{"rendered":"Sof&Atilde;&shy;a Castro confirma su debut en Hollywood"},"content":{"rendered":"<p>La actriz mexicana Sof&iacute;a Castro asegur&oacute; que contin&uacute;a tocando las puertas de Hollywood sin descartar su regreso a M&eacute;xico, y que ser&aacute; en febrero pr&oacute;ximo cuando se estrene su primera pel&iacute;cula en ingl&eacute;s &#8220;Monster Party&#8221;, en la que comparte cr&eacute;dito con Lance Reddick.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;Aunque no se trata de un protag&oacute;nico, la hija de Ang&eacute;lica Rivera y Jos&eacute; Alberto &#8220;El G&uuml;ero&#8221; Castro se&ntilde;al&oacute; que es su entrada a la industria hollywoodense.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Estoy muy contenta y para m&iacute; es un logro muy grande&#8221;, expres&oacute; visiblemente emocionada.<\/p>\n<p>&nbsp;Respecto a las diferencias de filmar en Estados Unidos y M&eacute;xico, sostuvo que m&aacute;s all&aacute; del pa&iacute;s, cada director y cada producci&oacute;n tiene una manera de trabajar particularmente.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;En charla con los medios, la actriz de tan s&oacute;lo 20 a&ntilde;os de edad mencion&oacute; que si bien se encuentra estudiando en Los &Aacute;ngeles y haciendo &#8220;castings&#8221;, no descarta la posibilidad de trabajar en M&eacute;xico como antes lo ha hecho, incluso con su padre.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;Castro viaj&oacute; a M&eacute;xico para asistir a la gala que organizaron Eva Longoria y Maluma para continuar recaudando fondos a beneficio de los damnificados por los sismos de septiembre pasado y aprovech&oacute; la oportunidad para instar a continuar apoyando a quienes m&aacute;s lo necesitan.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;&#8220;No es s&oacute;lo un mes sino demasiados meses para que se pueda reconstruir. M&eacute;xico demostr&oacute; que es muy fuerte y que nunca nos dejamos vencer bajo ninguna adversidad&#8221;, comparti&oacute; la actriz.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;Durante la contingencia, Sof&iacute;a Castro viaj&oacute; desde Los &Aacute;ngeles a la Ciudad de M&eacute;xico para sumarse a las brigadas en los centros de acopio y asegur&oacute; que no parar&aacute; de ir y venir hasta que &#8220;M&eacute;xico est&eacute; de pie&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sof&Atilde;&shy;a Castro confirma su debut en Hollywood<\/p>\n","protected":false},"author":1,"featured_media":199846,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[219],"tags":[12722],"class_list":["post-199845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos","tag-sofa-castro"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2017\/11\/1509821161_sofia.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/199845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=199845"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/199845\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/199846"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=199845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=199845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=199845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}