{"id":199562,"date":"2017-11-10T08:05:21","date_gmt":"2017-11-10T08:05:21","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/11\/10\/recibiran-alimentacion-sana-variada-y-suficiente-familias-vulnerables-de-cajeme\/"},"modified":"2017-11-10T08:05:21","modified_gmt":"2017-11-10T08:05:21","slug":"recibiran-alimentacion-sana-variada-y-suficiente-familias-vulnerables-de-cajeme","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/11\/10\/recibiran-alimentacion-sana-variada-y-suficiente-familias-vulnerables-de-cajeme\/","title":{"rendered":"Recibiran alimentacion sana, variada y suficiente familias vulnerables de Cajeme"},"content":{"rendered":"<p>Para abatir las carencias alimentarias en las comunidades rurales y sectores urbanos con familias vulnerables, el Ayuntamiento de Cajeme y la Secretar&iacute;a de Desarrollo Social (Sedesol) pusieron en marcha dos comedores comunitarios en la Comisar&iacute;a de C&oacute;corit y en la colonia Cuauht&eacute;moc C&aacute;rdenas.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante la inauguraci&oacute;n del comedor &ldquo;Pueblo M&aacute;gico&rdquo;, instalado en el barrio del Conty, la Secretaria de Desarrollo Social Municipal, Denisse Navarro Leyva manifest&oacute; que estos centros que benefician a cientos de ni&ntilde;os, mujeres embarazadas, personas con alguna discapacidad y adultos mayores, son posibles gracias a la gesti&oacute;n del Alcalde Faustino F&eacute;lix Ch&aacute;vez quien uni&oacute; esfuerzos con los gobiernos estatal y Federal.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Gracias al trabajo coordinado que hay entre los &oacute;rdenes de Gobierno, federal y municipal, que entre todos nos pusimos las pilas para que aqu&iacute; en el Conty tambi&eacute;n tuvieran su comedor comunitario, con lo que abate el rezago alimenticio y que nadie en el municipio se nos quede sin una buena alimentaci&oacute;n&rdquo;.<\/p>\n<p>&nbsp;<\/p>\n<p>Mientras que el Delegado de la Sedesol en Sonora, Jes&uacute;s Rodr&iacute;guez Qui&ntilde;onez reconoci&oacute; el apoyo del Presidente Municipal para que todos los programas de la Secretar&iacute;a aterricen en Cajeme.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Pedirte Denisse que seas el conducto amable para hacerle llegarla se&ntilde;or Presidente Municipal nuestro agradecimiento, nuestro reconocimiento a todo el apoyo que ha tenido Faustino, como Alcalde, para toda la actividad que ha venido desarrollando la Sedesol en Sonora y, particularmente, en Cajeme&rdquo;, manifest&oacute; Rodr&iacute;guez Qui&ntilde;onez.<\/p>\n<p>&nbsp;<\/p>\n<p>Adem&aacute;s, dijo, que las madres de familia que de manera voluntaria se desempe&ntilde;an como cocineras en los comedores comunitarios, ser&aacute;n inscritas en los beneficios que otorga el programa Federal Prospera.<\/p>\n<p>&nbsp;<\/p>\n<p>En estos eventos tambi&eacute;n estuvo presente el Secretario del Ayuntamiento, Luis Armando Alcal&aacute; Alcaraz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recibiran alimentacion sana, variada y suficiente familias vulnerables de Cajeme<\/p>\n","protected":false},"author":1,"featured_media":199563,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[177],"class_list":["post-199562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-cajeme"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2017\/11\/1510326321_familiascajeme.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/199562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=199562"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/199562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/199563"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=199562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=199562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=199562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}