{"id":199159,"date":"2017-11-22T08:39:29","date_gmt":"2017-11-22T08:39:29","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/11\/22\/frente-ciudadano-plantea-reordenar-seis-mil-500-programas-sociales\/"},"modified":"2017-11-22T08:39:29","modified_gmt":"2017-11-22T08:39:29","slug":"frente-ciudadano-plantea-reordenar-seis-mil-500-programas-sociales","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/11\/22\/frente-ciudadano-plantea-reordenar-seis-mil-500-programas-sociales\/","title":{"rendered":"Frente Ciudadano plantea reordenar seis mil 500 programas sociales"},"content":{"rendered":"<p>Para materializar el planteamiento de financiar una renta b&aacute;sica universal para todos los mexicanos, propuesta por el Frente Ciudadano por M&eacute;xico (PAN, PRD y Movimiento Ciudadano), el l&iacute;der panista Ricardo Anaya ahond&oacute; en la estrategia para conseguir la meta al sugerir que el primer reto ser&aacute; reordenar la pol&iacute;tica social e hizo alusi&oacute;n a que &ldquo;existen m&aacute;s de 6 mil 500 programas, muchos duplicados y con corrupci&oacute;n&rdquo;.<\/p>\n<p>&nbsp;<\/p>\n<p>El lunes, el Frente present&oacute; el eje toral de su plataforma, que tiene como punta de lanza otorgar un ingreso universal a partir de la reorientaci&oacute;n de la pol&iacute;tica social, austeridad y combate a la corrupci&oacute;n. Ayer, a trav&eacute;s de Twitter, el l&iacute;der albiazul abund&oacute; en tono futurista sobre ese proyecto: &ldquo;Debe ser una de las pol&iacute;ticas para enfrentar los retos de la automatizaci&oacute;n y la inteligencia artificial. En muchas partes del mundo comienzan a caminar en esa direcci&oacute;n&rdquo;.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;La #RentaB&aacute;sicaUniversal es una medida de preparaci&oacute;n para el futuro, en lugar de pensar en medidas proteccionistas para regresar a un pasado que no volver&aacute; a ser&rdquo;, agreg&oacute; Anaya en la red social sobre la apuesta del proyecto que el Frente present&oacute; en la sede del Instituto Nacional Electoral (INE), y a adonde acudieron tambi&eacute;n los dirigentes del PRD, Alejandra Barrales, y Movimiento Ciudadano (MC), Dante Delgado.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Sentencia al PRI<\/p>\n<p>&nbsp;<\/p>\n<p>En la presentaci&oacute;n, Anaya presumi&oacute; que el Frente avanza y agreg&oacute; que la &ldquo;revoluci&oacute;n del siglo XXI tiene que ser la de la igualdad y la del impulso al emprendimiento&rdquo;. Dijo confiar en que en 2018 el PAN, PRD y MC ganar&aacute; la Presidencia y sentenci&oacute; en un tuit a sus adversarios pol&iacute;ticos &ldquo;En el #FrenteCiudadano nos vamos a poner de acuerdo en un m&eacute;todo democr&aacute;tico, pero blindado contra la intervenci&oacute;n del PRI y del gobierno&rdquo;.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Contra el &ldquo;dedazo&rdquo;<\/p>\n<p>&nbsp;<\/p>\n<p>El coordinador del PRD en el Senado de la Rep&uacute;blica, Luis S&aacute;nchez Jim&eacute;nez, se sum&oacute; a la demanda del jefe de Gobierno de la Ciudad de M&eacute;xico, Miguel &Aacute;ngel Mancera, para que el candidato presidencial del Frente Ciudadano por M&eacute;xico no sea elegido por &ldquo;dedazo&rdquo; o imposici&oacute;n. Dijo que el m&eacute;todo para elegir al aspirante presidencial del Frente deber&aacute; ser transparente y democr&aacute;tico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frente Ciudadano plantea reordenar seis mil 500 programas sociales<\/p>\n","protected":false},"author":1,"featured_media":199160,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[12693],"class_list":["post-199159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-frente-ciudadano"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2017\/11\/1511365169_Frente-Ciudadano-por-Mexico-702x468.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/199159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=199159"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/199159\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/199160"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=199159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=199159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=199159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}