{"id":198812,"date":"2017-11-30T14:03:33","date_gmt":"2017-11-30T14:03:33","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/11\/30\/adquiere-municipio-terrenos-para-regularizarlos\/"},"modified":"2017-11-30T14:03:33","modified_gmt":"2017-11-30T14:03:33","slug":"adquiere-municipio-terrenos-para-regularizarlos","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/11\/30\/adquiere-municipio-terrenos-para-regularizarlos\/","title":{"rendered":"ADQUIERE MUNICIPIO TERRENOS PARA REGULARIZARLOS"},"content":{"rendered":"<p>Por Rafael Renteria<\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\"><span>Se aprueba en sesi&oacute;n de cabildo adquirir varios predios ubicados al oriente de Hermosillo y con ello resolver temas de vivienda de cientos de familias, asever&oacute; Angelina Mu&ntilde;oz Fern&aacute;ndez.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>La Sindica Municipal mencion&oacute;, que fueron 4 los predios que el Ayuntamiento adquiri&oacute; para resolver el tema de asentamientos de alrededor de 300 familias en el Tazajal y en la Nueva Victoria, para posteriormente entregarles sus t&iacute;tulos de propiedad siempre y cuando cumplan con las especificaciones que la autoridad municipal les indicara.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span>&nbsp;&ldquo;En el caso del Tazajal son predios que andan en un promedio de los mil a los dos mil metros cuadrados cada uno, la gente se acento as&iacute; y en el acuerdo quedo que la venta quedar&aacute; a valor catastral ser&aacute; de 49 pesos por metro cuadrado y en la Nueva Victoria los predios van desde los 200 a los 500 metros cuadrados y el valor catastral ser&aacute; de 51 pesos por metro cuadrado&rdquo;, especific&oacute;.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>La Sindica Municipal detall&oacute;, que en el Tazajal ser&aacute;n 100 familias las cuales podr&aacute;n acceder a diversos esquemas para adquirir sus t&iacute;tulos de propiedad y en el caso de la Nueva Victoria son 200 en promedio.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Por &uacute;ltimo mencion&oacute; que, tambi&eacute;n se aprob&oacute; una ejecutoria para indemnizar a un grupo de ciudadanos que resultaron afectados en sus predios, debido a que las autoridades municipales y estatales construir&aacute;n nuevas v&iacute;as de comunicaci&oacute;n, espec&iacute;ficamente de una vialidad que ser&aacute; la prolongaci&oacute;n del Bulevar Serna, hasta el Quintero Arce y concluyendo hasta las inmediaciones del Estadio Sonora.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ADQUIERE MUNICIPIO TERRENOS PARA REGULARIZARLOS<\/p>\n","protected":false},"author":1,"featured_media":198813,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[283],"class_list":["post-198812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-ayuntamiento"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2017\/11\/1512075813_ANGELINA-MUNOZ-FERNANDEZ-SINDICO-MUNICIPAL.2-300x342.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/198812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=198812"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/198812\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/198813"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=198812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=198812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=198812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}