{"id":198378,"date":"2017-12-12T08:57:16","date_gmt":"2017-12-12T08:57:16","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/12\/12\/entrega-gobernadora-apoyos-a-personas-con-discapacidad\/"},"modified":"2017-12-12T08:57:16","modified_gmt":"2017-12-12T08:57:16","slug":"entrega-gobernadora-apoyos-a-personas-con-discapacidad","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/12\/12\/entrega-gobernadora-apoyos-a-personas-con-discapacidad\/","title":{"rendered":"Entrega Gobernadora apoyos a personas con discapacidad"},"content":{"rendered":"<p>Para brindar herramientas necesarias y elevar la calidad de vida de personas discapacitadas, la Gobernadora Claudia Pavlovich Arellano entreg&oacute; becas, aparatos auditivos y proyectos productivos.<\/p>\n<p>&nbsp;<\/p>\n<p>Al continuar las acciones enmarcadas en la celebraci&oacute;n del D&iacute;a Internacional de la Discapacidad, ante decenas de familias que recibieron los m&aacute;s de 500 apoyos, la Gobernadora Pavlovich resalt&oacute; que el trabajo de su administraci&oacute;n es crear programas y acciones para que los sonorenses salgan adelante a pesar de las adversidades que tienen enfrente.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Me siento muy contenta de festejar este D&iacute;a Internacional de la Discapacidad, que se celebr&oacute; el 3 de diciembre, trabajando, entregando apoyos, herramientas para poder salir adelante, herramientas en lo deportivo, de trabajo, para poder seguir ech&aacute;ndole ganas a la vida&rdquo;, enfatiz&oacute;.<\/p>\n<p>&nbsp;<\/p>\n<p>Un total de 513 becas de discapacidad (274 de atenci&oacute;n temprana, 21 de impulso deportivo, 186 educativas y 32 especiales) entreg&oacute; la Gobernadora Pavlovich, adem&aacute;s de 30 aparatos auxiliares auditivos.<\/p>\n<p>&nbsp;<\/p>\n<p>Tambi&eacute;n 13 familias podr&aacute;n otorgar m&aacute;s oportunidades a sus ni&ntilde;os con discapacidad al recibir proyectos productivos para mejorar sus ingresos, como son carretas de hot dogs, tortiller&iacute;a, abarrotes, panader&iacute;a, implementos para venta de tamales y pasteles, taller de costura, venta de escobas y triciclo.<\/p>\n<p>&nbsp;<\/p>\n<p>Karina Z&aacute;rate F&eacute;lix, Directora General de DIF Sonora, destac&oacute; que la instrucci&oacute;n de la Gobernadora Pavlovich siempre ha sido conmemorar una fecha importante trabajando y apoyando a los sonorenses que lo necesitan, y en el D&iacute;a Internacional de la Discapacidad, no fue la excepci&oacute;n.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;La forma (que se conmemoran) en la que la Gobernadora siempre lo ha dicho, con amor y cari&ntilde;o, y la respuesta que podemos tener como Gobierno es cumpliendo con nuestra responsabilidad y poder apoyarlos a que salgan adelante todos los d&iacute;as&rdquo;, abund&oacute;.<\/p>\n<p>&nbsp;<\/p>\n<p>Presentes: Los secretarios de Salud y de Desarrollo Social, Gilberto Ungson Beltr&aacute;n, y Rogelio D&iacute;az Brown Ramsburg; la Presidenta de DIF Sonora, Margarita Ibarra de Torres; el Director de la Comisi&oacute;n del Deporte del Estado de Sonora (CODESON), Genaro Enr&iacute;quez Rasc&oacute;n.<\/p>\n<p>&nbsp;<\/p>\n<p>Adem&aacute;s, el Director General de Desarrollo Social del Ayuntamiento de Hermosillo, Carlos Rodr&iacute;guez Freaner y los beneficiados Juan Jos&eacute; G&oacute;mez Cruz, Karla Jaqueline Le&oacute;n Carranza, Leticia Carranza Silva, Ana Sof&iacute;a Castillo L&oacute;pez y Armando Espinoza Mart&iacute;nez.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrega Gobernadora apoyos a personas con discapacidad<\/p>\n","protected":false},"author":1,"featured_media":198379,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[237],"class_list":["post-198378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-cpa"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2017\/12\/1513094236_cpa-apoyo-cs-500x384.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/198378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=198378"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/198378\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/198379"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=198378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=198378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=198378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}