{"id":198190,"date":"2017-12-18T10:32:55","date_gmt":"2017-12-18T10:32:55","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/12\/18\/lakers-retirara-camisetas-de-kobe-bryant\/"},"modified":"2017-12-18T10:32:55","modified_gmt":"2017-12-18T10:32:55","slug":"lakers-retirara-camisetas-de-kobe-bryant","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/12\/18\/lakers-retirara-camisetas-de-kobe-bryant\/","title":{"rendered":"Lakers retirara camisetas de Kobe Bryant"},"content":{"rendered":"<p>Los Lakers de Los &Aacute;ngeles retirar&aacute;n esta noche las camisetas del astro Kobe Bryant, y es una despedida que incluso sus rivales en turno, los campeones vigentes de la NBA, Warriors de Golden State, no quieren perderse.<\/p>\n<p>&nbsp;<\/p>\n<p>El entrenador de los Warriors, Steve Kerr, dijo que sus jugadores estar&iacute;an en la banca, no en sus vestidores, para las festividades del medio tiempo en el Staples Center.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Es una experiencia ver c&oacute;mo se retira la camiseta de uno de los mejores jugadores en la historia y resulta que vamos a estar all&iacute;&rdquo;, dijo Kerr.<\/p>\n<p>&nbsp;<\/p>\n<p>El entrenador de los Warriors dijo que su plan depend&iacute;a de la aprobaci&oacute;n de los Lakers, y la presidenta del equipo de Los &Aacute;ngejes, Jeanie Buss, respondi&oacute; r&aacute;pidamente.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;&iexcl;Por supuesto que est&aacute;n invitados! Esper&aacute;bamos que quisieran presentar sus respetos a uno de los mejores jugadores de la historia de la NBA&rdquo;, escribi&oacute; Buss.<\/p>\n<p>&nbsp;<\/p>\n<p>Los Lakers retirar&aacute;n los dos n&uacute;meros que Bryant us&oacute; mientras jug&oacute; en el club, el 8 y el 24, en su carrera de dos d&eacute;cadas con los Lakers.<\/p>\n<p>&nbsp;<\/p>\n<p>Cinco veces campe&oacute;n de la NBA, Bryant &nbsp;se convertir&aacute; en el d&eacute;cimo jugador de los Lakers al que se le retirar&aacute; el n&uacute;mero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lakers retirara camisetas de Kobe Bryant<\/p>\n","protected":false},"author":1,"featured_media":198191,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188],"tags":[958],"class_list":["post-198190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-kobe-bryant"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2017\/12\/1513618376_kobe-bryant-no-8-no-24_vresize_1200_675_high_9-1024x576.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/198190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=198190"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/198190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/198191"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=198190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=198190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=198190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}