{"id":196794,"date":"2018-02-06T09:51:14","date_gmt":"2018-02-06T09:51:14","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2018\/02\/06\/tendra-nueva-techumbre-el-patio-central-de-la-escuela-primaria-1o-de-mayo-ogp\/"},"modified":"2018-02-06T09:51:14","modified_gmt":"2018-02-06T09:51:14","slug":"tendra-nueva-techumbre-el-patio-central-de-la-escuela-primaria-1o-de-mayo-ogp","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2018\/02\/06\/tendra-nueva-techumbre-el-patio-central-de-la-escuela-primaria-1o-de-mayo-ogp\/","title":{"rendered":"Tendra nueva techumbre el patio central de la escuela primaria 1o de Mayo: OGP"},"content":{"rendered":"<p>CIUDAD OBREG&Oacute;N.- Al lado de la sociedad de padres de familia, autoridades educativas, maestros y alumnos de la Escuela Primaria &ldquo;Primero de Mayo&rdquo;, Omar Guill&eacute;n particip&oacute; en el inicio de los trabajos de construcci&oacute;n de la techumbre del patio central de este plantel, obra en la que habr&aacute;n de invertirse recursos por el orden de los 500 mil pesos y que estar&aacute; concluida en un lapso aproximado de 6 semanas.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Interesados siempre en buscar alternativas que mejoren la infraestructura de los diversos planteles educativos del Municipio, sobre todo de nivel primaria y secundaria, nos dimos a la tarea de plantear la necesidad de esta escuela a la Gobernadora Claudia Pavlovich, quien siempre se ha mostrado sensible y con la firme voluntad de sumar en torno al tema educativo, apoyando con obras como &eacute;sta que hoy inicia aqu&iacute; con el respaldo del Cecop (Consejo Estatal para Concertaci&oacute;n de la Obra P&uacute;blica).<\/p>\n<p>&nbsp;<\/p>\n<p>Esta techumbre es para permitir que los ni&ntilde;os y las ni&ntilde;as estudien y realicen sus actividades c&iacute;vicas, recreativas, deportivas y culturales en mejores condiciones, m&aacute;s seguras, y esto es gracias a la respuesta de la Gobernadora y a la b&uacute;squeda de soluciones que -junto a los padres y maestros- nos hemos propuesto impulsar en favor de las nuevas generaciones que hoy se preparan desde las aulas para ser personas de bien, futuros ciudadanos trabajadores y productivos&rdquo;, explic&oacute; el legislador local.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tendra nueva techumbre el patio central de la escuela primaria Primero de Mayo: Omar Guillen<\/p>\n","protected":false},"author":1,"featured_media":196795,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[3965],"class_list":["post-196794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-omar-guillen"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2018\/02\/1517935874_descarga.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/196794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=196794"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/196794\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/196795"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=196794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=196794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=196794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}