{"id":195434,"date":"2018-03-15T09:02:57","date_gmt":"2018-03-15T09:02:57","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2018\/03\/15\/conviccion-de-equipo-es-clave-para-mantener-unidad\/"},"modified":"2018-03-15T09:02:57","modified_gmt":"2018-03-15T09:02:57","slug":"conviccion-de-equipo-es-clave-para-mantener-unidad","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2018\/03\/15\/conviccion-de-equipo-es-clave-para-mantener-unidad\/","title":{"rendered":"Conviccion de equipo es clave para mantener unidad"},"content":{"rendered":"<p>Moctezuma, Sonora, a 15 de marzo de 2018.- En uno m&aacute;s de los acercamientos que Sylvana Beltrones S&aacute;nchez y Manuel Ignacio &ldquo;Maloro&rdquo; Acosta Guti&eacute;rrez vienen sosteniendo con la militancia priista de los municipios del estado, se reunieron en Moctezuma, con la participaci&oacute;n de Bavispe, Nacozari, Cumpas, Hu&aacute;sabas, Divisaderos, Tepache, Granados, Bacerac, Huachinera, N&aacute;cori Chico y Bacad&eacute;huachi.<\/p>\n<p>&nbsp;<\/p>\n<p>El encuentro regional de car&aacute;cter interno se dio en t&eacute;rminos de entendimiento y compromiso con las estructuras y cuadros de la regi&oacute;n serrana de Sonora, donde se expusieron los retos y se analizaron a profundidad las necesidades para enfrentar con &eacute;xito cada encomienda.<\/p>\n<p>&nbsp;<\/p>\n<p>Sylvana Beltrones y Maloro Acosta coincidieron en que, mediante los trabajos llevados a cabo, se fortalecer&aacute; la atenci&oacute;n a la estructura territorial para alcanzar acciones s&oacute;lidas en favor del equipo<\/p>\n<p>&nbsp;<\/p>\n<p>Beltrones S&aacute;nchez expuso que a trav&eacute;s de la colaboraci&oacute;n en conjunto de quienes conocen las necesidades de la zona noreste del estado podr&aacute;n alcanzar con m&aacute;s facilidad las metas trazadas, agregando que la competencia obliga a construir la unidad siendo incluyentes. En su exposici&oacute;n enfatiz&oacute; a los participantes que, para efectos de un mejor entorno a las comunidades, la palabra &ldquo;Nosotros&rdquo; significa Sonora, sin exclusiones.<\/p>\n<p>&nbsp;<\/p>\n<p>En su oportunidad, Maloro Acosta dijo sentirse en familia y puntualiz&oacute; que se debe llevar una sola estrategia, una sola convicci&oacute;n y un solo prop&oacute;sito para mandar el mejor mensaje de unidad, abundando que se debe tener muy claro que lo que vive en cada municipio de la sierra baja, de la sierra alta y de cualquier zona del estado es punto de identificaci&oacute;n para los sonorenses.<\/p>\n<p>&nbsp;<\/p>\n<p>Los dos aspirantes reiteraron que la capacidad de permanecer como un gran equipo se debe al apoyo y principios que siempre han mostrado sus integrantes, as&iacute; como la visi&oacute;n para mantener el rumbo. Sylvana y Maloro hicieron un reconocimiento a los participantes de la reuni&oacute;n, exhortando a mantener el di&aacute;logo constante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conviccion de equipo es clave para mantener unidad<\/p>\n","protected":false},"author":1,"featured_media":195435,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[1894],"class_list":["post-195434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-sylvana-beltrones"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2018\/03\/1521129777_sylvana.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/195434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=195434"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/195434\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/195435"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=195434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=195434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=195434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}