{"id":194523,"date":"2018-04-10T10:51:59","date_gmt":"2018-04-10T10:51:59","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2018\/04\/10\/designan-al-doctor-juan-poom-medina-como-rector-de-el-colson\/"},"modified":"2018-04-10T10:51:59","modified_gmt":"2018-04-10T10:51:59","slug":"designan-al-doctor-juan-poom-medina-como-rector-de-el-colson","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2018\/04\/10\/designan-al-doctor-juan-poom-medina-como-rector-de-el-colson\/","title":{"rendered":"Designan al doctor Juan Poom Medina como rector de EL COLSON"},"content":{"rendered":"<p class=\"x_MsoNormal\" style=\"margin: 0cm 0cm 10pt;padding: 0px;border: 0px;font-size: 11pt;font-family: Calibri, sans-serif;vertical-align: baseline;text-align: justify;color: #212121\">De acuerdo con los estatutos de la Ley Org&aacute;nica y el Reglamento General de El Colegio de Sonora, se anunci&oacute; este 9 de abril de 2018 a trav&eacute;s del presidente del Comit&eacute; de Auscultaci&oacute;n de la Junta de Gobierno de esta instituci&oacute;n, la designaci&oacute;n del doctor Juan Poom Medina como nuevo rector para el periodo 2018-2023.<\/p>\n<p class=\"x_MsoNormal\" style=\"margin: 0cm 0cm 10pt;padding: 0px;border: 0px;font-size: 11pt;font-family: Calibri, sans-serif;vertical-align: baseline;text-align: justify;color: #212121\">Luego cumplir con los requisitos del proceso de elecci&oacute;n del nuevo titular de la instituci&oacute;n, el doctor Luis Antonio J&aacute;uregui Fr&iacute;as inform&oacute; a la comunidad acad&eacute;mica y administrativa que Poom Medina cumpli&oacute; con la documentaci&oacute;n, el perfil y la trayectoria requerida para ocupar este puesto.<\/p>\n<p class=\"x_MsoNormal\" style=\"margin: 0cm 0cm 10pt;padding: 0px;border: 0px;font-size: 11pt;font-family: Calibri, sans-serif;vertical-align: baseline;text-align: justify;color: #212121\">&ldquo;El d&iacute;a de hoy a las 10 de la ma&ntilde;ana se reuni&oacute; y escuch&oacute; nuestro informe y despu&eacute;s de haber presentado los resultados del proceso de auscultaci&oacute;n de la semana pasada, despu&eacute;s de&nbsp; deliberar ampliamente, la Junta de Gobierno acord&oacute; designar al doctor Juan Poom Medina como rector de El Colegio de Sonora a partir del 23 de abril de 2018&rdquo;, dijo.<\/p>\n<p class=\"x_MsoNormal\" style=\"margin: 0cm 0cm 10pt;padding: 0px;border: 0px;font-size: 11pt;font-family: Calibri, sans-serif;vertical-align: baseline;text-align: justify;color: #212121\">La propuesta de trabajo&nbsp;presentada por&nbsp;el doctor Poom Medina consiste en transitar hacia un Colegio con presencia m&aacute;s all&aacute; de Sonora y el Noroeste de M&eacute;xico; concluir temas y dar seguimiento a los asuntos internos que se encuentran en proceso para buscar armon&iacute;a entre el desarrollo de la vida intelectual interna y los procesos administrativos; entre los distintos Centros de Estudio (y programa); entre las distintas generaciones de profesores\/as que conforman la planta acad&eacute;mica, entre El Colegio y la comunidad externa.<\/p>\n<p class=\"x_MsoNormal\" style=\"margin: 0cm 0cm 10pt;padding: 0px;border: 0px;font-size: 11pt;font-family: Calibri, sans-serif;vertical-align: baseline;text-align: justify;color: #212121\">Agrega que esto s&oacute;lo ser&aacute; posible de concretar conjuntando una Rector&iacute;a creativa, din&aacute;mica, abierta, comunicativa, organizada, consultiva, conciliadora, integradora, transparente, cuya base de trabajo debe utilizar la experiencia acumulada, en distintas etapas, de toda la comunidad de la instituci&oacute;n.<\/p>\n<p class=\"x_MsoNormal\" style=\"margin: 0cm 0cm 10pt;padding: 0px;border: 0px;font-size: 11pt;font-family: Calibri, sans-serif;vertical-align: baseline;text-align: justify;color: #212121\">&ldquo;Tenemos mucho trabajo como comunidad, soy de la idea de que los resultados que est&aacute;n presentados tienen que ver con un trabajo en equipo que es lo que vamos a hacer, tenemos que seguir dialogando; tengan la plena certeza y seguridad de que con el equipo que m&aacute;s adelante me va a acompa&ntilde;ar, le vamos a rendir buenas cuentas a la Junta de Gobierno&rdquo;, expres&oacute; Poom Medina.<\/p>\n<p class=\"x_MsoNormalCxSpMiddle\">Juan Poom Medina (1970, Empalme, Sonora) es doctor en Ciencias Sociales con Especialidad en Ciencia Pol&iacute;tica. Facultad Latinoamericana de Ciencias Sociales (FLACSO), Ciudad de M&eacute;xico. Es autor de diversos especializados en temas electorales y de gesti&oacute;n p&uacute;blica que se enfocan al Estado de Sonora. Desde 1999, es profesor-investigador en el Programa de Estudios Pol&iacute;ticos y de Gesti&oacute;n P&uacute;blica en El Colegio de Sonora. Miembro del Sistema Nacional de Investigadores, nivel I.<\/p>\n<p class=\"x_MsoNormalCxSpMiddle\">&nbsp;<\/p>\n<p class=\"x_MsoNormalCxSpMiddle\">Fue miembro del Comit&eacute; Ciudadano de Seguridad P&uacute;blica del Estado de Sonora. En el a&ntilde;o 2006, obtuvo el Premio Nacional de Administraci&oacute;n P&uacute;blica que otorga el Instituto Nacional de Administraci&oacute;n P&uacute;blica (INAP) a trav&eacute;s de la Presidencia de la Rep&uacute;blica. Algunas de sus publicaciones son: Poom Medina, Juan y Rodr&iacute;guez Obreg&oacute;n, Jos&eacute; Arturo (2010) &ldquo;Comportamiento electoral y calidad de la democracia&rdquo;, en Russo Foresto, Juan Jos&eacute; Calidad democr&aacute;tica, formaci&oacute;n ciudadana y comportamiento electoral. M&eacute;xico: IFE-Conacyt. Poom Medina, Juan y Rodr&iacute;guez Obreg&oacute;n, Jos&eacute; Arturo (2011) &ldquo;Sonora: los saldos electorales del 5 de julio y los retos democr&aacute;ticos, en Larrosa Manuel Haro y Javier Santiago, Elecciones y partidos pol&iacute;ticos en M&eacute;xico, 2009. M&eacute;xico: UAM-Iztapalapa.<\/p>\n<p class=\"x_MsoNormalCxSpMiddle\">&nbsp;<\/p>\n<p class=\"x_MsoNormal\" style=\"margin: 0cm 0cm 10pt;padding: 0px;border: 0px;font-size: 11pt;font-family: Calibri, sans-serif;vertical-align: baseline;text-align: justify;color: #212121\">En El Colson ocup&oacute; el puesto de Secretario General&nbsp;desde el 16 de abril de 2015 hasta el 31 de enero de 2018; director general acad&eacute;mico del 24 de abril de 2008 al 15 de mayo de 2011; coordinador del &aacute;rea de Pol&iacute;ticas P&uacute;blicas de la maestr&iacute;a en Ciencias Sociales en 2007; y coordinador del Programa de Estudios Pol&iacute;ticos y Gesti&oacute;n P&uacute;blica en 2001.<\/p>\n<p class=\"x_MsoNormal\" style=\"margin: 0cm 0cm 10pt;padding: 0px;border: 0px;font-size: 11pt;font-family: Calibri, sans-serif;vertical-align: baseline;text-align: justify;color: #212121\">El pr&oacute;ximo 23 de abril se llevar&aacute; a cabo la ceremonia de Toma de Protesta en los patios de la instituci&oacute;n ante la presencia de personalidades locales para que de manera formal inicie su gesti&oacute;n que concluir&aacute; luego de cinco a&ntilde;os de trabajo en 2023.<\/p>\n<p class=\"x_MsoNormalCxSpMiddle\">Los integrantes de la Junta de Gobierno son: Dra. Gabriela Grijalva Monteverde<\/p>\n<p class=\"x_MsoNormalCxSpMiddle\">Rectora de El Colegio de Sonora; Dra. Cirila Quintero Ram&iacute;rez, Directora General Regional Noreste de El Colegio de la Frontera Norte; Dr. Jean Meyer Barth, Profesor Em&eacute;rito del Centro de Investigaci&oacute;n y Docencia Econ&oacute;micas; Dr. Gustavo Verduzco Igart&uacute;a, Profesor Investigador del Centro de Estudios Sociol&oacute;gicos de El Colegio de M&eacute;xico; Dra. Mar&iacute;a del Carmen Castro V&aacute;squez, Profesora Investigadora del Centro de Estudios en Salud y Sociedad de El Colegio de Sonora.<\/p>\n<p class=\"x_MsoNormalCxSpMiddle\">&nbsp;<\/p>\n<p class=\"x_MsoNormalCxSpLast\">Adem&aacute;s la Dra. Arminda Guadalupe Garc&iacute;a de Le&oacute;n Pe&ntilde;&uacute;&ntilde;uri, Secretaria General Acad&eacute;mica de la Unidad Regional Centro de la Universidad de Sonora; Dr. Leonardo Lomel&iacute; Vanegas, Secretario General&nbsp; de la Universidad Nacional Aut&oacute;noma de M&eacute;xico; y el Dr. Pablo Wong Gonz&aacute;lez, Director General del Centro de Investigaci&oacute;n en Alimentaci&oacute;n y Desarrollo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Designan al doctor Juan Poom Medina como rector de EL COLSON para el periodo 2018-2023<\/p>\n","protected":false},"author":1,"featured_media":194524,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[314],"class_list":["post-194523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-colson"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2018\/04\/1523382719_poom.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/194523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=194523"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/194523\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/194524"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=194523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=194523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=194523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}