{"id":193340,"date":"2018-05-04T18:07:18","date_gmt":"2018-05-04T18:07:18","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2018\/05\/04\/reportan-nueva-hospitalizacion-de-jose-jose\/"},"modified":"2018-05-04T18:07:18","modified_gmt":"2018-05-04T18:07:18","slug":"reportan-nueva-hospitalizacion-de-jose-jose","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2018\/05\/04\/reportan-nueva-hospitalizacion-de-jose-jose\/","title":{"rendered":"Reportan nueva hospitalizacion de Jose Jose"},"content":{"rendered":"<p>El cantante mexicano Jos&eacute; Jos&eacute;, ha regresado a un hospital en Miami pues su cuadro de salud, se ha complicado y contin&uacute;a adelgazando, informaron hoy televisoras.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;&#8220;El Pr&iacute;ncipe de la canci&oacute;n&#8221; hab&iacute;a sido llevado a un asilo para que continuara recibiendo tratamiento m&eacute;dico, pero regres&oacute; al hospital ante las complicaciones, inform&oacute; la cadena Telemundo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;Un reporte de la cadena Univisi&oacute;n indic&oacute; por otro lado que en estos momentos se tienen que buscar la manera de que &eacute;l cantante pueda &#8220;forzar su rehabilitaci&oacute;n&#8221; para que asimile todo los alimentos y las medicinas tan fuertes que le tienen que seguir administrando.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;El 24 de marzo del a&ntilde;o pasado, el propio Jos&eacute; Jos&eacute;, anunci&oacute; que padec&iacute;a c&aacute;ncer de p&aacute;ncreas y luego en noviembre su publicista inform&oacute; que le hab&iacute;an intervenido para extirparle el tumor y que ya estaba libre de c&aacute;ncer.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;A principios de febrero pasado fue trasladado a Miami para celebrar su cumplea&ntilde;os y el de su esposa. Estuvo en un hospital durante varios d&iacute;as y luego fue trasladado a un asilo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;El artista estaba siendo sometido en la Ciudad de M&eacute;xico a un tratamiento en el que le suministraban nutrientes v&iacute;a intravenosa ya que aparentemente hab&iacute;a tenido problemas para ingerir alimentos, lo que se notaba en su alarmante p&eacute;rdida de peso.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;Jos&eacute; R&oacute;mulo Sosa Ortiz, nacido en Ciudad de M&eacute;xico en 1948 en el seno de una familia de m&uacute;sicos, salt&oacute; a la popularidad con &#8220;El Triste&#8221;, la melod&iacute;a que lo catapult&oacute; tras el II Festival de la OTI en 1970.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reportan nueva hospitalizacion de Jose Jose<\/p>\n","protected":false},"author":1,"featured_media":193341,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[219],"tags":[1637],"class_list":["post-193340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos","tag-jose-jose"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2018\/05\/1525482438_josejose.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/193340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=193340"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/193340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/193341"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=193340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=193340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=193340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}