{"id":192612,"date":"2018-05-20T12:32:33","date_gmt":"2018-05-20T12:32:33","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2018\/05\/20\/presenta-luis-guero-nieves-propuesta-prometer-si-empobrece\/"},"modified":"2018-05-20T12:32:33","modified_gmt":"2018-05-20T12:32:33","slug":"presenta-luis-guero-nieves-propuesta-prometer-si-empobrece","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2018\/05\/20\/presenta-luis-guero-nieves-propuesta-prometer-si-empobrece\/","title":{"rendered":"Presenta Luis Guero Nieves propuesta: Prometer si empobrece"},"content":{"rendered":"<p>Hermosillo, Sonora a 20 de Mayo 2018.- Con el respaldo de liderazgos del sur de la ciudad y zona rural arranc&oacute; de manera oficial la campa&ntilde;a como candidato de la coalici&oacute;n PAN &ndash; PRD del Distrito 12 Hermosillo Sur, &nbsp;Luis &ldquo;G&uuml;ero&rdquo; Nieves, dando a conocer su primera propuesta llamada &ldquo;Prometer s&iacute; empobrece&rdquo;.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Mi propuesta de &ldquo;Prometer s&iacute; empobrece&rdquo; se refiere a que los ciudadanos no queremos a personajes que prometan algo para obtener votos y luego se olviden de esas &nbsp;promesas, por esto yo propongo que se pueda demandar a todo el que no cumpla sin importar colores para que estos no puedan volver a competir por ning&uacute;n cargo tal como lo hemos visto hasta ahora con aquellos que dejaron en malas condiciones a Hermosillo y ahora est&aacute; en una contienda por el Senado&rdquo;, se&ntilde;al&oacute; Luis &ldquo;G&uuml;ero&rdquo; Nieves, candidato de la colaci&oacute;n PAN &ndash; PRD.<\/p>\n<p>&nbsp;<\/p>\n<p>Adem&aacute;s hizo &eacute;nfasis en la importancia de brindar seguimiento a obras y programas que han beneficiado a familias recordando que el paso de Dami&aacute;n Zepeda por el Distrito V dej&oacute; &ldquo;un mejor Hermosillo creando y rehabilitando espacios de recreaci&oacute;n familiar, algo que no hicieron los de la actual administraci&oacute;n, de hecho nos quedaron mucho a deber&rdquo;.<\/p>\n<p>&nbsp;<\/p>\n<p>Por &uacute;ltimo, adem&aacute;s de agradecer la presencia del candidato al Senado Antonio &ldquo;To&ntilde;o&rdquo; Astiazar&aacute;n; Myrna Rea, Candidata a la Presidencia Municipal; Miguel Armenta, Dirigente Estatal del PRD; y Jes&uacute;s Ram&oacute;n D&iacute;az, Presidente del CDM PAN; Luis &ldquo;G&uuml;ero&rdquo; Nieves coment&oacute; que dar&aacute; a conocer cada una de sus propuestas a trav&eacute;s de recorridos por colonias tal como lo hizo en su etapa Legislador de 2012 a 2015, siendo el primero en lograr desde un curul la mayor inversi&oacute;n en infraestructura deportiva resaltando obras como el alumbrado de La Milla, circuito de atletismo y jogging en los campos de la Universidad de Sonora, unidad Deportiva &ldquo;Plutarco El&iacute;as Calles&rdquo; en el Coloso Alto, rehabilitaci&oacute;n del parque &ldquo;Las Arboledas#, rehabilitaci&oacute;n e iluminaci&oacute;n de las Unidades Deportivas en &ldquo;Los Portales&rdquo;, &ldquo;Altares y la Milla Sur&rdquo; en la colonia Cuauht&eacute;moc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Presenta Luis Guero Nieves propuesta: Prometer si empobrece<\/p>\n","protected":false},"author":1,"featured_media":192613,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[260],"class_list":["post-192612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-guero-nieves"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2018\/05\/1526844753_guero-nieves-mayo19-800x396.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/192612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=192612"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/192612\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/192613"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=192612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=192612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=192612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}