{"id":192247,"date":"2018-05-24T11:00:52","date_gmt":"2018-05-24T11:00:52","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2018\/05\/24\/despues-de-luis-miguel-se-viene-la-serie-de-jose-jose\/"},"modified":"2018-05-24T11:00:52","modified_gmt":"2018-05-24T11:00:52","slug":"despues-de-luis-miguel-se-viene-la-serie-de-jose-jose","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2018\/05\/24\/despues-de-luis-miguel-se-viene-la-serie-de-jose-jose\/","title":{"rendered":"Despues de Luis Miguel, se viene la serie de Jose Jose"},"content":{"rendered":"<p>Tras el &eacute;xito que ha tenido la serie sobre la vida de Luis Miguel, Netflix se alista para presentar la historia de otro grande de la m&uacute;sica mexicana: Jos&eacute; Jos&eacute;.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuentes de Netflix confirmaron a El Universal que estrenar&aacute;n &#8220;Jos&eacute; Jos&eacute;, el pr&iacute;ncipe de la canci&oacute;n&#8221; el pr&oacute;ximo 1 de junio.<\/p>\n<p>&nbsp;<\/p>\n<p>En diciembre de 2017 se mostr&oacute; un adelanto de la serie, protagonizada por Alejandro de la Madrid y que narra los inicios de la carrera del int&eacute;rprete.<\/p>\n<p>&nbsp;<\/p>\n<p>Danna Paola da vida a Lucero, el primer gran amor de Jos&eacute; Jos&eacute;, mientras que Itat&iacute; Cantoral interpreta a &#8220;Kiki&#8221; Herrera Calles, la primera esposa del cantante.<\/p>\n<p>&nbsp;<\/p>\n<p>La serie tocar&aacute; temas como la depresi&oacute;n y alcoholismo que enfrent&oacute; Jos&eacute; Jos&eacute;, as&iacute; como su consumo de drogas.<\/p>\n<p>&nbsp;<\/p>\n<p>En una entrevista el pasado diciembre, Jos&eacute; Jos&eacute; dijo estar impresionado por la caracterizaci&oacute;n que hizo de &eacute;l Alejandro de la Madrid.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Hasta camina chueco como yo&#8221;, coment&oacute;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despues de Luis Miguel, se viene la serie de Jose Jose<\/p>\n","protected":false},"author":1,"featured_media":192248,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[219],"tags":[1637],"class_list":["post-192247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos","tag-jose-jose"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2018\/05\/1527184852_jose-jose-luis-miguel.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/192247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=192247"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/192247\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/192248"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=192247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=192247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=192247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}