{"id":191588,"date":"2018-06-03T10:25:28","date_gmt":"2018-06-03T10:25:28","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2018\/06\/03\/cumple-sonora-siete-meses-sin-casos-de-dengue\/"},"modified":"2018-06-03T10:25:28","modified_gmt":"2018-06-03T10:25:28","slug":"cumple-sonora-siete-meses-sin-casos-de-dengue","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2018\/06\/03\/cumple-sonora-siete-meses-sin-casos-de-dengue\/","title":{"rendered":"Cumple Sonora siete meses sin casos de dengue"},"content":{"rendered":"<p>Hermosillo, Sonora, junio 03 de 2018.- El Estado de Sonora se mantiene sin registrar casos de dengue desde hace siete meses, gracias a las acciones que realiza la Secretar&iacute;a de Salud para combatir al mosco y a la participaci&oacute;n social al limpiar sus hogares, resalt&oacute; Gerardo &Aacute;lvarez Hern&aacute;ndez.<\/p>\n<p>&nbsp;<\/p>\n<p>El Director General de Promoci&oacute;n a la Salud y Prevenci&oacute;n de Enfermedades detall&oacute; que en el Panorama Epidemiol&oacute;gico se registran ya 28 semanas sin dengue en la entidad, el &uacute;ltimo corresponde a la semana 45 del 2017.<\/p>\n<p>&nbsp;<\/p>\n<p>En el reporte del Panorama Epidemiol&oacute;gico m&aacute;s reciente, se&ntilde;al&oacute;, tambi&eacute;n se informa que el &uacute;ltimo caso de chikungunya ocurri&oacute; en la semana 26 del 2016, por lo que se acumulan 98 semanas sin este padecimiento.<\/p>\n<p>&nbsp;<\/p>\n<p>El funcionario estatal coment&oacute; tambi&eacute;n que se tienen ya 24 semanas sin confirmaci&oacute;n de casos de zika en la entidad, debido a que el &uacute;ltimo se present&oacute; en la semana 49 del 2017.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Para evitar los criaderos del mosquito Aedes aegypti y de la garrapata caf&eacute;, es importante no bajar la guardia y continuar con las acciones de limpieza en nuestros patios&rdquo;, enfatiz&oacute;.<\/p>\n<p>&nbsp;<\/p>\n<p>Agreg&oacute; que para evitar picaduras por el mosquito se recomienda a la poblaci&oacute;n vestir pantalones y usar ropa que cubra los brazos, en caso de ser necesario, usar repelentes comerciales a base de DEET, que son los autorizados para su venta p&uacute;blica.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Es importante tirar los criaderos de mosquitos en los hogares como botes, botellas, tapas, corcholatas y llantas; tambi&eacute;n voltear y tapar las cubetas donde se pueda almacenar agua, y lavar frecuentemente recipientes en los que se acumule&rdquo;, a&ntilde;adi&oacute; el funcionario estatal.<\/p>\n<p>&nbsp;<\/p>\n<p>Con respecto a fiebre manchada, &Aacute;lvarez Hern&aacute;ndez manifest&oacute; que todas las personas pueden presentarla, pero las complicaciones y resultados fatales son m&aacute;s comunes en grupos vulnerables, sin embargo, puede curarse si el antibi&oacute;tico espec&iacute;fico, doxiciclina, se administra en los tres primeros d&iacute;as de iniciados los s&iacute;ntomas.<\/p>\n<p>&nbsp;<\/p>\n<p>A&ntilde;adi&oacute; que la presencia de fiebre, dolor de cabeza y malestar general, con el antecedente de historia de contacto con garrapatas, es suficiente para sospechar de la enfermedad, y ante ello es importante acudir al m&eacute;dico.<\/p>\n<p>&nbsp;<\/p>\n<p>Esta semana no se confirmaron casos de fiebre manchada en la entidad, con lo que se mantiene el acumulado de 25 casos durante el a&ntilde;o, adem&aacute;s, dijo, no se presentaron defunciones y se mantiene el registro de 12 fallecimientos hasta el momento.<\/p>\n<p>&nbsp;<\/p>\n<p>&Aacute;lvarez Hern&aacute;ndez explic&oacute; que esta semana inici&oacute; la temporada interestacional de influenza, en donde se tiene una baja circulaci&oacute;n de virus respiratorios, la cual se extiende desde la semana 20 a la 39 de cada a&ntilde;o.<\/p>\n<p>&nbsp;<\/p>\n<p>El Panorama Epidemiol&oacute;gico se&ntilde;ala que esta semana no ocurrieron casos de influenza, por lo que se mantiene el acumulado de 77 en la temporada; adem&aacute;s no sucedieron defunciones por este padecimiento, con lo que se mantiene el acumulado de 10 fallecimientos reportados hasta el momento.<\/p>\n<p>&nbsp;<\/p>\n<p>Respecto a los padecimientos relacionados con la temporada de calor, el funcionario estatal recomend&oacute; no esperar a tener sed para tomar l&iacute;quidos y tratar de consumir como m&iacute;nimo dos litros de agua a diario.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Se recomienda evitar la exposici&oacute;n solar en las horas de mayor radiaci&oacute;n, que es entre las 11:00 y las 17:00 horas, pero en caso de hacerlo, usar siempre bloqueador solar; elegir las primeras horas del d&iacute;a para llevar a cabo las actividades al aire libre y las deportivas, as&iacute; como las ceremonias c&iacute;vicas&rdquo;, se&ntilde;al&oacute;.<\/p>\n<p>&nbsp;<\/p>\n<p>Es recomendable, a&ntilde;adi&oacute;, vestir ropa ligera, holgada y de colores claros, que cubra la piel de la exposici&oacute;n frecuente al Sol, as&iacute; como utilizar sombrero o sombrilla para protegerse de los rayos solares.<\/p>\n<p>&nbsp;<\/p>\n<p>Si se presenta diarrea o alguna sospecha de deshidrataci&oacute;n o efectos asociados al calor, coment&oacute; que se debe acudir de inmediato a la unidad de salud m&aacute;s cercana y evitar automedicarse.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Esta semana ocurrieron tres eventos asociados a la temporada de calor, se trata de dos deshidrataciones y un golpe de calor, con lo que se acumulan 40 eventos; no ocurrieron defunciones asociadas al calor, por lo que la temporada se mantiene sin fallecimientos&rdquo;, finaliz&oacute;.<\/p>\n<p>&nbsp;<\/p>\n<p>PARA PONER ATENCI&Oacute;N<\/p>\n<p>&nbsp;<\/p>\n<p>Entre los s&iacute;ntomas m&aacute;s importantes que pueden indicar que una persona est&aacute; sufriendo eventos adversos por exponerse a calor ambiental, est&aacute;n:&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&middot; &nbsp; &nbsp; &nbsp; &nbsp; Mareo.<\/p>\n<p>&nbsp;<\/p>\n<p>&middot; &nbsp; &nbsp; &nbsp; &nbsp; Sudoraci&oacute;n excesiva al principio, despu&eacute;s, falta de sudor.<\/p>\n<p>&nbsp;<\/p>\n<p>&middot; &nbsp; &nbsp; &nbsp; &nbsp; Enrojecimiento y sequedad de la piel.<\/p>\n<p>&nbsp;<\/p>\n<p>&middot; &nbsp; &nbsp; &nbsp; &nbsp; Fiebre con temperatura desde los 39 a los 49 grados cent&iacute;grados.<\/p>\n<p>&nbsp;<\/p>\n<p>&middot; &nbsp; &nbsp; &nbsp; &nbsp; Comportamiento inadecuado, ejemplo: comenzar a quitarse la ropa sin importar el lugar, como consecuencia de deterioro neurol&oacute;gico.<\/p>\n<p>&nbsp;<\/p>\n<p>&middot; &nbsp; &nbsp; &nbsp; &nbsp; Aceleraci&oacute;n del ritmo card&iacute;aco, con latido del coraz&oacute;n d&eacute;bil.<\/p>\n<p>&nbsp;<\/p>\n<p>&middot; &nbsp; &nbsp; &nbsp; &nbsp; Dolor de cabeza.<\/p>\n<p>&nbsp;<\/p>\n<p>&middot; &nbsp; &nbsp; &nbsp; &nbsp; Crisis convulsivas.<\/p>\n<p>&nbsp;<\/p>\n<p>Signos de mayor severidad, conocidos como de alarma, que requieren atenci&oacute;n m&eacute;dica inmediata, son:&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&middot; &nbsp; &nbsp; &nbsp; &nbsp; Piel que se siente caliente y seca, pero no sudorosa.<\/p>\n<p>&nbsp;<\/p>\n<p>&middot; &nbsp; &nbsp; &nbsp; &nbsp; Confusi&oacute;n o p&eacute;rdida del conocimiento.<\/p>\n<p>&nbsp;<\/p>\n<p>&middot; &nbsp; &nbsp; &nbsp; &nbsp; V&oacute;mitos frecuentes.<\/p>\n<p>&nbsp;<\/p>\n<p>&middot; &nbsp; &nbsp; &nbsp; &nbsp; Falta de aire o problemas para respirar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cumple Sonora siete meses sin casos de dengue<\/p>\n","protected":false},"author":1,"featured_media":191589,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[407],"class_list":["post-191588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-sec-salud"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2018\/06\/1528046728_56686683696a7.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/191588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=191588"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/191588\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/191589"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=191588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=191588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=191588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}