{"id":190559,"date":"2018-06-19T16:51:53","date_gmt":"2018-06-19T16:51:53","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2018\/06\/19\/piden-a-maloro-acosta-llevar-a-cajeme-programa-encausa\/"},"modified":"2018-06-19T16:51:53","modified_gmt":"2018-06-19T16:51:53","slug":"piden-a-maloro-acosta-llevar-a-cajeme-programa-encausa","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2018\/06\/19\/piden-a-maloro-acosta-llevar-a-cajeme-programa-encausa\/","title":{"rendered":"Piden a Maloro Acosta llevar a Cajeme programa EnCausa"},"content":{"rendered":"<p>Ayudar a que las familias de Cajeme, que se encuentran en pobreza extrema y que viven a&uacute;n en casas de cart&oacute;n, salgan de esta condici&oacute;n, pidi&oacute; la se&ntilde;ora Lourdes Luna de la colonia Valle Verde a Manuel Ignacio Maloro Acosta, pues dijo &ldquo;sabemos que lo hizo en Hermosillo, con un programa que implement&oacute; all&aacute;, el EnCausa y ese lo queremos aqu&iacute;&rdquo;.<\/p>\n<p>&nbsp;<\/p>\n<p>El candidato de la coalici&oacute;n Todos por M&eacute;xico, encabez&oacute; aqu&iacute; reuniones con adultos mayores, con mujeres obreras del parque industrial, realiz&oacute; recorridos casa por casa en colonias populares y visit&oacute; Pueblo Yaqui, para dialogar con las familias del medio rural.<\/p>\n<p>&nbsp;<\/p>\n<p>Las familias de Cajeme en estado de vulnerabilidad, &ldquo;no est&aacute;n solas&rdquo;, tendr&aacute;n el respaldo y el apoyo, para que puedan salir adelante en sus necesidades b&aacute;sicas, respondi&oacute; Maloro Acosta.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Desde el Senado, vamos a luchar en equipo con Sylvana Beltrones S&aacute;nchez, para reforzar los programas de Prospera y para impulsar una pol&iacute;tica social, que sume todos los programas de rescate a la pobreza y que los beneficios le lleguen a los adultos mayores, a las mujeres con microcr&eacute;ditos, para emprender un negocio, pero sobre todo con capacitaci&oacute;n en desarrollo humano&rdquo;, destac&oacute;.<\/p>\n<p>&nbsp;<\/p>\n<p>Y es que los residentes de Cajeme de colonias en alta vulnerabilidad, pidieron a Maloro Acosta, replicar los programas que en Hermosillo sacaron de la pobreza extrema a familias, que hoy han encontrado respaldo para atender sus necesidades b&aacute;sicas.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Le pedimos que llegando al Senado, con el apoyo de todos, traiga ese programa a Cajeme y a todas las colonias populares, donde a&uacute;n hay mucha gente que no tiene ni vivienda, ni trabajo&rdquo;, plante&oacute; la se&ntilde;ora Lourdes Luna.<\/p>\n<p>&nbsp;<\/p>\n<p>En el caso de los adultos mayores, Maloro Acosta se comprometi&oacute; a impulsar las Casas de D&iacute;a, o guarder&iacute;as para personas de la tercera edad, y el empleo y la capacitaci&oacute;n como herramientas b&aacute;sicas, para que sigan aportando algo para ellos, para su familia y para su ciudad.<\/p>\n<p>&nbsp;<\/p>\n<p>Para las mujeres obreras, que al igual que muchas madres jefas de familia, tienen que salir a mantener a su familia, se comprometi&oacute; a reforzar los programas de becas para sus hijos, a mejorar el entorno donde viven con mejor seguridad y mejores espacios p&uacute;blicos.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Lo haremos a trav&eacute;s de una reforma a la ley de coordinaci&oacute;n fiscal, para que los municipios como Cajeme, tengan recursos para que puedan invertir en m&aacute;s patrullas, en m&aacute;s parques y que los gobiernos local y estatal, tengan presupuestos para las becas y para promover el empleo&rdquo;, asegur&oacute;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Piden a Maloro Acosta llevar a Cajeme programa EnCausa<\/p>\n","protected":false},"author":1,"featured_media":190560,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[2273],"class_list":["post-190559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-maloro"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2018\/06\/1529452313_990994425.JPG","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/190559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=190559"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/190559\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/190560"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=190559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=190559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=190559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}