{"id":190349,"date":"2018-06-21T11:51:39","date_gmt":"2018-06-21T11:51:39","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2018\/06\/21\/sre-avance-que-trump-reculara-sobre-migrantes-pero-del-dicho-al-hecho%c2%80\/"},"modified":"2018-06-21T11:51:39","modified_gmt":"2018-06-21T11:51:39","slug":"sre-avance-que-trump-reculara-sobre-migrantes-pero-del-dicho-al-hecho%c2%80","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2018\/06\/21\/sre-avance-que-trump-reculara-sobre-migrantes-pero-del-dicho-al-hecho%c2%80\/","title":{"rendered":"SRE: Avance que Trump reculara sobre migrantes, pero del dicho al hecho&acirc;\u0080&brvbar;"},"content":{"rendered":"<p>M&eacute;xico.- El Gobierno mexicano ve con buenos ojos que el presidente de Estados Unidos, Donald Trump, firmara la orden ejecutiva para poner fin a la separaci&oacute;n de las familias de migrantes en la frontera, pero no se conf&iacute;a.<\/p>\n<p>&nbsp;<\/p>\n<p>En este sentido, el subsecretario para Am&eacute;rica del Norte de la Secretar&iacute;a de Relaciones Exteriores (SRE), Carlos Sada Solana, afirm&oacute; que estar&aacute;n &ldquo;muy pendientes&rdquo; de las acciones que deber&aacute;n seguir las autoridades estadounidenses.<\/p>\n<p>&nbsp;<\/p>\n<p>En entrevista con Ciro G&oacute;mez Leyva, en Radio F&oacute;rmula, el diplom&aacute;tico asegur&oacute; que la decisi&oacute;n de Trump es un avance, pero cit&oacute; el viejo refr&aacute;n de: &ldquo;del dicho al hecho hay mucho trecho&rdquo;.&nbsp;&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Sada Solana indic&oacute; que el personal de la red de consulados en el pa&iacute;s vecino del norte observar&aacute; con detenimiento las instalaciones donde albergar&aacute;n a los ni&ntilde;os con los padres.&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Es muy importante la supervisi&oacute;n directa sobre qu&eacute; es lo que pasa en el terreno de la pr&aacute;ctica, porque del dicho al hecho hay mucho trecho y estamos viendo con inter&eacute;s cu&aacute;les son los siguientes pasos&rdquo;, se&ntilde;al&oacute;.<\/p>\n<p>De acuerdo con el funcionario, el decreto estadounidense, que permite que los ni&ntilde;os que cruzan la frontera junto a sus padres sin papeles se queden con ellos en los centros de detenci&oacute;n de inmigrantes durante un plazo, s&oacute;lo es un peque&ntilde;o avance porque la pol&iacute;tica de &ldquo;Cero Tolerancia&rdquo; contin&uacute;a.&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Hay un peque&ntilde;o avance, aunque Cero Tolerancia sigue, (por lo que) estaremos siguiendo con inter&eacute;s los pasos para saber qu&eacute; van a hacer de inmediato, cu&aacute;nto se van a tardar y c&oacute;mo proceder&aacute;n a partir de hoy; hay muchos criterios que van aplicar y eso hay que monitorearlo&rdquo;, apunt&oacute;.&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Asimismo, afirm&oacute; que la Patrulla Fronteriza tiene la obligaci&oacute;n de notificar a las autoridades mexicanas de las detenciones:&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Vamos a estar muy pendientes para que los que est&aacute;n separados se reunifiquen de inmediato, no ser&aacute; un proceso f&aacute;cil, y ver las instalaciones donde van a albergar a los ni&ntilde;os con los padres&rdquo;, acot&oacute;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SRE: Avance que Trump reculara sobre migrantes, pero del dicho al hecho&acirc;\u0080&brvbar;<\/p>\n","protected":false},"author":1,"featured_media":190350,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[1223],"class_list":["post-190349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-sre"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2018\/06\/1529607099_5b28327a9ce84.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/190349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=190349"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/190349\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/190350"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=190349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=190349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=190349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}