{"id":186423,"date":"2018-09-16T21:11:15","date_gmt":"2018-09-16T21:11:15","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2018\/09\/16\/rinde-protesta-celida-lopez-cardenas-como-presidenta-municipal\/"},"modified":"2018-09-16T21:11:15","modified_gmt":"2018-09-16T21:11:15","slug":"rinde-protesta-celida-lopez-cardenas-como-presidenta-municipal","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2018\/09\/16\/rinde-protesta-celida-lopez-cardenas-como-presidenta-municipal\/","title":{"rendered":"Rinde protesta Celida Lopez Cardenas como Presidenta Municipal"},"content":{"rendered":"<p>Hermosillo, Sonora; Septiembre 16 de 2018.- &ldquo;La transformaci&oacute;n real de una ciudad inicia con la transformaci&oacute;n de las personas que la habitan y tenemos que sacar adelante a esta gran ciudad&rdquo;, expres&oacute; la presidenta municipal C&eacute;lida Teresa L&oacute;pez C&aacute;rdenas en la Sesi&oacute;n Solemne de Instalaci&oacute;n del Ayuntamiento de Hermosillo para el periodo 2018- 2021.<\/p>\n<p>&nbsp;<\/p>\n<p>La capital del estado despu&eacute;s de tres a&ntilde;os ser&aacute; ejemplo en M&eacute;xico, adelant&oacute;, y en esta ciudad empezar&aacute; la verdadera transformaci&oacute;n social que presenta el proyecto de naci&oacute;n de Andr&eacute;s Manuel L&oacute;pez Obrador.<\/p>\n<p>&nbsp;<\/p>\n<p>La presidenta municipal asegur&oacute; que habr&aacute; una mejora palpable en los servicios p&uacute;blicos.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Mi compromiso es serio, tendremos que eliminar direcciones, desaparecer&aacute;n muchas funciones que tiene el Ayuntamiento, pero que lamentablemente no se pueden financiar; tendremos que hacerlo con valent&iacute;a y empezar a adelgazar la administraci&oacute;n&rdquo;.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Necesitamos entender que esta situaci&oacute;n econ&oacute;mica nos obliga a volver a lo b&aacute;sico, a lo que realmente no podemos evadir que es seguridad y servicios p&uacute;blicos; en tres a&ntilde;os esta ciudad ser&aacute; ejemplo a nivel nacional&rdquo;, destac&oacute;.<\/p>\n<p>&nbsp;<\/p>\n<p>Recuperaci&oacute;n del tejido social<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Comete traici&oacute;n a la patria, el que aqu&iacute; en la ciudad de Hermosillo contin&uacute;e envenenando a nuestros adolescentes. Continuamos hoy con ese mensaje que valientemente sostuvo en su campa&ntilde;a Ernesto de Lucas Hopkins, con el mensaje de Myrna Rea S&aacute;nchez, de Carlos Alberto Le&oacute;n Garc&iacute;a, de Norberto Barraza, de Jos&eacute; Guadalupe Curiel; todos y cada uno de nosotros en campa&ntilde;a lo dijimos: no podemos permitir que en esta ciudad se siga envenenando a nuestros j&oacute;venes con &lsquo;cristal&rsquo;, tenemos que hacer todos juntos un gran esfuerzo&rdquo;.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Por eso retomo la propuesta de Ernesto de Lucas Hopkins, en esta administraci&oacute;n, con su ayuda y la de todos ustedes, haremos realidad su propuesta de la primera cl&iacute;nica de rehabilitaci&oacute;n de esta ciudad, que ser&aacute; ejemplo para M&eacute;xico y para el mundo&rdquo;, anunci&oacute;.<\/p>\n<p>&nbsp;<\/p>\n<p>En su mensaje a la comunidad, L&oacute;pez C&aacute;rdenas solicit&oacute; a todos los hombres y mujeres que cuentan con un capital econ&oacute;mico que ayuden a construir esta nueva etapa en Hermosillo.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Tengo que suplicarte que te responsabilices hoy y que hagas m&aacute;s de lo que acostumbras hacer, que te preguntes cu&aacute;ntas horas a la semana le ayudas a tu pr&oacute;jimo, a tu vecino, a tu hermano&rdquo;, exhort&oacute;.<\/p>\n<p>&nbsp;<\/p>\n<p>Adem&aacute;s, resalt&oacute; la importancia de invertir en cultura, debido a que es otra herramienta b&aacute;sica para transformar la ciudad por medio de fomentar el lado humano que tenemos tan abandonado.<\/p>\n<p>&nbsp;<\/p>\n<p>Rendiremos cuentas a la comunidad<\/p>\n<p>&nbsp;<\/p>\n<p>No voy a esconderme ni a simular procesos, enfatiz&oacute; la alcaldesa, voy a enfrentarme cada mes junto con los servidores p&uacute;blicos a una Asamblea Municipal conformada por m&aacute;s de mil 200 personas, uno por colonia. Adem&aacute;s formaremos una asociaci&oacute;n de padres de familia por colonia para que haya una perfecta sinton&iacute;a en todas las pol&iacute;ticas p&uacute;blicas.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;No le tengo miedo al reclamo ciudadano y a las grandes exigencias de justicia de los hermosillenses; vamos a organizar una verdadera participaci&oacute;n ciudadana mediante a esta herramienta&rdquo;, mencion&oacute;.<\/p>\n<p>&nbsp;<\/p>\n<p>Natalia Rivera Grijalva, jefa de la oficina del Ejecutivo Estatal, en representaci&oacute;n de la gobernadora Claudia Pavlovich Arellano, tom&oacute; protesta de ley a los integrantes del nuevo Ayuntamiento encabezado por L&oacute;pez C&aacute;rdenas y el s&iacute;ndico municipal, Ferm&iacute;n Gonz&aacute;lez Gaxiola.<\/p>\n<p>&nbsp;<\/p>\n<p>Asistieron Francisco Guti&eacute;rrez Rodr&iacute;guez, presidente del Supremo Tribunal de Justicia del Estado; Florentino Valencia Samaniego, representante de Andr&eacute;s Manuel L&oacute;pez Obrador, presidente electo de M&eacute;xico; Norberto Cort&eacute;s Rodr&iacute;guez, comandante de la Cuarta Zona Militar; el diputado federal Jorge Ruso; los ex alcaldes Francisco B&uacute;rquez Valenzuela y Alejandro L&oacute;pez Caballero; y el presidente estatal de Morena, Jacobo Mendoza Ruiz.<\/p>\n<p>&nbsp;<\/p>\n<p>Forman parte del Cuerpo de regidores:<\/p>\n<p>&nbsp;<\/p>\n<p>Mayra Ortega Figueroa<\/p>\n<p>Carlos Duarte Rubio<\/p>\n<p>Mar&iacute;a Engracia Carrazco Valenzuela<\/p>\n<p>Sergio Luque Santana<\/p>\n<p>Ofelia Valenzuela Mungarro<\/p>\n<p>Iv&aacute;n Miranda P&eacute;rez<\/p>\n<p>Emma Guadalupe Rodr&iacute;guez Molina<\/p>\n<p>Gaspar Paco Gonz&aacute;lez<\/p>\n<p>Ver&oacute;nica Rodr&iacute;guez Gallardo<\/p>\n<p>Armando Moreno Soto<\/p>\n<p>Guadalupe Mar&iacute;a Mend&iacute;vil Corral<\/p>\n<p>Ignacio Lagarda Hermosillo<\/p>\n<p>Myrna Rea S&aacute;nchez<\/p>\n<p>Ernesto de Lucas Hopkins<\/p>\n<p>X&oacute;chitl S&aacute;nchez Garc&iacute;a<\/p>\n<p>Sebasti&aacute;n Heras Gast&eacute;lum<\/p>\n<p>Carlos Le&oacute;n Garc&iacute;a<\/p>\n<p>Carlos Sosa Casta&ntilde;eda<\/p>\n<p>Jos&eacute; Guadalupe Curiel<\/p>\n<p>Rafael Garc&iacute;a Porchas<\/p>\n<p>Rogelio Monta&ntilde;o Herrera<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rinde protesta Celida Lopez Cardenas como Presidenta Municipal<\/p>\n","protected":false},"author":1,"featured_media":186424,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[1579],"class_list":["post-186423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-celida-lopez"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2018\/09\/1537157475_celidal.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/186423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=186423"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/186423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/186424"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=186423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=186423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=186423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}