{"id":183723,"date":"2018-11-12T06:33:50","date_gmt":"2018-11-12T06:33:50","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2018\/11\/12\/aplicaran-estado-y-federacion-plan-de-desarrollo-urbano-en-ciudades-fronterizas\/"},"modified":"2018-11-12T06:33:50","modified_gmt":"2018-11-12T06:33:50","slug":"aplicaran-estado-y-federacion-plan-de-desarrollo-urbano-en-ciudades-fronterizas","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2018\/11\/12\/aplicaran-estado-y-federacion-plan-de-desarrollo-urbano-en-ciudades-fronterizas\/","title":{"rendered":"Aplicaran Estado y Federacion plan de Desarrollo Urbano en ciudades fronterizas"},"content":{"rendered":"<p>Los municipios de San Luis R&iacute;o Colorado y Nogales fueron seleccionados entre las 15 ciudades del pa&iacute;s, en las que el pr&oacute;ximo Gobierno Federal aplicar&aacute; un Plan de Desarrollo Urbano para comunidades con alta marginaci&oacute;n, inform&oacute; Elia Sallard Hern&aacute;ndez.<\/p>\n<p>Luego de participar en un recorrido por comunidades marginadas de San Luis R&iacute;o Colorado junto al pr&oacute;ximo titular de la Secretar&iacute;a de Desarrollo Agrario, Territorial y Urbano (Sedatu), Rom&aacute;n Meyer Falc&oacute;n, la directora general de la Comisi&oacute;n de Vivienda del Estado de Sonora (Coves), indic&oacute; que el proyecto contempla la inversi&oacute;n de 10 mil millones de pesos a nivel nacional.<\/p>\n<p>&ldquo;Agradecemos el inter&eacute;s por parte del pr&oacute;ximo titular de Sedatu por conocer las necesidades de vivienda en nuestro estado, donde la gobernadora Claudia Pavlovich nos ha instruido a trabajar en coordinaci&oacute;n con las pr&oacute;ximas autoridades federales para multiplicar el n&uacute;mero de acciones que beneficien a las familias que m&aacute;s lo necesitan&rdquo;, expres&oacute; la funcionaria estatal.<\/p>\n<p>El recorrido y reuni&oacute;n de trabajo por el municipio fronterizo estuvo encabezado por el alcalde Santos Gonz&aacute;lez Yescas, quien expuso a los pr&oacute;ximos titulares de vivienda a nivel federal, las necesidades de San Luis R&iacute;o Colorado en materia de infraestructura, desarrollo urbano y vivienda.<\/p>\n<p>Acompa&ntilde;ando a Meyer Falc&oacute;n, participaron en las reuniones de trabajo, Carlos Mart&iacute;nez Vel&aacute;zquez, pr&oacute;ximo director general del Infonavit; y Armando Rosales Garc&iacute;a, propuesto para la Subsecretar&iacute;a de Desarrollo Urbano y de Vivienda en la Sedatu, adem&aacute;s de Carina Arvizu Machado y Daniel Gonz&aacute;lez, del equipo de transici&oacute;n.<\/p>\n<p>En presencia de los propuestos para encabezar la mayor parte del gabinete de Vivienda del pr&oacute;ximo Gobierno Federal, la titular de la Coves expuso los programas que se consideran prioritarios para impulsar, fortalecer y mantener vigentes con apoyo de subsidios de la federaci&oacute;n.<\/p>\n<p>Entre ellos se encuentran los programas sociales enfocados en abatir el hacinamiento, vivienda completa para familias en pobreza extrema, acceso a la vivienda para trabajadores no afiliados y de los sectores productivos primarios como son la pesca y miner&iacute;a, adem&aacute;s de vivienda para sonorenses migrantes.<\/p>\n<p>Como parte de los avances en atenci&oacute;n a estos sectores, Sallard Hern&aacute;ndez expuso a la mesa de trabajo el acercamiento que se ha tenido con familias que viven en comunidades pesqueras y mineras para conocer sus necesidades espec&iacute;ficas de vivienda, para trazar los programas adecuados que permitan solventarlos, as&iacute; como los lazos de colaboraci&oacute;n establecidos con los consulados mexicanos en Arizona para atenci&oacute;n a migrantes.<\/p>\n<p>Por parte del Gobierno del Estado de Sonora atendi&oacute; los temas de infraestructura y desarrollo urbano para San Luis R&iacute;o Colorado, el coordinador de Proyectos Especiales de la Secretar&iacute;a de Infraestructura y Desarrollo Urbano (Sidur), &Aacute;ngel L&oacute;pez Guzm&aacute;n.<\/p>\n<p>Se anunci&oacute; un recorrido similar por el municipio fronterizo de Nogales este s&aacute;bado, para identificar las necesidades particulares de vivienda, desarrollo urbano y seguridad que permitan mejorar la calidad de vida de sus pobladores.<\/p>\n<p>El Plan de Desarrollo Urbano anunciado por el pr&oacute;ximo Gobierno Federal corresponde a un programa especial para mejorar la calidad de vida de las familias que viven en las comunidades m&aacute;s marginadas en 15 ciudades tur&iacute;sticas o fronterizas de M&eacute;xico.<\/p>\n<p>El resto de las ciudades son: Acapulco de Ju&aacute;rez, Los Cabos, Valle de Banderas, Puerto Vallarta, Solidaridad, Tijuana, Matamoros, Ciudad Acu&ntilde;a, Mexicali, Reynosa, Nuevo Laredo y Piedras Negras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aplicaran Estado y Federacion plan de Desarrollo Urbano en ciudades fronterizas de Sonora<\/p>\n","protected":false},"author":1,"featured_media":183724,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[810],"class_list":["post-183723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-coves"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2018\/11\/1542029630_coves-s-500x303.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/183723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=183723"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/183723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/183724"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=183723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=183723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=183723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}