{"id":183102,"date":"2018-11-23T14:13:08","date_gmt":"2018-11-23T14:13:08","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2018\/11\/23\/incrementara-el-frio-este-fin-de-semana-en-sonora-conagua\/"},"modified":"2018-11-23T14:13:08","modified_gmt":"2018-11-23T14:13:08","slug":"incrementara-el-frio-este-fin-de-semana-en-sonora-conagua","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2018\/11\/23\/incrementara-el-frio-este-fin-de-semana-en-sonora-conagua\/","title":{"rendered":"Incrementara el frio este fin de semana en Sonora: Conagua"},"content":{"rendered":"<p class=\"MsoNormal\"><span lang=\"ES-MX\">Desde este viernes y hasta el domingo, dos frentes fr&iacute;os tocar&aacute;n territorio sonorense y de esa forma contribuir&aacute;n para seguir manteniendo las temperaturas bajas, asever&oacute; Gilberto Lagarda V&aacute;zquez.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">El meteor&oacute;logo de la Comisi&oacute;n Nacional del Agua en Sonora, se&ntilde;al&oacute; que este viernes ingres&oacute; al estado un frente fr&iacute;o d&eacute;bil y para el domingo otro fen&oacute;meno similar pero que sus alcances ser&aacute;n, de traer consigo descensos m&aacute;s marcados en las temperaturas, en pr&aacute;cticamente toda la entidad.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span lang=\"ES-MX\"><span>&nbsp;<\/span>&ldquo;Este &uacute;ltimo frente fr&iacute;o si viene m&aacute;s fuerte y se espera que sea un descenso m&aacute;s marcado en las temperaturas y ser&iacute;a un inicio de la pr&oacute;xima semana con temperaturas bajas para Sonora. Volver&iacute;an varios lugares como bajo y Hermosillo, y (Ciudad) Obreg&oacute;n podr&iacute;an a bajar de los 10 grados cent&iacute;grados&rdquo;, dijo.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Lagarda V&aacute;zquez, resalt&oacute; ese frente fr&iacute;o del domingo, traer&aacute; consigo rachas de vientos mayores a los 50 kil&oacute;metros por hora en la mayor parte del estado hasta el lunes.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Igualmente, extern&oacute;, que para este s&aacute;bado se esperan lluvias moderadas menores de 25 mil&iacute;metros para el oriente y sur de Sonora, debido a la humedad presente.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Finalmente, el meteor&oacute;logo de la Conagua en Sonora abund&oacute;, que en la zona del oriente y norte del estado habr&aacute; lugares donde el term&oacute;metro marque desde un grado hasta menos cero grados cent&iacute;grados, espec&iacute;ficamente Y&eacute;cora, Agua Prieta y Arizpe.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Incrementara el frio este fin de semana en Sonora: Conagua<\/p>\n","protected":false},"author":1,"featured_media":183103,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[224],"class_list":["post-183102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-conagua"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2018\/11\/1543007588_Hermosillo.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/183102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=183102"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/183102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/183103"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=183102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=183102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=183102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}