{"id":182644,"date":"2018-12-01T20:26:42","date_gmt":"2018-12-01T20:26:42","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2018\/12\/01\/inician-programa-de-prevencion-de-adicciones-en-escuelas\/"},"modified":"2018-12-01T20:26:42","modified_gmt":"2018-12-01T20:26:42","slug":"inician-programa-de-prevencion-de-adicciones-en-escuelas","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2018\/12\/01\/inician-programa-de-prevencion-de-adicciones-en-escuelas\/","title":{"rendered":"Inician programa de prevencion de adicciones en escuelas"},"content":{"rendered":"<div class=\"post-body-inner\">\n<p>Hermosillo, Sonora, 01 de diciembre de 2018.- La Coordinaci&oacute;n de Seguridad Ciudadana, a cargo de Mar&iacute;a Isabel Batriz L&oacute;pez, inici&oacute; el programa Prevenci&oacute;n del Suicidio y de las Adicciones, as&iacute; como el fortalecimiento del autoestima con alumnos del Colegio Dr. Braulio P&eacute;rez Marcio.<\/p>\n<p>La Coordinadora de Seguridad Ciudadana y Prevenci&oacute;n del Delito, coment&oacute; que debido a que la presidenta municipal, Celida L&oacute;pez C&aacute;rdenas, est&aacute; preocupada por la juventud, instruy&oacute; que se realizara el programa para los adolescentes que empiezan con el entusiasmo de salir adelante en sus estudios.<\/p>\n<p>Batriz L&oacute;pez explic&oacute; que invitaron a un equipo de profesionistas de la cl&iacute;nica de rehabilitaci&oacute;n San Gabriel, para apoyar en las pl&aacute;ticas con motivo de que los estudiantes est&eacute;n enterados y no ignoren lo que puede afectarles el consumir de inicio alcohol, porque despu&eacute;s lleva a sustancias t&oacute;xicas hasta que es demasiado tarde.<\/p>\n<p>&ldquo;Tenemos que estar al pendiente de esas personas que nos ofrecen y saber decir que no, porque hay alguien que los quiere, que son sus familias y padres&rdquo;, expres&oacute; a los ni&ntilde;os y j&oacute;venes que asistieron.<\/p>\n<p>El programa de pl&aacute;ticas se llev&oacute; por primera vez a dicho plantel escolar, pero se replicar&aacute; a todos los centros educativos posibles con ni&ntilde;os de 10 a&ntilde;os en adelante, donde tambi&eacute;n se dar&aacute; seguimiento con distintos temas en cada ocasi&oacute;n, inform&oacute; la funcionaria.<\/p>\n<p>Los especialistas en adicciones, prevenci&oacute;n del suicidio y delito que impartir&aacute;n las charlas son: Esteban Arturo Molina, Viridiana Leyva Siqueiros y Mar&iacute;a Ofelia Ochoa Mora, quien inici&oacute; con el tema &ldquo;Fortaleciendo mi Autoestima&rdquo;.<\/p>\n<p>\u2028Estuvieron en el arranque Abdiel Isa&iacute; Aguirre L&oacute;pez, director del colegio; Aar&oacute;n Antonio Torres, presidente de la Comisi&oacute;n de Salud de la instituci&oacute;n; C&eacute;sar Ontiveros Mendoza, presidente del Sistema Educativo Adventista zona 2; M&iacute;a L&oacute;pez, presidenta de la Sociedad de Padres de Familia; y Ra&uacute;l Alberto Escalante, presidente de la Junta Escolar.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Inician programa de prevencion de adicciones en escuelas<\/p>\n","protected":false},"author":1,"featured_media":182645,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[10502],"class_list":["post-182644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-ayuntamiento-hmo"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2018\/12\/1543721202_programaescuelas.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/182644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=182644"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/182644\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/182645"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=182644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=182644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=182644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}