{"id":180350,"date":"2019-01-24T13:58:38","date_gmt":"2019-01-24T13:58:38","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2019\/01\/24\/no-vamos-a-desconocer-al-gobierno-de-maduro-sre\/"},"modified":"2019-01-24T13:58:38","modified_gmt":"2019-01-24T13:58:38","slug":"no-vamos-a-desconocer-al-gobierno-de-maduro-sre","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2019\/01\/24\/no-vamos-a-desconocer-al-gobierno-de-maduro-sre\/","title":{"rendered":"No vamos a desconocer al gobierno de Maduro: SRE"},"content":{"rendered":"<p>M&eacute;xico.- El titular de la Secretar&iacute;a de Relaciones Exteriores (SRE), Marcelo Ebrard, afirm&oacute; que el gobierno de M&eacute;xico<strong> no va a desconocer<\/strong>&nbsp;al actual gobierno de Venezuela encabezado por Nicol&aacute;s Maduro.<\/p>\n<div class=\"fb-quote fb_iframe_widget\" style=\"position: absolute;left: 244.5px;top: 816px\">&nbsp;<\/div>\n<p>En conferencia de prensa matutina, el secretario dijo que buscar&aacute;n el di&aacute;logo para evitar la <strong>confrontaci&oacute;n y la violencia pol&iacute;tica.<\/strong><\/p>\n<p>Nosotros tenemos relaciones diplom&aacute;ticas con Venezuela y tiene un gobierno constituido. No vamos, en este momento, a proceder a romper relaciones o desconocer ese gobierno. <cite> Marcelo Ebrard<\/cite><\/p>\n<p><span id=\"docs-internal-guid-c2b30526-7fff-f5a4-e882-08304eac4c63\"><span style=\"vertical-align: baseline\">El canciller reiter&oacute;, como ayer lo hicieron en un<a href=\"https:\/\/www.sdpnoticias.com\/internacional\/2019\/01\/23\/mexico-y-uruguay-urgen-a-dar-una-solucion-pacifica-a-la-crisis-politica-de-venezuela\"> comunicado conjunto<\/a> con el gobierno de Uruguay, que se apegar&aacute;n al <a href=\"https:\/\/www.sdpnoticias.com\/nacional\/2019\/01\/24\/me-apego-al-articulo-89-de-la-constitucion-en-caso-venezuela-amlo\">art&iacute;culo 89 de la Constituci&oacute;n<\/a> de la no intervenci&oacute;n en la pol&iacute;tica de otros pueblos.<\/span><\/span><\/p>\n<p><span id=\"docs-internal-guid-02ae84e0-7fff-f9ae-8468-8a8080390a1e\"><span style=\"vertical-align: baseline\">&ldquo;Coincidimos con la Organizaci&oacute;n de las Naciones Unidas (ONU), en primer lugar, respecto a que <strong>necesitamos hacer esfuerzos <\/strong>para reducir tensiones, evitar un escalamiento que lleve a la violencia y rechazar cualquier tipo de violencia pol&iacute;tica&rdquo;, dijo Ebrard.<\/span><\/span><\/p>\n<p>A&ntilde;adi&oacute; que buscar&aacute; hablar con naciones de la<strong> Uni&oacute;n Europea (UE) y de todo el mundo <\/strong>para buscar la paz y el di&aacute;logo, y aclar&oacute; que ellos est&aacute;n dispuestos, pero no depende de ellos que se realice.<\/p>\n<p><span id=\"docs-internal-guid-aa21560e-7fff-f35e-7c31-ba398d3f9d58\"><span style=\"vertical-align: baseline\">Ebrard reiter&oacute; que M&eacute;xico seguir&aacute; en relaciones diplom&aacute;ticas con Venezuela y <strong><a href=\"https:\/\/www.sdpnoticias.com\/internacional\/2019\/01\/23\/juan-guaido-opositor-de-maduro-se-declara-presidente-interino-de-venezuela\">conforme vaya cambiando la situaci&oacute;n <\/a><\/strong>tendr&aacute;n que ir tomando decisiones, esto, respecto a la autoproclamaci&oacute;n como presidente de Juan Guaid&oacute;.<\/span><\/span><\/p>\n<p><span id=\"docs-internal-guid-a5f34ba8-7fff-dfb5-f328-b71c4805fb21\"><span style=\"vertical-align: baseline\">El ex jefe de gobierno capitalino dijo que a trav&eacute;s de <strong>Juan Manuel Nungaray,<\/strong> encargado de negocios de la SRE, est&aacute; la representaci&oacute;n de M&eacute;xico en Venezuela para atender a los connacionales que lo necesiten.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No vamos a desconocer al gobierno de Maduro: SRE<\/p>\n","protected":false},"author":1,"featured_media":180351,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[1223],"class_list":["post-180350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-sre"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2019\/01\/1548363518_468120_grande_qTwE8U4F.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/180350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=180350"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/180350\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/180351"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=180350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=180350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=180350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}