{"id":177427,"date":"2019-03-25T13:20:59","date_gmt":"2019-03-25T13:20:59","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2019\/03\/25\/en-mi-administracion-se-ha-fortalecido-la-seguridad-ceida-lopez\/"},"modified":"2019-03-25T13:20:59","modified_gmt":"2019-03-25T13:20:59","slug":"en-mi-administracion-se-ha-fortalecido-la-seguridad-ceida-lopez","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2019\/03\/25\/en-mi-administracion-se-ha-fortalecido-la-seguridad-ceida-lopez\/","title":{"rendered":"En mi administracion se ha fortalecido la seguridad: C&Atilde;&copy;eida Lopez"},"content":{"rendered":"<p class=\"MsoNormal\"><span>Reconoce la Presidenta de Hermosillo que en la estrategia que han estado implementado desde que tom&oacute; las riendas de la ciudad en materia de seguridad p&uacute;blica, ha rendido resultados positivos para la ciudadan&iacute;a y el sector empresarial y comercial.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>C&eacute;lida L&oacute;pez C&aacute;rdenas, mencion&oacute; que la semana anterior se tuvo una reuni&oacute;n entre la direcci&oacute;n de seguridad p&uacute;blica y comerciantes del centro, donde se expusieron diversas temas afines al tema de delitos y en ese sentido, enfatiz&oacute;, que en Hermosillo no se tiene una alza en robos de comercios gracias a los operativos especiales para ello.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span><span>&nbsp;<\/span>&ldquo;Y cualquier manifestaci&oacute;n de un ciudadano en el tema de seguridad, por m&aacute;s peque&ntilde;a que sea la vamos a atender. No tenemos una alza de robos de comercios en el centro, estamos conteniendo, tenemos obviamente un gran compromiso. Estuve yo el viernes con el Secretario de Seguridad P&uacute;blica revisando y haciendo las comparativos de cada uno de los &iacute;ndices de casa a robo habitaci&oacute;n, robo a comercio, robo a personas, etc, analizando las llamadas, tiempos de respuesta y dem&aacute;s&rdquo;, declar&oacute;.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span>&nbsp;<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span>La alcaldesa reconoci&oacute;, que los hermosillenses quieren vivir en una ciudad tranquila y segura, por lo que todos los d&iacute;as hay ese compromiso de atender cualquier delito que se presente y darles una soluci&oacute;n lo m&aacute;s pronto posible.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>C&eacute;lida L&oacute;pez reconoci&oacute;, que en su administraci&oacute;n se tiene claro que faltan m&aacute;s elementos para la polic&iacute;a y patrullas, y en ese sentido mencion&oacute;, que la intenci&oacute;n para este trienio es poder contratar al menos unos 200 elementos de los 600 que se requieren as&iacute; unas 80<span>&nbsp; <\/span>patrullas nuevas.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En mi administracion se ha fortalecido la seguridad: C&Atilde;&copy;eida Lopez<\/p>\n","protected":false},"author":1,"featured_media":177428,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[1579],"class_list":["post-177427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-celida-lopez"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2019\/03\/1553545259_WhatsAppImage2019-03-20at14.40.46.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/177427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=177427"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/177427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/177428"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=177427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=177427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=177427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}