{"id":176959,"date":"2019-04-01T15:50:59","date_gmt":"2019-04-01T15:50:59","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2019\/04\/01\/los-peligros-de-que-tu-hijo-abuse-de-los-audifonos\/"},"modified":"2019-04-01T15:50:59","modified_gmt":"2019-04-01T15:50:59","slug":"los-peligros-de-que-tu-hijo-abuse-de-los-audifonos","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2019\/04\/01\/los-peligros-de-que-tu-hijo-abuse-de-los-audifonos\/","title":{"rendered":"Los peligros de que tu hijo abuse de los audifonos"},"content":{"rendered":"<p><strong>El o&iacute;do de un ni&ntilde;o<\/strong><\/p>\n<p>El o&iacute;do de un ni&ntilde;o tiene tres partes: o&iacute;do externo, o&iacute;do medio, o&iacute;do interno y trompa de Eustaquio.<\/p>\n<p>Todo es m&aacute;s chiquito que el o&iacute;do adulto, la trompa es m&aacute;s recta y los adenoides est&aacute;n m&aacute;s cerca de la trompa de Eustaquio<\/p>\n<p><strong>&iquest;El o&iacute;do de un ni&ntilde;o es m&aacute;s sensible?<\/strong><\/p>\n<p>Los ni&ntilde;os son igual de sensibles que los adultos, no hay diferencia.<\/p>\n<p>Las diferencias son las enfermedades que tienen los ni&ntilde;os que son m&aacute;s infecciosas, al&eacute;rgicas y traum&aacute;ticas o pueden ser problemas gen&eacute;ticos o hereditarios.<\/p>\n<div id=\"outstream_article\" data-id=\"69\" data-m=\"{&quot;i&quot;:69,&quot;p&quot;:66,&quot;n&quot;:&quot;article-inlineOutstreamAd&quot;,&quot;t&quot;:&quot;inlineOutstreamAd&quot;,&quot;o&quot;:3}\">&nbsp;<\/div>\n<p>En los adultos son las inflamatorias, al&eacute;rgicas y la exposici&oacute;n al ruido.<\/p>\n<p>La p&eacute;rdida del o&iacute;do de un ni&ntilde;o se debe a problemas cong&eacute;nitos o hereditarios que tienen cierta predisposici&oacute;n a infecciones respiratorias que afectan al o&iacute;do.<\/p>\n<p>En el adulto se debe a la exposici&oacute;n al ruido y degeneraci&oacute;n por situaci&oacute;n de que se degeneran las c&eacute;lulas del nervio auditivo debido a la edad, problemas vasculares y problemas metab&oacute;lico<\/p>\n<p><strong>&iquest;Por qu&eacute; es peligroso el uso de auriculares en los ni&ntilde;os?<\/strong><\/p>\n<p>Usar los aud&iacute;fonos de manera incorrecta puede llegar a alterar la capacidad de aprendizaje, de memoria y de retenci&oacute;n de los ni&ntilde;os, adem&aacute;s de que favorece el aislamiento social.<\/p>\n<p>Adem&aacute;s, el problema con los aud&iacute;fonos es que se recibe el sonido por el aire que es el conducto de la oreja o por los huesos.<\/p>\n<p>Entonces se mete el aud&iacute;fono y se pone en contacto con los huesos de la cabeza.<\/p>\n<p>Por ejemplo, si vas a un concierto las vibraciones se sienten en los huesos y con los aud&iacute;fonos se sienten directamente en la cabeza y en o&iacute;do.<\/p>\n<p><strong>Consecuencias por el uso excesivo de aud&iacute;fonos<\/strong><\/p>\n<p>Hipoacusia.- disminuci&oacute;n paulatina de la capacidad para escuchar por el uso de aud&iacute;fonos a vol&uacute;menes muy altos.<\/p>\n<p>Tinnitus.- Escuchar zumbidos todo el tiempo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los peligros de que tu hijo abuse de los audifonos <\/p>\n","protected":false},"author":1,"featured_media":176960,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[336],"tags":[11839],"class_list":["post-176959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","tag-audifonos"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2019\/04\/1554159059_1551903500_268055_1551903909_portadilla_normal.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/176959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=176959"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/176959\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/176960"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=176959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=176959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=176959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}