{"id":176284,"date":"2019-04-12T08:48:37","date_gmt":"2019-04-12T08:48:37","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2019\/04\/12\/resalta-sara-valle-firma-en-guaymas-de-convenio-sonora-con-actitur\/"},"modified":"2019-04-12T08:48:37","modified_gmt":"2019-04-12T08:48:37","slug":"resalta-sara-valle-firma-en-guaymas-de-convenio-sonora-con-actitur","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2019\/04\/12\/resalta-sara-valle-firma-en-guaymas-de-convenio-sonora-con-actitur\/","title":{"rendered":"Resalta Sara Valle firma en Guaymas de convenio Sonora con Actitur"},"content":{"rendered":"<p>Teniendo a cientos de personas como testigo en el majestuoso Mirador Esc&eacute;nico de San Carlos, Guaymas, la alcaldesa Sara Valle Dessens, acompa&ntilde;&oacute; a la gobernadora Claudia Pavlovich en la firma del convenio Sonora con Actitur.<\/p>\n<p>&nbsp;<\/p>\n<p>La intenci&oacute;n de este convenio es la de promover la buena hospitalidad y trato a los turistas, para que el turismo aumente en Sonora.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Les pido siempre sonre&iacute;r y apoyar a los turistas, un turista contento hablar&aacute; bien de Sonora y eso nos generar&aacute; m&aacute;s turismo&rdquo;, coment&oacute; Pavlovich Arellano.<\/p>\n<p>&nbsp;<\/p>\n<p>Por su parte la alcaldesa se comprometi&oacute; a apoyar en todo lo necesario el programa, buscando mejores beneficios para los guaymenses.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Si tenemos m&aacute;s turistas esto es autom&aacute;ticamente una buena derrama econ&oacute;mica, misma de la cual nos beneficiamos todos los guaymenses&rdquo;, coment&oacute; Valle Dessens.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resalta Sara Valle firma en Guaymas de convenio Sonora con Actitur<\/p>\n","protected":false},"author":1,"featured_media":176285,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[9019],"class_list":["post-176284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-sara-valle"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2019\/04\/1555084117_Inicia-Sonora-con-Actitur-1.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/176284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=176284"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/176284\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/176285"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=176284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=176284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=176284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}