{"id":172984,"date":"2019-06-12T06:58:39","date_gmt":"2019-06-12T06:58:39","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2019\/06\/12\/pide-salud-sonora-extremar-medidas-contra-ola-de-calor-2\/"},"modified":"2019-06-12T06:58:39","modified_gmt":"2019-06-12T06:58:39","slug":"pide-salud-sonora-extremar-medidas-contra-ola-de-calor-2","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2019\/06\/12\/pide-salud-sonora-extremar-medidas-contra-ola-de-calor-2\/","title":{"rendered":"Pide Salud Sonora extremar medidas contra ola de calor"},"content":{"rendered":"<p><span style=\"font-family: Arial, Helvetica, sans-serif;font-size: small\">Hermosillo, Sonora, junio 12 de 2019.- Ante el incremento de temperaturas en la entidad, la Secretar&iacute;a de Salud llama a la poblaci&oacute;n a extremar precauciones para prevenir enfermedades derivadas del calor, subray&oacute; Gerardo &Aacute;lvarez Hern&aacute;ndez.<\/p>\n<p>El director general de Promoci&oacute;n a la Salud y Prevenci&oacute;n de Enfermedades recomend&oacute; a la poblaci&oacute;n no esperar a tener sed para consumir l&iacute;quidos y tratar de tomar m&iacute;nimo dos litros de agua diariamente, evitar exposici&oacute;n solar en las horas de mayor radiaci&oacute;n y utilizar siempre bloqueador solar.<\/p>\n<p>&lsquo;&rsquo;Elija las primeras horas del d&iacute;a para llevar a cabo las actividades al aire libre y las deportivas, as&iacute; como ceremonias c&iacute;vicas, tambi&eacute;n se recomienda evitar el trabajo f&iacute;sico intenso y prolongado bajo el rayos del Sol&rsquo;&rsquo;, extern&oacute;.<\/p>\n<p>Otras recomendaciones, agreg&oacute;, son: vestir ropa ligera, holgada y de colores claros, preferentemente que cubra a la piel de la exposici&oacute;n frecuente al Sol, utilizar sombrero o sombrilla y cubrir ventanas colocando persianas, cortinas o peri&oacute;dicos, lo que ayuda a disminuir hasta en un 80 por ciento el calor en el interior de la casa.<\/p>\n<p>&Aacute;lvarez Hern&aacute;ndez enfatiz&oacute; que es muy importante no permanecer dentro de un veh&iacute;culo cerrado o estacionado ni permitir que otros lo hagan, ya que la temperatura se incrementa dos grados cada 10 minutos que est&eacute; cerrado y puede tener consecuencias fatales.<\/p>\n<p>As&iacute; mismo, el especialista a&ntilde;adi&oacute; que los s&iacute;ntomas m&aacute;s importantes que indican que una persona puede padecer alguna enfermedad derivada del calor, son: dolor de cabeza, mareo, sudoraci&oacute;n excesiva al principio y despu&eacute;s falta de sudor, enrojecimiento, sequedad en la piel y fiebre desde 39 a 41 grados cent&iacute;grados.<\/p>\n<p>&lsquo;&rsquo;Tambi&eacute;n puede presentar aceleraci&oacute;n del ritmo card&iacute;aco, con latido del coraz&oacute;n d&eacute;bil, crisis convulsivas y otros signos de mayor severidad como: piel que se siente caliente y seca pero no sudorosa, confusi&oacute;n o p&eacute;rdida del conocimiento, v&oacute;mitos frecuentes, falta de aire o problemas para respirar&rsquo;&rsquo;, recalc&oacute;.<\/p>\n<p>Por &uacute;ltimo, se&ntilde;al&oacute; que en caso de que los labios y piel est&eacute;n secos, se debe solicitar gratuitamente Vida Suero Oral en cualquier unidad del sector salud y acudir de inmediato por atenci&oacute;n m&eacute;dica si presenta alguno de los s&iacute;ntomas.<\/p>\n<p>Recomendaciones contra el calor:<br \/>&bull; No permanecer dentro de un veh&iacute;culo cerrado o estacionado ni permitir que otros lo hagan.<br \/>&bull; No esperar a tener sed para consumir l&iacute;quidos.<br \/>&bull; Tratar de tomar m&iacute;nimo dos litros de agua diariamente.<br \/>&bull; Evitar exposici&oacute;n solar en las horas de mayor radiaci&oacute;n.<br \/>&bull; Utilizar siempre bloqueador solar.<br \/>&bull; Vestir ropa ligera, holgada y de colores claros.<br \/>&bull; Utilizar sombrero o sombrilla y cubrir ventanas colocando persianas, cortinas o peri&oacute;dicos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pide Salud Sonora extremar medidas contra ola de calor <\/p>\n","protected":false},"author":1,"featured_media":172985,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[407],"class_list":["post-172984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-sec-salud"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2019\/06\/1560347919_timthumb.php.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/172984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=172984"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/172984\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/172985"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=172984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=172984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=172984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}