{"id":167084,"date":"2019-09-30T06:28:39","date_gmt":"2019-09-30T06:28:39","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2019\/09\/30\/gana-cecyte-sonora-primer-lugar-en-escultura\/"},"modified":"2019-09-30T06:28:39","modified_gmt":"2019-09-30T06:28:39","slug":"gana-cecyte-sonora-primer-lugar-en-escultura","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2019\/09\/30\/gana-cecyte-sonora-primer-lugar-en-escultura\/","title":{"rendered":"Gana CECyTE Sonora primer lugar en Escultura"},"content":{"rendered":"<p><span style=\"font-family: Arial, Helvetica, sans-serif;font-size: small\">Guadalajara, Jalisco, septiembre 30 de 2019.- El primer lugar en Escultura obtuvo el Colegio de Estudios Cient&iacute;ficos y Tecnol&oacute;gicos del Estado de Sonora, CECyTE Sonora, en el XXI Festival Nacional de Arte y Cultura de los CECyTE&rsquo;s 2019, realizado en Guadalajara, Jalisco.<\/p>\n<p>La alumna, Miriam Jes&uacute;s Aguirre Garc&iacute;a, de EMSaD Bacerac, particip&oacute; con un torso femenino elaborado con piedra Esteatita de M&aacute;tape, Sonora, y obtuvo el primer lugar en la competencia nacional.<\/p>\n<p>Con este premio, CECyTE Sonora sigue poniendo en alto el nombre del estado a nivel nacional, al mantenerse por varios a&ntilde;os como de los m&aacute;s galardonados en este Festival en el que participan planteles de toda la Rep&uacute;blica Mexicana.<\/p>\n<p>La delegaci&oacute;n Sonora se conform&oacute; con 35 alumnos y asesores, quienes participaron en las categor&iacute;as de Danza, Escultura, Poes&iacute;a, Pintura, Declamaci&oacute;n, Oratoria, Cuento Corto y Canto Tradicional.<\/p>\n<p>El director general de CECyTE Sonora, Am&oacute;s Benjam&iacute;n Moreno Ru&iacute;z, felicit&oacute; a todos los j&oacute;venes participantes y agradeci&oacute; el apoyo de sus maestros asesores y principalmente a los padres de familia, ya que es el resultado del trabajo en equipo.<\/p>\n<p>El evento se desarroll&oacute; del 22 al 26 de septiembre, participaron 721 competidores de 29 estados de la Rep&uacute;blica.<\/p>\n<p>El Colegio particip&oacute; por primera vez en Canto de Exhibici&oacute;n con alumnos del plantel Hermosillo II; en un escenario para el p&uacute;blico en general, de la ciudad tapat&iacute;a.<\/p>\n<p>Las actividades se realizaron en distintas sedes como el Hospicio Caba&ntilde;as, la Catedral y el edificio Arroniz, entre otros recintos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Gana CECyTE Sonora primer lugar en Escultura <\/p>\n","protected":false},"author":1,"featured_media":167085,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[2256],"class_list":["post-167084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-cecytes"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2019\/09\/1569850119_0919168.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/167084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=167084"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/167084\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/167085"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=167084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=167084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=167084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}