{"id":165848,"date":"2019-10-23T08:30:52","date_gmt":"2019-10-23T08:30:52","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2019\/10\/23\/impulsa-secretaria-de-economia-a-emprendedores\/"},"modified":"2019-10-23T08:30:52","modified_gmt":"2019-10-23T08:30:52","slug":"impulsa-secretaria-de-economia-a-emprendedores","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2019\/10\/23\/impulsa-secretaria-de-economia-a-emprendedores\/","title":{"rendered":"Impulsa Secretaria de Economia a emprendedores"},"content":{"rendered":"<p><span style=\"font-family: Arial, Helvetica, sans-serif;font-size: small\">Hermosillo, Sonora, octubre 23 de 2019.- A trav&eacute;s del taller Impulsa con Facebook, la Secretar&iacute;a de Econom&iacute;a reuni&oacute; a emprendedores, empresarios y estudiantes universitarios, a fin de brindarles una herramienta para impulsar las ventas de los negocios, mediante la plataforma de Facebook, con la creaci&oacute;n de contenidos creativos para su comunidad, as&iacute; como el desarrollo de estrategias con el objetivo de alcanzar a sus clientes potenciales.<\/p>\n<p>Jorge Vidal Ahumada, secretario de Econom&iacute;a, destac&oacute; que con esta jornada de capacitaci&oacute;n buscan acercar a los j&oacute;venes emprendedores, empresarios y universitarios con el sector de los negocios, aprovechando el auge que tienen actualmente las redes sociales, espec&iacute;ficamente Facebook.<\/p>\n<p>&ldquo;El inter&eacute;s que tiene la gobernadora es el tratar de mostrar, de ense&ntilde;ar, de compartir todos los avances tecnol&oacute;gicos que empresas como Facebook tienen a nivel mundial, con ustedes que est&aacute;n en la innovaci&oacute;n, con ustedes que son los emprendedores, con ustedes que son los empresarios; el gran reto el d&iacute;a de ma&ntilde;ana sin duda constante en el estado de Sonora y en el mundo, es el estar con toda la capacitaci&oacute;n posible, el transitar de la econom&iacute;a de la manufactura, que es lo que caracteriza al estado de Sonora, a la econom&iacute;a de las ideas, a la econom&iacute;a de la innovaci&oacute;n y la tecnolog&iacute;a&rdquo;, indic&oacute;.<\/p>\n<p>On&eacute;simo Mariscales Delgadillo, subsecretario de Educaci&oacute;n Media Superior y Superior, dijo que en este tipo de eventos se involucra al sector acad&eacute;mico para que tengan un cercamiento con las plataformas digitales de mayor difusi&oacute;n y conocer la utilidad de sus herramientas.<\/p>\n<p>&ldquo;Es un taller que estamos atendiendo el secretario de Econom&iacute;a, que es el responsable de este sector tan importante de impulsar muchas tareas, pero lo estamos haciendo con la academia que son los planteles de Media Superior, las universidades y, por supuesto el otro elemento, el sector empresarial, es muy gratificante tener aqu&iacute; a Facebook, y por eso agradecerles que est&eacute;n aqu&iacute; en Sonora&rdquo;, se&ntilde;al&oacute;.<\/p>\n<p>Omar Guill&eacute;n Partida, subsecretario de Impulso a la Comercializaci&oacute;n, destac&oacute; la b&uacute;squeda de nuevas herramientas para hacer crecer la econom&iacute;a, a trav&eacute;s de las plataformas digitales m&aacute;s usadas a nivel mundial.<\/p>\n<p>&ldquo;Tenemos que buscar todas las herramientas necesarias para que se d&eacute; esta transformaci&oacute;n digital, la econom&iacute;a a nivel mundial ya est&aacute; rompiendo fronteras a trav&eacute;s de las plataformas electr&oacute;nicas, y sabemos que la plataforma m&aacute;s famosa en el mundo, precisamente es la empresa Facebook&rdquo;, destac&oacute;.<\/p>\n<p>Laura Beatriz Ugalde Aburto, especialista en emprendimiento para Facebook, mencion&oacute; que el fin de esta capacitaci&oacute;n es impulsar los negocios ya establecidos o ayudar a crear uno a quienes tienen la inquietud.<\/p>\n<p>&ldquo;Esperamos que esta capacitaci&oacute;n y este taller les ayude mucho, para que ustedes o impulsen su negocio o lo empiecen a crear&rdquo;, dijo.<\/p>\n<p>Presentes: Larissa Vega, especialista de emprendimiento para Facebook; y Christian Romo Flores, jefe de estrategias E-Commerce de la Secretar&iacute;a de Econom&iacute;a.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Impulsa Secretaria de Economia a emprendedores<\/p>\n","protected":false},"author":1,"featured_media":165849,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[1120],"class_list":["post-165848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-sec-economia"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2019\/10\/1571844652_1019148b.JPG","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/165848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=165848"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/165848\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/165849"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=165848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=165848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=165848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}